{"id":155176,"date":"2023-08-28T15:04:33","date_gmt":"2023-08-28T05:04:33","guid":{"rendered":"https:\/\/www.eventbookings.com\/?page_id=155176"},"modified":"2026-03-09T21:37:57","modified_gmt":"2026-03-09T10:37:57","slug":"alternative-to-ticketleap","status":"publish","type":"page","link":"https:\/\/www.eventbookings.com\/en-us\/alternative-to-ticketleap\/","title":{"rendered":"EventBookings vs Ticketleap"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"155176\" class=\"elementor elementor-155176\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7963541 laptop-container  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7963541\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08b005c\" data-id=\"08b005c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23bce2a br-none SharpSans ticketing udergreen-curve elementor-widget elementor-widget-heading\" data-id=\"23bce2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Leaders in the Event Space are Making the Switch!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac5ca90 SharpSans  elementor-widget elementor-widget-heading\" data-id=\"ac5ca90\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Discover why EventBookings is becoming the top choice for event organizers. While many platforms devour up to 15% in ticketing fees, EventBookings ensures you retain more of your hard-earned money.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4a04c43 compare-button-section elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a04c43\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e141b5 comp-btn\" data-id=\"4e141b5\" data-element_type=\"column\" data-no-translation=\"\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-beb01bf elementor-mobile-align-center elementor-align-left elementor-tablet-align-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-button\" data-id=\"beb01bf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0bf838b\" data-id=\"0bf838b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0cd080 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"b0cd080\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><em>Free Forever.<br>\nNo Credit Card Required.<\/em><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bd8e936 top-logo-section elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd8e936\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1c4e262\" data-id=\"1c4e262\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-764d49a elementor-widget elementor-widget-image\" data-id=\"764d49a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"112\" height=\"25\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\" class=\"attachment-full size-full wp-image-158596\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-066ffed\" data-id=\"066ffed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8a4613 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e8a4613\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"168\" height=\"26\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/software-advice-logo.svg\" class=\"attachment-full size-full wp-image-158616\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6cd0c30\" data-id=\"6cd0c30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3e8788 elementor-widget elementor-widget-image\" data-id=\"c3e8788\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"115\" height=\"21\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/get-apps-logo.svg\" class=\"attachment-full size-full wp-image-158611\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50db19f top-star-review elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50db19f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-786c19d\" data-id=\"786c19d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-676cc89 elementor-widget elementor-widget-image\" data-id=\"676cc89\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"127\" height=\"18\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png\" class=\"attachment-full size-full wp-image-158606\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png 127w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image-18x3.png 18w\" sizes=\"(max-width: 127px) 100vw, 127px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-054bde3\" data-id=\"054bde3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a362e1 review--content-text elementor-widget elementor-widget-heading\" data-id=\"6a362e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Excellent 4.7\/5<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3ad6b3 elementor-widget elementor-widget-html\" data-id=\"f3ad6b3\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n.top-star-review p{\n   font-family: Sharp Sans !important;\n}\n@media (max-width:1024px) {\n.compare-button-section .elementor-row{\n    max-width: 330px;\n    justify-content: center;\n    margin: 0 auto;\n    flex-wrap: nowrap;\n    }\n.compare-button-section .elementor-column:nth-child(1){\n        width:200px;\n    }\n.top-logo-section .elementor-row{\n    max-width:421px;\n    justify-content: center;\n    margin: 0 auto;\n    flex-wrap: nowrap;\n}\n.top-star-review .elementor-row{\n    max-width: 367px;\n    margin: 0 auto;\n    flex-wrap: nowrap;\n    justify-content: center;\n}\n.top-star-review .elementor-column:nth-child(1){\n        width:127px;\n}\n}\n@media (max-width:767px) {\n.compare-button-section .elementor-column:nth-child(1) {\n    width: 116px;\n}\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53b4379\" data-id=\"53b4379\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d895738 elementor-widget elementor-widget-image\" data-id=\"d895738\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"775\" height=\"749\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/banner-10.png\" class=\"attachment-full size-full wp-image-156351\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/banner-10.png 775w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/banner-10-300x290.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/banner-10-768x742.png 768w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/banner-10-12x12.png 12w\" sizes=\"(max-width: 775px) 100vw, 775px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d04b69 compare-button-section comp-btn comp-btn elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d04b69\" data-element_type=\"section\" data-no-translation=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19441f5\" data-id=\"19441f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6beabab elementor-mobile-align-center elementor-align-left elementor-tablet-align-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-button\" data-id=\"6beabab\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a6eb3fa\" data-id=\"a6eb3fa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-155581b elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"155581b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><em>Free Forever.<br>\nNo Credit Card Required.<\/em><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-37bcd0d top-logo-section elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37bcd0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b93fdfb\" data-id=\"b93fdfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73ae672 elementor-widget elementor-widget-image\" data-id=\"73ae672\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"112\" height=\"25\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\" class=\"attachment-full size-full wp-image-158596\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-018731e\" data-id=\"018731e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa747fb elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"aa747fb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"168\" height=\"26\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/software-advice-logo.svg\" class=\"attachment-full size-full wp-image-158616\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-083d094\" data-id=\"083d094\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfaef03 elementor-widget elementor-widget-image\" data-id=\"bfaef03\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"115\" height=\"21\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/get-apps-logo.svg\" class=\"attachment-full size-full wp-image-158611\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8c4502 top-star-review elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8c4502\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bbae119\" data-id=\"bbae119\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1637ce8 elementor-widget elementor-widget-image\" data-id=\"1637ce8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"127\" height=\"18\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png\" class=\"attachment-full size-full wp-image-158606\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png 127w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image-18x3.png 18w\" sizes=\"(max-width: 127px) 100vw, 127px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c92ab4c\" data-id=\"c92ab4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5066e71 elementor-widget elementor-widget-heading\" data-id=\"5066e71\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Excellent 4.7\/5<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5257ac4a laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5257ac4a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68d2aa49\" data-id=\"68d2aa49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a3b1ec elementor-widget elementor-widget-shortcode\" data-id=\"7a3b1ec\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><!-- AU and All other Country Except (USA, Canada, USA, UK, NZ) -->\n                <div class=\"client-logo-section\">\n                    <h4 class=\"client-title\">Events created by thousands of organizations around the globe<\/h4>\n                    <div class=\"client-logo-box\">\n                         <div class=\"logo-item\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/omg-logo-grey.png\" width=\"77\" height=\"73\" alt=\"Brand Logo\">\n                        <\/div>\n                          <div class=\"logo-item\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/IPSC-Australia.png\" width=\"150\" height=\"54\" alt=\"Brand Logo\">\n                        <\/div>\n                       \n                       \n                         <div class=\"logo-item\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/bibi.png\" width=\"97\" height=\"97\" alt=\"Brand Logo\">\n                        <\/div>\n                         <div class=\"logo-item\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/IFAM-logo.png\" width=\"100\" height=\"100\" alt=\"Brand Logo\">\n                        <\/div>\n                         <div class=\"logo-item\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/TIA-logo-strip_blue.png\" width=\"156\" height=\"47\" alt=\"Brand Logo\">\n                        <\/div>\n                          <div class=\"logo-item\">\n                            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/taca-logo.png\" width=\"110\" height=\"55\" alt=\"Brand Logo\">\n                        <\/div>\n                    <\/div>\n                <\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51b611a0 SharpSans  elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"51b611a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">US$<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6b1e8d SharpSans  elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"c6b1e8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00a2<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60aef557 calculate-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60aef557\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef118a6\" data-id=\"ef118a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab378b6 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"7ab378b6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">More Affordable Ticketing Fees Than Ticketleap<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2541e7d8 br-none elementor-widget elementor-widget-heading\" data-id=\"2541e7d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Exdplore Your Savings: Adjust the Sliders to See How Much You and Your Attendees Can <br> Save by Switching from Ticketleap to EventBookings.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-75f3949 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75f3949\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-da25695\" data-id=\"da25695\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc9cc8e calculator-long n-short elementor-widget elementor-widget-html\" data-id=\"dc9cc8e\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n    .trybooking-n-eventbrite-cal .ranger-slieds {\r\n        border-right: 0;\r\n        padding-right: 0;\r\n    }\r\n\r\n    .trybooking-n-eventbrite-cal .vs-dynamic-value {\r\n        align-items: center;\r\n        justify-content: center;\r\n        flex-wrap: wrap;\r\n        text-align: center;\r\n    }\r\n\r\n    .trybooking-n-eventbrite-cal .vs-dynamic-value .amount {\r\n        margin: 0\r\n    }\r\n\r\n    .trybooking-n-eventbrite-cal .vs-dynamic-value .vs_save_1 {\r\n        flex-basis: 100%;\r\n    }\r\n\r\n    .trybooking-n-eventbrite-cal .values {\r\n        display: block;\r\n        flex-basis: 100%;\r\n        margin-top: 20px;\r\n    }\r\n\r\n    .trybooking-n-eventbrite-cal .vs-dynamic-value {\r\n        margin-top: 40px;\r\n    }\r\n\r\n    @media screen and (max-width: 991px) {\r\n        .trybooking-n-eventbrite-cal .vs-dynamic-value .vs_save_1 {\r\n            margin-bottom: 0;\r\n        }\r\n    }\r\n\r\n    @media screen and (max-width: 767px) {\r\n        .trybooking-n-eventbrite-cal .vs-dynamic-value .vs_save_1 {\r\n            text-align: center;\r\n        }\r\n\r\n        .calculate-section .vs_save_2 {\r\n            padding: 0 0 10px 0 !important;\r\n            border: 0;\r\n        }\r\n\r\n        .trybooking-n-eventbrite-cal .values {\r\n            margin-top: 10px;\r\n        }\r\n\r\n        .trybooking-n-eventbrite-cal .vs-dynamic-value {\r\n            margin-top: 10px;\r\n        }\r\n\r\n        .calculate-section .vs_save_2 {\r\n            border-right: 0 !important;\r\n            width: 100%;\r\n        }\r\n    }\r\n<\/style>\r\n<div class=\"row\">\r\n    <div class=\"col-lg-12 col-sm-12\">\r\n        <div class=\"ranger-slieds\">\r\n            <!-- Entry Fee  -->\r\n            <div class=\"range-slider entry-fee-slide\">\r\n                <div class=\"slider-label\">Average Entry Fee<\/div>\r\n                <input id=\"first_field\" class=\"range-slider__range has_dollar\" type=\"range\" value=\"100\" min=\"50\"\r\n                       max=\"1500\">\r\n                <span class=\"range-value\">\r\n                    <span class=\"js_currency\"><\/span>\r\n                    <span class=\"range-slider__value1 js-range-value\">100.00<\/span>\r\n                <\/span>\r\n            <\/div>\r\n            <!-- Attendees Per Event  -->\r\n            <div class=\"range-slider per-event-slide\">\r\n                <div class=\"slider-label\">Attendees Per Event<\/div>\r\n                <input id=\"second_field\" class=\"range-slider__range\" type=\"range\" value=\"100\" min=\"100\" max=\"450\">\r\n                <span class=\"range-value\">\r\n                    <span class=\"range-slider__value2 js-range-value\">0<\/span>\r\n                <\/span>\r\n            <\/div>\r\n            <!-- Events Per Year  -->\r\n            <div class=\"range-slider events-year-slide\">\r\n                <div class=\"slider-label\">Events Per Year<\/div>\r\n                <input id=\"third_field\" class=\"range-slider__range\" type=\"range\" value=\"4\" min=\"4\" max=\"12\">\r\n                <span class=\"range-value\">\r\n                    <span class=\"range-slider__value2 js-range-value\">0<\/span>\r\n                <\/span>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div id=\"vs-dynamic-value-js\" class=\"vs-dynamic-value\">\r\n    <div class=\"vs_save_1\">Your Savings Per Year<\/div>\r\n    <div class=\"values\">\r\n        <div class=\"vs_save_2\">\r\n            <div id=\"vs2\" class=\"vs2 amount green\"><span class=\"js_currency\"><\/span><span class=\"js_amount\"><\/span>\r\n            <\/div>\r\n            <!--<div class=\"vs-z1 per-yr-zm mt-3\">(excluding ZOOM & payment processing fees)<\/div>-->\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<script>\r\n    const countryList = {\r\n        'en-AU': {\r\n            eb_percentage: 2,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.0,\r\n            comp_base: 1.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"AU$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Australia settings\r\n        'en-US': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage:  2.0,\r\n            comp_base: 1.00,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"US$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ United States settings\r\n        'en-CA': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.0,\r\n            comp_base: 1.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"CA$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Canada settings\r\n        'en-GB': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.0,\r\n            comp_base: 1.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u00a3\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ United Kingdom settings\r\n        'en-NZ': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.0,\r\n            comp_base: 1.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"NZ$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ New Zealand\r\n        'en-IE': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.9,\r\n            comp_base: 0.79,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Ireland\r\n        'en-BE': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 4.0,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Belgium\r\n\t\t        'en-DK': {\r\n            eb_percentage: 1,\r\n            eb_base: 1.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.5,\r\n            comp_base: 9.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Kr\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Denmark\r\n\t\t'fi': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Finland settings\r\n\t\t'fr-FR': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ France settings\r\n        'de-DE': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Germany settings\t\r\n        'id-ID': {\r\n            eb_percentage: 1,\r\n            eb_base: 1500.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Rp\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Indonesia settings\t\t\r\n        'it-IT': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Italy settings\t\t\r\n        'ms-MY': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.50,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 4.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"RM\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Malaysia settings\t\t\r\n        'nl-NL': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 4.0,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Netherlands settings\t\t\r\n        'en-SG': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"S$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Singapore settings\t\t\r\n        'es-ES': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 9.0,\r\n            comp_base: 0.19,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Spain settings\t\t\r\n        'sv-SE': {\r\n            eb_percentage: 1,\r\n            eb_base: 2.10,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Kr\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Sweden settings\t\r\n        'de-CH': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.25,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Fr\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Switzerland settings\t\t\r\n        'th': {\r\n            eb_percentage: 1,\r\n            eb_base: 3.50,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u0e3f\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Thailand settings\t\t\r\n        'ar-AE': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.80,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"AED\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ United Arab Emirates settings\t\t\r\n        'el-CY': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Cyprus settings\t\t\r\n        'tl-PH': {\r\n            eb_percentage: 1,\r\n            eb_base: 4.50,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 4.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20b1\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Philippines settings\t\t\r\n        'en-ZA': {\r\n            eb_percentage: 1,\r\n            eb_base: 2.50,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"R\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ South Africa settings\t\t\r\n        'zh-TW': {\r\n            eb_percentage: 1,\r\n            eb_base: 5.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 4.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"NT$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Taiwan settings\t\t\r\n        'ar-EG': {\r\n            eb_percentage: 1,\r\n            eb_base: 3.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"E\u00a3\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Egypt settings\t\t\r\n        'ko-KR': {\r\n            eb_percentage: 1,\r\n            eb_base: 300.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20a9\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ South Korea settings\t\t\r\n        'ro-RO': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Lei\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Romania settings\t\t\r\n        'zh-CN': {\r\n            eb_percentage: 1,\r\n            eb_base: 1.50,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u00a5\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ China settings\t\t\r\n        'ar-SA': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.80,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u0631.\u0633\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Saudi Arabia settings\t\t\r\n        'el-GR': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.15,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Greece settings\t\t\r\n        'pt-BR': {\r\n            eb_percentage: 1,\r\n            eb_base: 1.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 9.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"R$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Brazil settings\t\t\r\n        'no-NO': {\r\n            eb_percentage: 1,\r\n            eb_base: 2.10,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 4.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Kr\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Norway settings\t\t\r\n        'pt-PT': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Portugal settings\t\t\r\n        'hu-HU': {\r\n            eb_percentage: 1,\r\n            eb_base: 35.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.5,\r\n            comp_base: 399.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Ft\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Hungary settings\t\t\r\n        'ar-JO': {\r\n            eb_percentage: 1,\r\n            eb_base:  0.10,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u062f.\u0627\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Jordan settings\t\t\r\n        'fj': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"F$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Fiji settings\t\r\n        'ar-QA': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.99,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u0631.\u0642\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Qatar settings\t\t\r\n        'es-AR': {\r\n            eb_percentage: 1,\r\n            eb_base: 50.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"AR$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Argentina settings\t\t\r\n        'ja-JP': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u00a5\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Japan settings\t\t\r\n        'hr': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Croatia settings\t\t\r\n        'bg-BG': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.18,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u043b\u0432\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Bulgaria settings\t\t\r\n        'en-GB': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u00a3\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Canada settings\t\t\r\n        'de-AT': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.5,\r\n            comp_base: 0.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Austria settings\t\r\n        'cs-CZ': {\r\n            eb_percentage: 1,\r\n            eb_base: 5.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.5,\r\n            comp_base: 39.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"K\u010d\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Czech Republic settings\t\t\r\n        'sk-SK': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Slovakia settings\t\t\r\n        'es-MX': {\r\n            eb_percentage: 1,\r\n            eb_base: 1.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"MX$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Mexico settings\t\t\r\n        'et': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Estonia settings\t\r\n        'en-BD': {\r\n            eb_percentage: 1,\r\n            eb_base: 10.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u09f3\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Bangladesh settings\t\t\r\n        'sl-SI': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Canada settings\t\t\r\n        'en-GB': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u00a3\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Slovenia settings\t\t\r\n        'en-MT': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Malta settings\t\t\r\n        'lt-LT': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Lithuania settings\t\t\r\n        'lv': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20ac\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Latvia settings\t\t\r\n        'zh-HK': {\r\n            eb_percentage: 1,\r\n            eb_base: 1.0,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 5.99,\r\n            comp_base: 0.0,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"HK$\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Hong Kong settings\t\t\r\n        'pl-PL': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.15,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 2.5,\r\n            comp_base: 5.99,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"z\u0142\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Poland settings\t\t\r\n        'en_GI': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.30,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u00a3\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Gibraltar settings\t\t\r\n        'de_LI': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"Fr\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ Liechtenstein settings\t\t\r\n        'hi-IN': {\r\n            eb_percentage: 1,\r\n            eb_base: 0.20,\r\n            subscription: 0,\r\n\r\n            comp_percentage: 6.95,\r\n            comp_base: 0.59,\r\n            comp_subscription: 0,\r\n\r\n\r\n            currency: \"\u20b9\",\r\n            initialPrice: 100,\r\n            minPrice: 50,\r\n            maxPrice: 1500,\r\n        }, \/\/ India settings\r\n    };\r\n\r\n    \/\/ Get the language code from the <html> tag to identify the country\r\n    const htmlLang = $('html').attr('lang');\r\n\r\n    \/\/ Get the corresponding country settings based on the language code\r\n    const countryVal = countryList[htmlLang];\r\n\r\n    const settings = {\r\n        fill: '#22B0AF',\r\n        background: '#EDEDED'\r\n    }\r\n\r\n\r\n    $('#first_field').attr('min', countryVal.minPrice);\r\n    $('#first_field').attr('max', countryVal.maxPrice);\r\n    $('#first_field').val(countryVal.initialPrice);\r\n    $('.js_currency').text(countryVal.currency);\r\n\r\n    function numberWithCommas(number) {\r\n        var parts = number.toString().split(\".\");\r\n        parts[0] = parts[0].replace(\/\\B(?=(\\d{3})+(?!\\d))\/g, \",\");\r\n        return parts.join(\".\");\r\n    }\r\n\r\n    function calculate() {\r\n        var ticket_price = $('#first_field').val();\r\n        var total_ticket = $('#second_field').val();\r\n        var total_event = $('#third_field').val();\r\n\r\n        var percentage = countryVal.eb_percentage \/ 100;\r\n        var base = countryVal.eb_base;\r\n        var subscription = countryVal.subscription;\r\n\r\n        var comp_percentage = countryVal.comp_percentage \/ 100;\r\n        var comp_base = countryVal.comp_base;\r\n        var comp_subscription = countryVal.comp_subscription;\r\n\r\n        var eb_ticketing_fee = (((ticket_price * percentage) + base) * total_ticket * total_event) + (subscription * 12);\r\n        var comp_ticketing_fee = (((ticket_price * comp_percentage) + comp_base) * total_ticket * total_event) + (comp_subscription * 12);\r\n\r\n        var vs_run_pro_savings = Math.ceil(comp_ticketing_fee - eb_ticketing_fee);\r\n        $(\".js_amount\").html(numberWithCommas(vs_run_pro_savings) + '.00')\r\n    }\r\n\r\n    $(document).ready(function () {\r\n        $('.range-slider input').on('input', function () {\r\n            const $slider = $(this);\r\n            applyFill($(this));\r\n            const value = parseFloat($slider.val()).toFixed(2); \/\/ Format to 2 decimal places if needed\r\n            const $valueSpan = $slider.siblings('.range-value').children('.js-range-value');\r\n            if ($(this).hasClass('has_dollar')) {\r\n                $valueSpan.text(`${value}`);\r\n            } else {\r\n                $valueSpan.text(`${value}`);\r\n            }\r\n        });\r\n\r\n        function applyFill($slider) {\r\n            const min = $slider.attr('min');\r\n            const max = $slider.attr('max');\r\n            const value = $slider.val();\r\n            const percentage = 100 * (value - min) \/ (max - min);\r\n            const bg = `linear-gradient(90deg, ${settings.fill} ${percentage}%, ${settings.background} ${percentage + 0.1}%)`;\r\n            $slider.css('background', bg);\r\n        }\r\n\r\n        \/\/ Initialize the span values on page load\r\n        $('.range-slider input').each(function () {\r\n            const $slider = $(this);\r\n            applyFill($(this));\r\n            const value = parseFloat($slider.val()).toFixed(2);\r\n            const $valueSpan = $slider.siblings('.range-value').children('.js-range-value');\r\n            if ($(this).hasClass('has_dollar')) {\r\n                $valueSpan.text(`${value}`);\r\n            } else {\r\n                $valueSpan.text(`${value}`);\r\n            }\r\n\r\n        });\r\n        calculate();\r\n    });\r\n\r\n\r\n    \/\/ Add event listeners to input fields to recalculate values on change\r\n    $('#first_field, #second_field, #third_field').on('input change', function () {\r\n        calculate(); \/\/ Recalculate whenever relevant inputs are changed\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53706692 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53706692\" data-element_type=\"section\" id=\"Compare\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ed67671\" data-id=\"4ed67671\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c39079d elementor-widget elementor-widget-heading\" data-id=\"c39079d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Feature comparison EventBookings vs Ticketleap<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-134efb67 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"134efb67\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-38fb3557\" data-id=\"38fb3557\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1850f058 overflow-auto elementor-widget elementor-widget-eb-table-list-custom\" data-id=\"1850f058\" data-element_type=\"widget\" data-widget_type=\"eb-table-list-custom.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <!-- Add Markup Starts -->\n\n\n\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\"><\/div>\n            <\/div>\n            <div><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-99166\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2022\/11\/event-booking-150x40-1.png\" alt=\"\" width=\"150\" height=\"40\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2022\/11\/event-booking-150x40-1.png 150w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2022\/11\/event-booking-150x40-1-18x5.png 18w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/p><\/div>\n            <div><h2><strong>Ticketleap<\/strong><\/h2><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Service Fee (Per Ticket)<\/div>\n            <\/div>\n            <div><p>1% + $0.30<\/p><\/div>\n            <div><p>2.99% + $0.99<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Service Charge for Free Events<\/div>\n            <\/div>\n            <div><p>Free<\/p><\/div>\n            <div><p>Free<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Hassle Free Refund and Cancellation<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>No<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Built in Virtual Event Platform<\/div>\n            <\/div>\n            <div><div class=\"elementor-element elementor-element-2fc1ec99   elementor-widget elementor-widget-heading\" data-id=\"2fc1ec99\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><p class=\"elementor-heading-title elementor-size-default\">Yes. No third party tools required.<\/p><\/div><\/div><\/div>\n            <div><p>No<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Ticket Scanner App<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>Yes<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Payouts During or Before Event<\/div>\n            <\/div>\n            <div><div class=\"elementor-element elementor-element-2b1bba1   elementor-widget elementor-widget-heading\" data-id=\"2b1bba1\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><p class=\"elementor-heading-title elementor-size-default\">Yes (On request)<\/p><\/div><\/div><\/div>\n            <div><div class=\"elementor-element elementor-element-6c7d581a elementor-widget elementor-widget-heading\" data-id=\"6c7d581a\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><p class=\"elementor-heading-title elementor-size-default\">4-7 business days after event ends<\/p><\/div><\/div><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Purchase Protection<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>No<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Fundraising Options<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>Limited<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Order Form Customization<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>Yes<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Survey Form<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>Yes<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Event Promotion Tools<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>Yes<\/p><\/div>\n        <\/div>\n                <div class=\"comparison-item\">\n            <div class=\"title-container\">\n                <div class=\"icon-svg\">\n                    <img decoding=\"async\" src=\"\">\n                <\/div>\n                <div class=\"table-title\">Customised Page Layout<\/div>\n            <\/div>\n            <div><p>Yes<\/p><\/div>\n            <div><p>No<\/p><\/div>\n        <\/div>\n        \n\n        <!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a68b328 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a68b328\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2baab173\" data-id=\"2baab173\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-72adb828 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72adb828\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4aad6637\" data-id=\"4aad6637\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-199128cf SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"199128cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Uncover your exact charges with EventBookings<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba066cd br-none elementor-widget elementor-widget-heading\" data-id=\"3ba066cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Recognizing the distinct requirements of every event and organization, we've designed an in-depth Pricing Calculator. This empowers you to meticulously calculate precise fees, unveiling both the<br> per-ticket cost for attendees and the expenses you'll incur.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b819230 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1b819230\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/en-us\/pricing\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calculate EventBookings Fees<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6685401a leverage-complete-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6685401a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-267c1718\" data-id=\"267c1718\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ae60b12 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"3ae60b12\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7 key benefits of using EventBookings<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1480f8a1 elementor-section-full_width SharpSans  br-none elementor-section-height-default elementor-section-height-default\" data-id=\"1480f8a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e2bc942\" data-id=\"e2bc942\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1337c307 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"1337c307\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"100\" height=\"100\" rx=\"50\" fill=\"#C0EBFA\"><\/rect><path d=\"M51.8577 43.2587C50.92 42.4932 49.8657 42.0045 48.8004 41.7702V40.1948C48.8004 39.3927 48.1503 38.7422 47.3478 38.7422C46.5453 38.7422 45.8948 39.3927 45.8948 40.1948V41.7562C44.3495 42.0956 42.9241 43.0201 42.2053 44.5426C41.4656 46.1102 41.5081 47.7292 42.4376 49.165C43.2994 50.4957 44.8194 51.5082 46.6945 52.2858C48.4048 52.9955 49.3215 53.7501 49.7471 54.4045C50.1221 54.9809 50.1946 55.5932 49.9058 56.3692C49.6466 57.0661 48.8745 57.6043 47.5598 57.6511C46.2604 57.6971 44.8553 57.2126 43.9764 56.3724C43.3964 55.8181 42.4766 55.8388 41.9224 56.4188C41.3677 56.9987 41.3884 57.9181 41.9684 58.4728C43.0426 59.4994 44.4581 60.151 45.8948 60.4192V61.8106C45.8948 62.6127 46.5453 63.2633 47.3478 63.2633C48.1503 63.2633 48.8004 62.6128 48.8004 61.8106V60.4223C50.4077 60.0996 51.9606 59.1798 52.629 57.3826C53.2043 55.8361 53.1107 54.2466 52.1827 52.8201C51.305 51.4708 49.7811 50.4207 47.8077 49.6019C46.1679 48.9217 45.2754 48.2019 44.8767 47.5857C44.5454 47.0743 44.4795 46.5314 44.8331 45.7823C45.1191 45.1758 45.8129 44.6672 46.8317 44.5401C47.833 44.415 49.0163 44.6898 50.0199 45.5095C50.6416 46.0169 51.5567 45.9246 52.0641 45.3029C52.5712 44.6812 52.4788 43.7661 51.8576 43.2587L51.8577 43.2587Z\" fill=\"black\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M31 65.0773C31 68.3485 33.6519 71 36.9227 71H57.5567C60.8275 71 63.4794 68.3485 63.4794 65.0773V36.9231C63.4794 33.6519 60.8275 31 57.5567 31H36.9227C33.6519 31 31 33.6519 31 36.9231V65.0773ZM36.9227 68.0948C35.2565 68.0948 33.9056 66.7439 33.9056 65.0773V36.9231C33.9056 35.2565 35.2565 33.9056 36.9227 33.9056H57.5567C59.2229 33.9056 60.5737 35.2565 60.5737 36.9231V65.0773C60.5737 66.7439 59.2229 68.0948 57.5567 68.0948H36.9227Z\" fill=\"black\"><\/path><path d=\"M73.4536 45.1953C73.4536 43.1588 71.8025 41.5078 69.7657 41.5078H67.7105C66.908 41.5078 66.2578 42.1579 66.2578 42.9605C66.2578 43.7626 66.9079 44.4131 67.7105 44.4131H69.7657C70.1975 44.4131 70.5479 44.7635 70.5479 45.1954V63.0994C70.5479 63.5313 70.1975 63.8817 69.7657 63.8817H67.7105C66.908 63.8817 66.2578 64.5322 66.2578 65.3343C66.2578 66.1368 66.9079 66.7873 67.7105 66.7873H69.7657C71.8025 66.7873 73.4536 65.1363 73.4536 63.0994V45.1953Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAffordable ticketing options\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWith just a 2.5% fee per ticket and an extra 30 cents in Australia, and a compelling 1% plus 30 cents for US, our platform offers industry-leading affordability. You can even pass these fees to attendees for added flexibility.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-132d33d4 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"132d33d4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.960938\" y=\"0.40625\" width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#BBF9BB\"><\/rect><path d=\"M69.6255 25.5H30.3551C28.9346 25.5 27.5728 26.0648 26.5683 27.0699C25.5642 28.0754 25 29.4387 25 30.8606V70.172C25 71.594 25.5642 72.9572 26.5683 73.9628C27.5727 74.9679 28.9346 75.5327 30.3551 75.5327H69.6255C71.046 75.5327 72.4078 74.9679 73.4123 73.9628C74.4164 72.9573 74.9806 71.594 74.9806 70.172V30.8606C74.9806 29.4387 74.4164 28.0755 73.4123 27.0699C72.4079 26.0648 71.046 25.5 69.6255 25.5ZM71.4106 70.172C71.4106 70.6459 71.2225 71.1006 70.8878 71.4356C70.5531 71.7707 70.0989 71.9589 69.6255 71.9589H30.3551C29.8817 71.9589 29.4275 71.7707 29.0928 71.4356C28.7581 71.1006 28.57 70.6459 28.57 70.172V39.7951H71.4106V70.172ZM71.4106 36.2213H28.57V30.8606C28.57 30.3868 28.7581 29.9321 29.0928 29.5971C29.4275 29.262 29.8817 29.0738 30.3551 29.0738H69.6255C70.0989 29.0738 70.5531 29.262 70.8878 29.5971C71.2225 29.9321 71.4106 30.3868 71.4106 30.8606V36.2213Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M33.9294 30.8594H32.1444C31.5065 30.8594 30.9172 31.2 30.5984 31.7528C30.2797 32.3056 30.2797 32.9869 30.5984 33.5397C30.9172 34.0925 31.5065 34.4331 32.1444 34.4331H33.9294C34.5673 34.4331 35.1566 34.0925 35.4753 33.5397C35.7941 32.9869 35.7941 32.3056 35.4753 31.7528C35.1566 31.2 34.5673 30.8594 33.9294 30.8594Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M41.07 30.8594H39.285C38.6471 30.8594 38.0578 31.2 37.7391 31.7528C37.4203 32.3056 37.4203 32.9869 37.7391 33.5397C38.0578 34.0925 38.6471 34.4331 39.285 34.4331H41.07C41.7079 34.4331 42.2972 34.0925 42.616 33.5397C42.9347 32.9869 42.9347 32.3056 42.616 31.7528C42.2972 31.2 41.7079 30.8594 41.07 30.8594Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M35.7107 54.0885H64.271C65.2177 54.0885 66.1258 53.712 66.7956 53.0419C67.4649 52.3714 67.8411 51.4624 67.8411 50.5147V46.941C67.8411 45.9933 67.4649 45.0842 66.7956 44.4138C66.1258 43.7437 65.2177 43.3672 64.271 43.3672H35.7107C34.764 43.3672 33.8559 43.7437 33.1861 44.4138C32.5168 45.0843 32.1406 45.9933 32.1406 46.941V50.5147C32.1406 51.4624 32.5168 52.3714 33.1861 53.0419C33.8559 53.712 34.764 54.0885 35.7107 54.0885ZM35.7107 46.941H64.271V50.5147H35.7107V46.941Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M62.4873 57.6641H55.3472C53.4338 57.6641 51.6659 58.686 50.7097 60.3444C49.753 62.0028 49.753 64.0466 50.7097 65.705C51.6659 67.3635 53.4338 68.3854 55.3472 68.3854H62.4873C64.4006 68.3854 66.1685 67.3635 67.1247 65.705C68.0814 64.0466 68.0814 62.0028 67.1247 60.3444C66.1685 58.686 64.4006 57.6641 62.4873 57.6641ZM62.4873 64.8116H55.3472C54.7093 64.8116 54.12 64.471 53.8012 63.9181C53.4825 63.3653 53.4825 62.6841 53.8012 62.1313C54.12 61.5785 54.7093 61.2378 55.3472 61.2378H62.4873C63.1252 61.2378 63.7144 61.5784 64.0332 62.1313C64.3519 62.6841 64.3519 63.3653 64.0332 63.9181C63.7144 64.471 63.1251 64.8116 62.4873 64.8116Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUser-friendly interface\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tArranging, managing, and boosting events is effortless using our simple and user-centric platform.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-302b8a53 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"302b8a53\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-302b8a53{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583ed0f7 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"583ed0f7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100\" height=\"101\" viewbox=\"0 0 100 101\" fill=\"none\"><rect width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#E9D8FB\"><\/rect><path d=\"M63.448 51.2193L40.7321 55.072C40.1493 55.1186 39.636 55.4728 39.3849 56.0015C39.1341 56.5299 39.1839 57.1519 39.5155 57.634C39.8472 58.1157 40.4103 58.3835 40.993 58.3369H41.2704L63.9863 54.4354C64.5688 54.3392 65.0558 53.9391 65.264 53.386C65.4722 52.8329 65.3696 52.2104 64.995 51.7535C64.6205 51.2966 64.0307 51.0743 63.4479 51.1705L63.448 51.2193Z\" fill=\"black\" stroke=\"#E9D8FB\" stroke-width=\"0.5\"><\/path><path d=\"M48.5623 50.6143C49.2961 51.1215 50.1658 51.3945 51.0572 51.3978C52.4513 51.4025 53.7599 50.7262 54.5633 49.5856C55.2265 48.6565 55.4926 47.5009 55.3026 46.375C55.1126 45.2487 54.4821 44.2448 53.5506 43.5853C52.6195 42.9258 51.4637 42.6648 50.3397 42.8602C49.227 43.0482 48.2335 43.668 47.5739 44.5848C46.9147 45.5016 46.6428 46.6414 46.8172 47.7575C46.9941 48.905 47.6224 49.9336 48.5623 50.6143H48.5623ZM50.1931 46.5004C50.3529 46.2777 50.5924 46.1258 50.8617 46.0758H51.0412C51.2578 46.0758 51.4689 46.1443 51.6444 46.2719C52.1012 46.6053 52.2097 47.2422 51.889 47.7083C51.7314 47.9364 51.4882 48.0912 51.2148 48.1375C50.9418 48.1834 50.6615 48.1171 50.4377 47.9531C50.2084 47.8001 50.0544 47.557 50.0136 47.2841C49.9674 47.0068 50.0384 46.723 50.2095 46.5003L50.1931 46.5004Z\" fill=\"black\" stroke=\"#E9D8FB\" stroke-width=\"0.5\"><\/path><path d=\"M56.1416 58.9065C55.2115 58.2447 54.0569 57.9795 52.9318 58.1693C51.8067 58.3592 50.8023 58.9881 50.1406 59.9187C49.4748 60.8672 49.2113 62.0409 49.4067 63.1837C49.5855 64.1809 50.1075 65.0847 50.8817 65.7377C51.6559 66.3906 52.6341 66.7517 53.6467 66.7586C55.0397 66.7605 56.3472 66.0849 57.1528 64.9465C57.8244 64.0133 58.0952 62.8498 57.9052 61.7155C57.7156 60.5811 57.0804 59.5696 56.1416 58.9064L56.1416 58.9065ZM54.5108 63.004C54.3532 63.2321 54.11 63.387 53.8367 63.4329C53.5633 63.4792 53.283 63.4125 53.0595 63.2489C52.8349 63.0937 52.6868 62.8506 52.6518 62.5795C52.5998 62.308 52.6613 62.0275 52.8215 61.8023C52.9816 61.5774 53.2266 61.4277 53.4996 61.388H53.6627C53.8796 61.388 54.0908 61.4565 54.2662 61.5836C54.4857 61.7411 54.6335 61.9794 54.6764 62.2461C54.719 62.5128 54.6539 62.7858 54.4944 63.004L54.5108 63.004Z\" fill=\"black\" stroke=\"#E9D8FB\" stroke-width=\"0.5\"><\/path><path d=\"M74.7654 50.2735L70.6721 34.7326C70.3525 33.5494 69.6299 32.5152 68.6296 31.8087C67.629 31.1022 66.4132 30.768 65.1926 30.8638L54.1687 31.7129L53.7283 30.0804L53.7286 30.0801C53.4964 29.1505 52.9438 28.3325 52.1681 27.7709C51.3925 27.2094 50.4431 26.9401 49.4887 27.0112L38.8403 27.8438H38.8399C37.4458 27.9367 36.1685 28.6568 35.3666 29.8028L26.9354 41.7029C26.1797 42.7242 25.8627 44.0055 26.0549 45.2614C26.2995 46.4763 27.0148 47.5447 28.0446 48.2327L32.5779 51.4976L31.8441 52.5259C30.89 53.8945 30.5173 55.5864 30.8078 57.2298C31.0979 58.8735 32.0279 60.3343 33.3933 61.2923L52.4405 74.8417C53.4946 75.5872 54.7541 75.9863 56.0446 75.9844C56.3758 76.0052 56.7082 76.0052 57.0394 75.9844C58.6815 75.7093 60.144 74.7859 61.0999 73.4213L73.7546 55.579C74.8881 54.0599 75.2609 52.1035 74.7659 50.2735H74.7654ZM34.5183 48.886L29.9194 45.621H29.9198C29.6016 45.4123 29.3836 45.0814 29.3162 44.7068C29.254 44.3169 29.3479 43.9183 29.5772 43.5969L38.0244 31.6968C38.2773 31.3495 38.6723 31.1338 39.1007 31.109L49.7174 30.2764C50.0734 30.2793 50.3883 30.5093 50.5 30.8478L50.8426 31.9089L49.2118 32.0393C47.3601 32.1745 45.6635 33.1252 44.5806 34.6352L34.5183 48.886ZM71.1619 53.6037L58.4904 71.4627C58.0398 72.1106 57.3449 72.5464 56.5663 72.671C55.7808 72.8175 54.9694 72.6408 54.3157 72.1813L35.2852 58.6478C34.6398 58.1824 34.2034 57.4817 34.0691 56.6972C33.9347 55.9123 34.1138 55.1063 34.5678 54.4526L47.255 36.6094C47.7778 35.8807 48.5957 35.4205 49.4894 35.3526L53.0934 35.075L65.4704 34.1119H65.6335C66.0717 34.1174 66.4962 34.265 66.843 34.5331C67.1903 34.801 67.4411 35.1745 67.5576 35.5975L71.6509 51.1226C71.8674 51.9811 71.688 52.8917 71.1616 53.6038L71.1619 53.6037Z\" fill=\"black\" stroke=\"#E9D8FB\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDiscount codes and promotions\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCreate and distribute discount codes to incentivize ticket purchases or run promotional campaigns, helping you attract more attendees and boost ticket sales.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a82bc5b elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5a82bc5b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.960938\" y=\"0.507812\" width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#FFB661\"><\/rect><path d=\"M74.0651 57.1848C73.6173 56.6291 72.804 56.5412 72.2485 56.9891L64.8094 62.9833L61.6208 60.1415V60.1411C61.0871 59.6662 60.27 59.714 59.7956 60.2481C59.3209 60.7823 59.369 61.6003 59.9026 62.0756L63.9107 65.6453C64.3823 66.0647 65.0883 66.082 65.58 65.6857L73.872 59.0041C74.4271 58.555 74.5133 57.7405 74.0651 57.1848L74.0651 57.1848Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M66.9075 49.4062C63.7247 49.4062 60.6719 50.6722 58.4212 52.9251C56.1705 55.1782 54.9062 58.2338 54.9062 61.4199C54.9062 64.6064 56.1705 67.662 58.4212 69.9151C60.6719 72.1681 63.7247 73.4339 66.9075 73.4339C70.0903 73.4339 73.1428 72.168 75.3934 69.9151C77.6441 67.662 78.9086 64.6064 78.9086 61.4199C78.9052 58.2349 77.6394 55.1812 75.3896 52.929C73.1398 50.6767 70.0892 49.4101 66.9075 49.4062ZM66.9075 70.8453V70.8457C64.4103 70.8457 62.0153 69.8524 60.2494 68.0847C58.4834 66.3169 57.4916 63.9195 57.4916 61.4196C57.4916 58.9198 58.4834 56.5223 60.2494 54.7545C62.0153 52.9871 64.4102 51.9939 66.9075 51.9939C69.4047 51.9939 71.7997 52.9871 73.5656 54.7545C75.3312 56.5223 76.3234 58.9197 76.3234 61.4196C76.3207 63.9187 75.3277 66.3145 73.5626 68.0815C71.7974 69.8489 69.404 70.8429 66.9076 70.8456L66.9075 70.8453Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M40.7878 47.9045C39.7463 46.9286 38.3647 46.3994 36.9386 46.431C35.5124 46.4622 34.155 47.0515 33.1578 48.0721C32.1602 49.093 31.6016 50.4642 31.6016 51.8922C31.6016 53.3202 32.1602 54.6913 33.1578 55.7123C34.155 56.7329 35.5123 57.3221 36.9386 57.3534C38.3647 57.3849 39.7463 56.8558 40.7878 55.8799C41.8288 56.8546 43.21 57.3826 44.635 57.3507C46.06 57.3191 47.4162 56.7299 48.4126 55.7096C49.4094 54.6894 49.9676 53.3191 49.9676 51.8922C49.9676 50.4653 49.4094 49.095 48.4126 48.0748C47.4162 47.0545 46.0599 46.4653 44.635 46.4337C43.2099 46.4017 41.8288 46.9297 40.7878 47.9045ZM37.0744 54.7713C36.313 54.7717 35.5827 54.469 35.0442 53.9302C34.5056 53.3914 34.2032 52.6604 34.2028 51.8983C34.2028 51.1361 34.5052 50.4051 35.0434 49.866C35.5817 49.3272 36.3119 49.0241 37.0732 49.0241C37.8345 49.0241 38.5648 49.3268 39.103 49.8656C39.6416 50.4048 39.944 51.1358 39.944 51.8979C39.9432 52.6597 39.6409 53.3899 39.103 53.9287C38.5648 54.4675 37.8353 54.7706 37.0743 54.7714L37.0744 54.7713ZM47.3715 51.8944C47.3723 52.6981 47.0364 53.4657 46.4451 54.0095C45.8538 54.5533 45.0616 54.824 44.2614 54.7551C43.4612 54.6861 42.7267 54.2841 42.2369 53.6471C42.627 52.5125 42.627 51.2801 42.2369 50.1455C42.7736 49.4353 43.6135 49.0197 44.5034 49.024C45.2628 49.0247 45.9911 49.3271 46.5289 49.8643C47.0664 50.4016 47.3692 51.1303 47.3715 51.8909L47.3715 51.8944Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M66.3177 40.4112C66.3177 39.6968 65.7391 39.1172 65.025 39.1172H54.4255C53.7114 39.1172 53.1328 39.6968 53.1328 40.4112C53.1328 41.126 53.7114 41.7053 54.4255 41.7053H65.025C65.3678 41.7053 65.6968 41.5689 65.9391 41.3263C66.1815 41.0837 66.3177 40.7547 66.3177 40.4112Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M52.7752 60.8846H27.9301C27.7396 60.8846 27.5853 60.7302 27.5853 60.5395V35.9337C27.5853 35.7431 27.7396 35.5886 27.9301 35.5886H70.0101C70.1012 35.5886 70.189 35.6252 70.2536 35.6899C70.3182 35.7546 70.3548 35.842 70.3548 35.9337V47.6978C71.2447 47.922 72.1107 48.2328 72.9402 48.626V35.9331C72.9402 35.1552 72.6312 34.4092 72.0818 33.8592C71.5324 33.3093 70.7872 33 70.0101 33H27.9301C27.1529 33 26.4077 33.3093 25.8579 33.8592C25.3086 34.4092 25 35.1552 25 35.9331V60.539C25 61.3169 25.3086 62.0629 25.8579 62.6133C26.4077 63.1632 27.1529 63.4721 27.9301 63.4721H52.9131H52.9128C52.8085 62.7943 52.7535 62.1095 52.7485 61.4232C52.7485 61.2422 52.7681 61.0647 52.775 60.884L52.7752 60.8846Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSwift and secure transactions\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRest assured, as your information stays protected with our dependable payment processing system, ensuring quick and smooth transactions.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24997540\" data-id=\"24997540\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65df556e elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"65df556e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><path d=\"M65.6175 33.3273L64.0728 32.1582C64.0473 32.1402 64.0214 32.1281 63.9959 32.1101C63.2649 28.5016 59.8746 25.7624 55.8043 25.7624H55.6251L51.6191 22.7292C48.4273 20.3497 43.9725 20.3497 40.7741 22.7351L36.7749 25.7623H36.5956C32.5257 25.7623 29.1288 28.5078 28.4045 32.1162C28.3661 32.1401 28.3214 32.1581 28.2892 32.1882L26.7893 33.3213C24.0585 35.3889 22.4883 38.4644 22.4883 41.755V60.1277C22.4883 65.6366 27.2825 70.1203 33.1791 70.1203H59.2336C65.124 70.1203 69.9182 65.6366 69.9182 60.1219V41.7546C69.9182 38.4639 68.348 35.3948 65.6176 33.3268L65.6175 33.3273ZM67.1108 39.8012L64.1497 42.0068V35.3112C65.643 36.492 66.6686 38.0625 67.1108 39.8011V39.8012ZM42.3828 24.6055C44.6325 22.9271 47.7734 22.9271 50.0163 24.5996L51.5547 25.7624H40.8506L42.3828 24.6055ZM36.6014 28.16H55.8104C58.9959 28.16 61.5917 30.5819 61.5917 33.5669V43.9254L50.0226 52.551C47.7729 54.2295 44.632 54.2295 42.3823 52.551L30.8201 43.9191V33.5669C30.8201 30.5819 33.4092 28.16 36.6014 28.16ZM28.2561 35.3114V42.007L25.295 39.801C25.7372 38.0628 26.7628 36.4923 28.2561 35.3115V35.3114ZM59.2264 67.7226H33.1776C28.6973 67.7226 25.0504 64.3115 25.0504 60.1218V42.6836L40.7799 54.4207C42.376 55.6137 44.286 56.2071 46.2022 56.2071C48.1185 56.2071 50.0289 55.6137 51.6245 54.4207L67.3541 42.6836V60.1207C67.3541 64.3109 63.7072 67.722 59.2269 67.722L59.2264 67.7226Z\" fill=\"black\"><\/path><path d=\"M39.9497 37.7573H52.4677C53.1727 37.7573 53.7495 37.2179 53.7495 36.5586C53.7495 35.8992 53.1727 35.3598 52.4677 35.3598L39.9497 35.3594C39.2447 35.3594 38.668 35.8988 38.668 36.5581C38.668 37.2175 39.2385 37.7573 39.9497 37.7573V37.7573Z\" fill=\"black\"><\/path><path d=\"M39.9497 46.1475H52.4677C53.1727 46.1475 53.7495 45.6081 53.7495 44.9488C53.7495 44.2894 53.1727 43.75 52.4677 43.75H39.9497C39.2447 43.75 38.668 44.2894 38.668 44.9488C38.668 45.6082 39.2385 46.1475 39.9497 46.1475Z\" fill=\"black\"><\/path><rect x=\"0.660156\" y=\"0.5\" width=\"100\" height=\"100\" rx=\"50\" fill=\"#FFC9BD\"><\/rect><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M33.7143 46.485C32.6364 46.7632 31.6416 47.3258 30.8419 48.1273C29.6615 49.3059 29 50.904 29 52.5711V57.2854C29 58.9526 29.6615 60.5506 30.8419 61.7292C32.0205 62.9096 33.6186 63.5711 35.2857 63.5711H36.8571C37.6899 63.5711 38.49 63.2396 39.0792 62.6503C39.6685 62.0611 40 61.2609 40 60.4283V49.4283C40 48.5956 39.6685 47.7954 39.0792 47.2062C38.4899 46.617 37.6916 46.2854 36.8571 46.2854V44.6309C36.9091 37.6818 43.2684 32.143 51 32.143C58.7628 32.143 65.1429 37.7278 65.1429 44.7144V46.2858C64.3101 46.2858 63.51 46.6173 62.9208 47.2066C62.3315 47.7958 62 48.596 62 49.4286V60.4286C62 61.2613 62.3315 62.0615 62.9208 62.6507C63.3498 63.0797 63.8889 63.3719 64.4718 63.4992C63.9502 64.6163 63.3059 65.4806 62.396 66.0293C61.7832 66.3986 61.0571 66.6105 60.1929 66.6782C59.5313 64.8679 57.787 63.5714 55.7378 63.5714C53.1201 63.5714 51 65.6866 51 68.2857C51 70.8849 53.12 73 55.7378 73C57.8136 73 59.5751 71.6706 60.2164 69.8255C61.7359 69.7361 62.9776 69.3478 64.0176 68.721C65.7606 67.6697 66.9721 65.9033 67.8739 63.463C69.1107 63.2318 70.2577 62.6317 71.1581 61.7295C72.3385 60.5509 73 58.9528 73 57.2857V52.5714C73 50.9042 72.3385 49.3061 71.1581 48.1276C70.3584 47.3261 69.3636 46.7635 68.2857 46.4853V44.7143C68.2857 36.0886 60.5843 29 51 29C41.4547 29 33.7753 36.0335 33.7143 44.6119V46.485ZM57.3064 67.9992C57.1696 67.2651 56.5161 66.7137 55.7381 66.7137C54.8612 66.7137 54.1431 67.4145 54.1431 68.2851C54.1431 69.1557 54.8611 69.8565 55.7381 69.8565C56.527 69.8565 57.1885 69.2894 57.3127 68.5412C57.2892 68.4202 57.2814 68.2929 57.2892 68.1659C57.2923 68.1091 57.2987 68.0525 57.3064 67.9992ZM66.7367 60.428C67.5617 60.4217 68.352 60.0916 68.9367 59.5072C69.526 58.9179 69.8575 58.1178 69.8575 57.2851V52.5709C69.8575 51.7381 69.526 50.938 68.9367 50.3488C68.3474 49.7595 67.5473 49.428 66.7146 49.428H65.1432V60.428H66.7367ZM36.8571 49.428V60.428H35.2857C34.453 60.428 33.6529 60.0965 33.0636 59.5072C32.4744 58.9179 32.1429 58.1178 32.1429 57.2851V52.5709C32.1429 51.7381 32.4743 50.938 33.0636 50.3488C33.6529 49.7595 34.453 49.428 35.2857 49.428H36.8571Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDedicated customer support\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCount on the EventBookings team for exceptional support. Whether it's inquiries, event setup, or complex issues, we're here to help anywhere, anytime.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a085da8 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5a085da8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.125\" y=\"0.507812\" width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#C7CBFD\"><\/rect><path d=\"M67.7204 31H31.9809C30.6265 31 29.3282 31.5265 28.3704 32.4644C27.4131 33.4019 26.875 34.6738 26.875 35.9997V58.4998C26.875 59.8261 27.4131 61.0976 28.3704 62.0355C29.3282 62.973 30.6265 63.5 31.9809 63.5H47.2981V68.5001H40.9157C40.2109 68.5001 39.6395 69.0597 39.6395 69.7498C39.6395 70.4404 40.2109 71 40.9157 71H58.7865C59.4912 71 60.0626 70.4404 60.0626 69.7498C60.0626 69.0597 59.4912 68.5001 58.7865 68.5001H52.404V63.5H67.7212C69.0756 63.5 70.374 62.973 71.3317 62.0355C72.2891 61.0976 72.8271 59.8261 72.8271 58.4998V35.9997C72.8271 34.6738 72.2891 33.4019 71.3317 32.4644C70.374 31.5265 69.0756 31 67.7212 31H67.7204ZM70.2731 58.5005L70.2735 58.5C70.2727 59.163 70.0034 59.7983 69.5247 60.267C69.0461 60.7358 68.3973 60.9995 67.7204 61.0003H31.9809C31.3039 60.9995 30.6552 60.7358 30.1765 60.267C29.6979 59.7983 29.4286 59.1629 29.4278 58.5V36C29.4286 35.3374 29.6979 34.7017 30.1765 34.2334C30.6552 33.7646 31.304 33.501 31.9809 33.5001H67.7204C68.3973 33.5009 69.0461 33.7646 69.5247 34.2334C70.0034 34.7017 70.2727 35.3375 70.2735 36L70.2731 58.5005ZM49.8502 48.5001C51.2041 48.5001 52.5029 47.9732 53.4607 47.0357C54.418 46.0978 54.9561 44.8263 54.9561 43.5C54.9561 42.1741 54.418 40.9022 53.4607 39.9647C52.5029 39.0268 51.2041 38.5002 49.8502 38.5002C48.4962 38.5002 47.1975 39.0268 46.2397 39.9647C45.2824 40.9022 44.7443 42.1741 44.7443 43.5C44.7456 44.8259 45.2841 46.0969 46.2414 47.034C47.1988 47.9715 48.4967 48.4989 49.8502 48.5001ZM49.8502 41.0001C50.5271 41.0001 51.1768 41.2634 51.6554 41.7325C52.1341 42.2013 52.4029 42.8371 52.4029 43.5C52.4029 44.1633 52.1341 44.7991 51.6554 45.2678C51.1768 45.7366 50.5272 46.0003 49.8502 46.0003C49.1732 46.0003 48.5236 45.7366 48.0449 45.2678C47.5663 44.7991 47.2975 44.1633 47.2975 43.5C47.2983 42.8374 47.5676 42.2021 48.0458 41.7334C48.5245 41.2646 49.1733 41.001 49.8502 41.0001ZM60.0611 56.3981L60.0615 57.2498C60.0615 57.9399 59.4901 58.4995 58.7854 58.4995C58.0802 58.4995 57.5088 57.9399 57.5088 57.2498V56.3977C57.5088 55.8975 57.2041 55.4455 56.7348 55.2488L55.3809 54.68C51.8473 53.2055 47.853 53.2055 44.3197 54.68L42.9648 55.2488H42.9644C42.4956 55.4463 42.1917 55.8979 42.1917 56.3977V57.2498C42.1917 57.9399 41.6203 58.4995 40.9151 58.4995C40.2104 58.4995 39.639 57.9399 39.639 57.2498V56.3977C39.6386 55.664 39.8582 54.9462 40.2707 54.3334C40.6831 53.7207 41.2699 53.2403 41.9588 52.9515L43.315 52.3827C47.49 50.6395 52.2109 50.6395 56.386 52.3827L57.7408 52.9515C58.4302 53.2403 59.0174 53.7208 59.4299 54.3331C59.8427 54.9459 60.0624 55.6636 60.062 56.3978L60.0611 56.3981Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIntegrated video conferencing\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNo longer worry about investing extra time and money in third-party video conferencing software. EventBookings seamlessly integrates it all for you.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-628105c1 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"628105c1\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100\" height=\"100\" viewbox=\"0 0 100 100\" fill=\"none\"><rect width=\"100\" height=\"100\" rx=\"50\" fill=\"#C0EBFA\"><\/rect><path d=\"M69.1292 37.382L67.5845 36.2128C67.559 36.1949 67.5331 36.1827 67.5076 36.1648C66.7766 32.5563 63.3863 29.8171 59.3161 29.8171H59.1368L55.1309 26.7839C51.9391 24.4044 47.4842 24.4044 44.2858 26.7898L40.2866 29.817H40.1073C36.0374 29.817 32.6405 32.5624 31.9163 36.1709C31.8778 36.1948 31.8331 36.2127 31.8009 36.2429L30.301 37.376C27.5702 39.4436 26 42.519 26 45.8097V64.1824C26 69.6913 30.7942 74.175 36.6908 74.175H62.7453C68.6357 74.175 73.4299 69.6913 73.4299 64.1766V45.8093C73.4299 42.5186 71.8597 39.4495 69.1294 37.3815L69.1292 37.382ZM70.6225 43.8559L67.6614 46.0615V39.3659C69.1547 40.5467 70.1803 42.1172 70.6225 43.8557V43.8559ZM45.8945 28.6602C48.1442 26.9818 51.2851 26.9818 53.5281 28.6543L55.0665 29.8171H44.3623L45.8945 28.6602ZM40.1131 32.2147H59.3221C62.5076 32.2147 65.1035 34.6365 65.1035 37.6216V47.9801L53.5344 56.6057C51.2846 58.2841 48.1438 58.2841 45.894 56.6057L34.3318 47.9738V37.6216C34.3318 34.6365 36.9209 32.2147 40.1131 32.2147ZM31.7678 39.3661V46.0617L28.8067 43.8556C29.2489 42.1175 30.2745 40.547 31.7678 39.3662V39.3661ZM62.7381 71.7773H36.6893C32.209 71.7773 28.5621 68.3662 28.5621 64.1765V46.7383L44.2917 58.4754C45.8877 59.6684 47.7978 60.2617 49.714 60.2617C51.6302 60.2617 53.5407 59.6684 55.1363 58.4754L70.8658 46.7383V64.1754C70.8658 68.3656 67.2189 71.7767 62.7386 71.7767L62.7381 71.7773Z\" fill=\"black\"><\/path><path d=\"M43.4615 41.812H55.9794C56.6845 41.812 57.2612 41.2726 57.2612 40.6132C57.2612 39.9539 56.6844 39.4145 55.9794 39.4145L43.4615 39.4141C42.7564 39.4141 42.1797 39.9535 42.1797 40.6128C42.1797 41.2722 42.7502 41.812 43.4615 41.812V41.812Z\" fill=\"black\"><\/path><path d=\"M43.4615 50.2022H55.9794C56.6845 50.2022 57.2612 49.6628 57.2612 49.0035C57.2612 48.3441 56.6844 47.8047 55.9794 47.8047H43.4615C42.7564 47.8047 42.1797 48.3441 42.1797 49.0035C42.1797 49.6629 42.7502 50.2022 43.4615 50.2022Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBuilt-in email marketing\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCut costs and time with EventBookings' in-platform email marketing tools \u2013 no external services needed.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-319bfa90 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"319bfa90\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-28ac72c9\" data-id=\"28ac72c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d5d0cd1 elementor-mobile-align-center elementor-align-center new-fix-url elementor-widget elementor-widget-button\" data-id=\"1d5d0cd1\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33f4ba60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33f4ba60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-525415c1\" data-id=\"525415c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58a2187e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58a2187e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4dfc1888\" data-id=\"4dfc1888\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-612a268 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"612a268\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manage everything on a single platform<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f454b44 br-none elementor-widget elementor-widget-heading\" data-id=\"7f454b44\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">EventBookings presents an all-inclusive ticketing solution. Its intuitive design comes with an array of exceptional features that can enhance your event experiences. Learn more about <br>these features in comparison to Ticketleap:<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5df687c9 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5df687c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69187968\" data-id=\"69187968\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ad9641f elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ad9641f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78380695\" data-id=\"78380695\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1658be8d elementor-widget elementor-widget-image\" data-id=\"1658be8d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"633\" height=\"447\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-1.png\" class=\"attachment-full size-full wp-image-114965\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-1.png 633w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-1-300x212.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-1-18x12.png 18w\" sizes=\"(max-width: 633px) 100vw, 633px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43244e6b\" data-id=\"43244e6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef8277f SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"ef8277f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Customizable and high-converting event page<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-307e2ec1 br-none elementor-widget elementor-widget-heading\" data-id=\"307e2ec1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Tailor your event's appearance to match your branding with EventBookings. Alongside an irresistible event description, you can add texts, images, videos, PDFs, event thumbnails, and event tags and use smartly positioned social buttons, booking times, and call-to-actions. Whereas Ticketleap restricts to a fixed event template allowing only a hero image and accent color.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b196928 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b196928\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-612d89ff\" data-id=\"612d89ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57bb50a0 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"57bb50a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cost-effective ticketing system <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-671d371d elementor-widget elementor-widget-text-editor\" data-id=\"671d371d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Choose EventBookings for affordability compared to Ticketleap. Our fees are 1% + 30\u00a2 on US and 2.5% + 30\u00a2 per ticket within Australia, while TicketLeap offers pricing at $1 plus 2%, with an average credit card fee of a total of 3%.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-40b59a34\" data-id=\"40b59a34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3484a9 elementor-widget elementor-widget-image\" data-id=\"3e3484a9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"679\" height=\"531\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event.png\" class=\"attachment-full size-full wp-image-220246\" alt=\"Compare with EventBookings competitors\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event.png 679w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event-300x235.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event-15x12.png 15w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4eaba5 elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b4eaba5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-145ba93\" data-id=\"145ba93\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-401d93c elementor-widget elementor-widget-image\" data-id=\"401d93c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"554\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events.png\" class=\"attachment-full size-full wp-image-220226\" alt=\"My events\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events.png 717w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events-300x232.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events-16x12.png 16w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a71999\" data-id=\"9a71999\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-865f1eb SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"865f1eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Flexible ticketing fees<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72809ed br-none elementor-widget elementor-widget-heading\" data-id=\"72809ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">EventBookings gives organizers the flexibility to cover event service charges by themselves or pass them to attendees, keeping their revenue intact. But Ticketleap controls all displayed ticketing fees and does not allow additional fees, reducing potential revenue.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f345c7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4f345c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3519d45\" data-id=\"3519d45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cb941e SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"8cb941e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zero-cost inbuilt video hosting<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a62cb0 elementor-widget elementor-widget-text-editor\" data-id=\"3a62cb0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Say goodbye to the hassle of third-party video hosting software. EventBookings offers a solution with integrated video conferencing and hosting for all your online events. When using Ticketleap, dealing with complex third-party hosting software can be frustrating.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b2731c0\" data-id=\"b2731c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c4bb5c elementor-widget elementor-widget-image\" data-id=\"6c4bb5c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"502\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2025\/02\/Run-virtual-business-events-1.png\" class=\"attachment-full size-full wp-image-214351\" alt=\"Run virtual business events\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2025\/02\/Run-virtual-business-events-1.png 673w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2025\/02\/Run-virtual-business-events-1-300x224.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2025\/02\/Run-virtual-business-events-1-16x12.png 16w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4779e77f elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4779e77f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7f485fa4\" data-id=\"7f485fa4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6733a6cf elementor-widget elementor-widget-image\" data-id=\"6733a6cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"481\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting.png\" class=\"attachment-full size-full wp-image-220336\" alt=\"Track sales in real-time with advanced reporting\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting.png 668w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting-300x216.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting-18x12.png 18w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44487673\" data-id=\"44487673\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fa57c05 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"3fa57c05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Advanced data analysis dashboard<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3490cd68 br-none elementor-widget elementor-widget-heading\" data-id=\"3490cd68\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Uncover event insights with EventBookings's advanced dashboard and get details on attendees, payouts, conversions, ticket sales, revenue, page views, and beyond. Additionally, leverage the dashboard to extend invitations to potential attendees, craft registration forms, and access in-depth visitor and campaign details.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d234d64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d234d64\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-210de088\" data-id=\"210de088\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d67f6a4 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"d67f6a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Your privacy is our focus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f45b474 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f45b474\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-79502c71\" data-id=\"79502c71\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7db18d8d SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"7db18d8d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"84.453\" height=\"93.891\" viewbox=\"0 0 84.453 93.891\"><g id=\"on-site-icon\" transform=\"translate(0.7 0.701)\"><path id=\"Path_19689\" data-name=\"Path 19689\" d=\"M106.655,94.613a10.43,10.43,0,0,0,14.735,0l1.548-1.548a9.563,9.563,0,0,0,12.413-.944l2.889-2.889,15.924,15.9a6.778,6.778,0,0,0,4.843,1.963,8.5,8.5,0,0,0,8.24-7.721A6.8,6.8,0,0,0,165.3,93.99L149.443,78.113c6.249-5.551,12.574-6.947,20.993-7.3l.991.991h0a7.824,7.824,0,0,0,11.063,0l.085-.085a7.815,7.815,0,0,0,0-11.053L140.6,18.693a7.825,7.825,0,0,0-11.053,0l-.094.094a7.826,7.826,0,0,0,0,11.054l.991.991c-.368,9.109-1.983,15.773-8.741,22.531L109.154,65.908a9.561,9.561,0,0,0-.944,12.413l-1.558,1.558a10.431,10.431,0,0,0,0,14.735Zm3.332-3.342a5.663,5.663,0,0,1,0-8.061l1.463-1.463,8.061,8.061-1.463,1.463a5.664,5.664,0,0,1-8.061.01Zm51.473,10.006c-1.217,1.208-3.03,1.454-3.965.51L141.581,85.882l4.5-4.474,15.9,15.915c.935.934.7,2.746-.519,3.955ZM132.783,22.138l.094-.094h0a3.105,3.105,0,0,1,4.379,0L179.244,64a3.1,3.1,0,0,1,0,4.379l-.085.085a3.1,3.1,0,0,1-4.38,0l-42-41.966a3.107,3.107,0,0,1,0-4.362ZM166.01,66.4c-7.448.736-13.725,2.832-19.909,8.373L126.5,55.176c5.569-6.174,7.637-12.46,8.373-19.909ZM112.5,69.232l10.7-10.686,19.521,19.521-10.7,10.7a4.862,4.862,0,0,1-6.872,0L112.5,76.123a4.862,4.862,0,0,1,0-6.872Z\" transform=\"translate(-103.606 -14.602)\" fill=\"#22d88f\" stroke=\"#fff\" stroke-width=\"1.4\"><\/path><path id=\"Path_19690\" data-name=\"Path 19690\" d=\"M492.57,58.174l-5.135,5.182a2.36,2.36,0,0,0,3.323,3.313l5.173-5.125a2.379,2.379,0,1,0-3.36-3.37Z\" transform=\"translate(-422.305 -48.75)\" fill=\"#22d88f\" stroke=\"#fff\" stroke-width=\"1.4\"><\/path><path id=\"Path_19691\" data-name=\"Path 19691\" d=\"M536.015,159.82l-6.976.34a2.361,2.361,0,0,0,.113,4.72h.113l6.947-.331h0a2.363,2.363,0,1,0-.227-4.72Z\" transform=\"translate(-455.412 -133.84)\" fill=\"#22d88f\" stroke=\"#fff\" stroke-width=\"1.4\"><\/path><path id=\"Path_19692\" data-name=\"Path 19692\" d=\"M414.567,17.345a2.359,2.359,0,0,0,2.35-2.228l.331-6.947h0a2.363,2.363,0,1,0-4.72-.227L412.2,14.89h0a2.361,2.361,0,0,0,2.247,2.473Z\" transform=\"translate(-360.179 -5.694)\" fill=\"#22d88f\" stroke=\"#fff\" stroke-width=\"1.4\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGuaranteed privacy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe are committed to safeguarding your attendee's privacy in EventBookings. Their preferences will never be utilized to display other events on your event page.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-54e37eca\" data-id=\"54e37eca\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1defa888 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"1defa888\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\" viewbox=\"0 0 64 64\" fill=\"none\"><path d=\"M44.9089 21.7763C46.5348 21.7763 48.0942 21.1304 49.244 19.9807C50.3937 18.831 51.0396 17.2717 51.0396 15.6458C51.0396 14.0199 50.3937 12.4606 49.244 11.3109C48.0942 10.1612 46.5348 9.51532 44.9089 9.51532C44.7637 8.17194 44.1209 6.93156 43.107 6.03832C42.0931 5.14509 40.7816 4.66372 39.4305 4.68895C38.4141 4.71239 37.4215 5.00167 36.5516 5.52799C35.6817 6.05431 34.9649 6.79931 34.4724 7.68881C34.1242 6.12077 33.2468 4.72036 31.9878 3.72291C30.7287 2.72545 29.1646 2.19175 27.5584 2.21146C25.6609 2.22797 23.8457 2.98908 22.5038 4.33087C21.162 5.67265 20.4008 7.48776 20.3843 9.38526V9.51603C19.9144 9.40156 19.4301 9.35749 18.9472 9.38526C17.3212 9.38526 15.7618 10.0311 14.6121 11.1808C13.4623 12.3305 12.8164 13.8898 12.8164 15.5158C12.8164 17.1417 13.4623 18.701 14.6121 19.8507C15.7618 21.0004 17.3212 21.6462 18.9472 21.6462H44.9038L44.9089 21.7763Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M4.60547 41.3438H25.4754V55.6906H4.60547V41.3438Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M59.3897 55.6906H43.738C43.0466 55.6887 42.3841 55.4132 41.8952 54.9244C41.4063 54.4355 41.1308 53.773 41.1289 53.0816V43.9527C41.1308 43.2614 41.4063 42.5989 41.8952 42.11C42.3841 41.6211 43.0466 41.3456 43.738 41.3438H59.3905C60.0819 41.3456 60.7444 41.6211 61.2333 42.11C61.7222 42.5989 61.9977 43.2614 61.9996 43.9527V53.0823C61.9975 53.7737 61.7218 54.4361 61.2328 54.9249C60.7437 55.4136 60.0811 55.6889 59.3897 55.6906Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M28.0838 62.2089H2L4.6091 55.6875H25.4747L28.0838 62.2089Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M51.5625 55.6875V60.904\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M46.3477 60.9062H56.7826\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M34.6055 29.6016H51.5635V36.1229\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M12.4297 36.1229V29.6016H29.3878\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M31.9961 26.9978V21.7812\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M34.6049 29.6012C34.6049 30.1172 34.4519 30.6216 34.1652 31.0506C33.8785 31.4797 33.471 31.8141 32.9943 32.0115C32.5175 32.209 31.9929 32.2607 31.4868 32.16C30.9807 32.0593 30.5158 31.8109 30.1509 31.446C29.786 31.0811 29.5375 30.6162 29.4369 30.1102C29.3362 29.6041 29.3879 29.0795 29.5853 28.6027C29.7828 28.126 30.1172 27.7186 30.5463 27.4319C30.9753 27.1452 31.4798 26.9922 31.9958 26.9922C32.6878 26.9922 33.3514 27.2671 33.8407 27.7563C34.33 28.2456 34.6049 28.9092 34.6049 29.6012Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTrusted data security\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe highly value your trust. Your data remains confidential and is never shared with advertisers or marketing agencies.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2b085faa\" data-id=\"2b085faa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-383b5787 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"383b5787\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"62\" height=\"62\" viewbox=\"0 0 62 62\" fill=\"none\"><path d=\"M51.4264 44.0219H58.218C58.6223 44.0048 59.0257 44.0725 59.4024 44.2205C59.7808 44.3692 60.1237 44.5958 60.409 44.8855C60.6943 45.1752 60.9156 45.5215 61.0585 45.9022C61.1956 46.2672 61.2577 46.6559 61.2412 47.0452L61.2425 47.0645C61.2764 47.6031 61.1773 48.1418 60.9537 48.633C60.757 49.0653 60.4692 49.4491 60.111 49.7586C60.2524 50.1297 60.3254 50.524 60.3259 50.9222V50.9227C60.3255 51.3906 60.2115 51.8515 59.9936 52.2656C59.8075 52.6195 59.5503 52.9303 59.2389 53.1788C59.4771 53.8163 59.4876 54.519 59.2646 55.1664C59.042 55.8126 58.6023 56.3589 58.0236 56.7145C58.0932 56.9811 58.1282 57.2558 58.1275 57.5318M51.4264 44.0219L57.8775 57.5312M51.4264 44.0219C51.7764 42.9938 51.9867 41.9226 52.051 40.8373L52.0522 40.8184L52.0504 40.7995C51.867 38.8171 51.0036 36.9591 49.6067 35.5406L49.6054 35.5393C49.1177 35.0516 48.492 34.8532 47.8806 34.8241C47.2714 34.7952 46.6623 34.9331 46.178 35.1342L51.4264 44.0219ZM58.1275 57.5318L57.8775 57.5312M58.1275 57.5318C58.1275 57.5317 58.1275 57.5315 58.1275 57.5313L57.8775 57.5312M58.1275 57.5318C58.1272 58.2829 57.8287 59.0032 57.2976 59.5343C56.7663 60.0656 56.0459 60.3641 55.2946 60.3643H55.2945H43.2097H43.2089C43.0984 60.3639 42.9886 60.348 42.8825 60.317L42.8831 60.3171L42.9521 60.0768M57.8775 57.5312C57.8773 58.2163 57.6052 58.8732 57.1208 59.3575C56.6364 59.8419 55.9795 60.1141 55.2945 60.1143H43.2097C43.1225 60.114 43.0358 60.1014 42.9521 60.0768M42.9521 60.0768L42.8817 60.3167M42.9521 60.0768L42.5186 59.9525V60.1847C42.5186 60.194 42.5185 60.2032 42.5182 60.2125M42.8817 60.3167L31.5977 60.2926C31.6243 60.5218 31.7346 60.733 31.9073 60.8859C32.0801 61.0387 32.3032 61.1224 32.5338 61.1209M42.8817 60.3167L42.5182 60.2125M42.8817 60.3167L32.5346 61.3709M42.5182 60.2125L42.4216 60.1847L42.2686 60.1408V60.1847C42.2686 60.433 42.17 60.6711 41.9944 60.8467C41.8188 61.0222 41.5807 61.1209 41.3325 61.1209H32.5338M42.5182 60.2125C42.5111 60.517 42.3871 60.8075 42.1712 61.0234C41.9487 61.2459 41.647 61.3709 41.3325 61.3709H32.5346M32.5338 61.1209V61.3709H32.5346M32.5338 61.1209L32.5355 61.3708C32.5352 61.3708 32.5349 61.3709 32.5346 61.3709M32.5346 61.3709C32.2427 61.3726 31.9603 61.2666 31.7417 61.0731C31.5228 60.8794 31.3831 60.6118 31.3494 60.3214L31.3494 60.321L29.8517 47.2164M32.5346 61.3709L29.8517 47.2164M29.8517 47.2164C29.8516 47.2163 29.8516 47.2162 29.8516 47.2161M29.8517 47.2164L29.8516 47.2161M29.8516 47.2161C29.8323 47.0494 29.8486 46.8804 29.8995 46.7204C29.9503 46.5603 30.0347 46.4128 30.1468 46.2878C30.2589 46.1627 30.3963 46.0629 30.5499 45.9949C30.7032 45.9271 30.8692 45.8925 31.0368 45.8935M29.8516 47.2161L41.3318 46.1435M31.0368 45.8935C31.0371 45.8935 31.0375 45.8935 31.0378 45.8935L31.0361 46.1435V45.8935H31.0368ZM31.0368 45.8935H41.331M41.331 45.8935C41.3308 45.8935 41.3305 45.8935 41.3303 45.8935L41.3318 46.1435M41.331 45.8935H41.3318V46.1435M41.331 45.8935C41.4246 45.893 41.5176 45.9035 41.6082 45.9245C42.3855 44.8193 43.9898 42.3596 44.635 41.1403C44.8777 40.6818 44.959 39.9707 44.9578 39.2313C44.9567 38.5041 44.8767 37.7949 44.8275 37.3614C44.8274 37.3605 44.8273 37.3597 44.8272 37.3589L45.0756 37.3306C45.0505 37.1443 45.0348 36.9569 45.0286 36.769L41.3318 46.1435M57.9543 48.0412V48.0615C57.7714 48.0953 57.5977 48.1719 57.4481 48.2865C57.2291 48.4544 57.0754 48.6933 57.0136 48.9623C56.9518 49.2313 56.9857 49.5133 57.1095 49.76C57.2292 49.9986 57.4259 50.1896 57.6672 50.3025C57.7609 50.3711 57.8368 50.4612 57.8886 50.5654C57.9435 50.6757 57.9695 50.7981 57.9641 50.9212L57.9638 50.9212L57.9639 50.9337C57.9648 51.0708 57.9112 51.2027 57.815 51.3003C57.7189 51.3978 57.5881 51.4532 57.4514 51.4544H57.3538C57.0792 51.4256 56.8029 51.4935 56.5727 51.6467C56.3382 51.8029 56.167 52.0373 56.0896 52.3082C56.0122 52.5791 56.0337 52.8686 56.1503 53.1251C56.267 53.3815 56.471 53.5881 56.726 53.7078L56.7395 53.7141L56.7537 53.7188C56.8252 53.7425 56.8913 53.7801 56.9482 53.8295C57.005 53.879 57.0515 53.9392 57.0849 54.0067C57.1184 54.0742 57.1381 54.1477 57.1429 54.2229C57.1477 54.2981 57.1375 54.3735 57.113 54.4447C57.0884 54.516 57.05 54.5816 56.9999 54.6379C56.9498 54.6942 56.889 54.7399 56.8211 54.7725C56.7532 54.8051 56.6795 54.8239 56.6042 54.8278C56.529 54.8317 56.4537 54.8207 56.3828 54.7953L56.3709 54.791L56.3586 54.788C56.0742 54.7176 55.7738 54.7549 55.5152 54.8929C55.2567 55.0308 55.0584 55.2596 54.9586 55.535C54.8587 55.8105 54.8643 56.1132 54.9743 56.3848C55.0805 56.6469 55.2767 56.8621 55.5271 56.9921C55.6027 57.056 55.6636 57.1355 55.7055 57.2254C55.7507 57.3222 55.7726 57.4283 55.7694 57.5352L55.7693 57.5352V57.5426C55.7693 57.665 55.7207 57.7824 55.6341 57.8689C55.5476 57.9555 55.4302 58.0041 55.3079 58.0041H43.3773L42.5186 57.7453V48.3847C42.6617 48.3166 42.7935 48.226 42.9088 48.1162L42.9237 48.102L42.936 48.0855C44.333 46.2296 45.6026 44.2813 46.7363 42.2539L46.7364 42.2539L46.7392 42.2486C47.1569 41.4579 47.2964 40.4402 47.3213 39.5011C47.3436 38.6582 47.274 37.8538 47.2137 37.2896C47.338 37.2504 47.4794 37.2191 47.6116 37.2056C47.7102 37.1956 47.7935 37.1965 47.8557 37.2066C47.9133 37.2159 47.9314 37.2295 47.9315 37.2292C47.9316 37.2292 47.9311 37.2288 47.9304 37.228L47.9305 37.2282C48.9253 38.2441 49.5455 39.5676 49.6896 40.9821C49.6971 41.1071 49.6719 41.3252 49.6123 41.622C49.5535 41.9148 49.4658 42.2628 49.3614 42.633C49.1528 43.373 48.8811 44.1893 48.6516 44.8061L48.6505 44.8093C48.5871 44.9871 48.567 45.1775 48.5921 45.3647C48.6171 45.5518 48.6865 45.7303 48.7944 45.8852C48.9024 46.0401 49.0458 46.167 49.2126 46.2553C49.3795 46.3436 49.5651 46.3908 49.7539 46.3929V46.3929H49.7567H58.1809C58.4721 46.3929 58.6278 46.4589 58.7144 46.5454C58.801 46.632 58.867 46.7877 58.867 47.079C58.867 47.6268 58.7235 47.8419 58.6132 47.932C58.4949 48.0286 58.3465 48.0412 58.2043 48.0412H57.9543ZM40.1464 58.9993H33.5991L32.3736 48.2658H40.1458L40.1464 58.9993Z\" fill=\"#FF8484\" stroke=\"#FF8484\" stroke-width=\"0.5\"><\/path><mask id=\"path-2-outside-1_10027_82683\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0.210938\" width=\"30\" height=\"30\" fill=\"black\"><rect fill=\"white\" y=\"0.210938\" width=\"30\" height=\"30\"><\/rect><path d=\"M28.228 27.4218H27.2919V6.66464C27.8356 6.47084 28.3063 6.11424 28.6401 5.64335C28.9739 5.17247 29.1544 4.61019 29.1572 4.03301C29.1601 3.45584 28.985 2.89182 28.6558 2.4177C28.3267 1.94358 27.8594 1.5824 27.3177 1.38331C26.776 1.18421 26.186 1.15688 25.6282 1.30502C25.0704 1.45316 24.5718 1.76958 24.2002 2.21123C23.8286 2.65287 23.6021 3.19828 23.5515 3.77324C23.501 4.3482 23.6288 4.92478 23.9176 5.42451L20.0285 9.90902C19.4227 9.63129 18.7379 9.57813 18.0966 9.75906C17.4552 9.93999 16.8991 10.3432 16.5278 10.8965L14.1879 10.3069C14.1441 9.89479 14.0095 9.49745 13.794 9.14343C13.5784 8.78941 13.2872 8.4875 12.9411 8.25936C12.5951 8.03121 12.2029 7.88249 11.7926 7.82387C11.3822 7.76525 10.9641 7.79818 10.568 7.9203C10.1719 8.04242 9.80777 8.2507 9.50171 8.53019C9.19565 8.80969 8.95524 9.15346 8.79775 9.53686C8.64025 9.92025 8.56957 10.3338 8.59077 10.7477C8.61198 11.1616 8.72455 11.5658 8.9204 11.931L4.94692 16.401C4.59812 16.2462 4.22144 16.1642 3.83989 16.1599C3.45834 16.1556 3.07991 16.2291 2.72771 16.376C2.37551 16.5228 2.05693 16.7399 1.79141 17.0139C1.52589 17.288 1.319 17.6133 1.18338 17.9699C1.04775 18.3266 0.986234 18.7072 1.00258 19.0884C1.01892 19.4696 1.11278 19.8436 1.27844 20.1873C1.44409 20.5311 1.67805 20.8375 1.96605 21.0878C2.25405 21.3381 2.59005 21.5271 2.95352 21.6432V27.4231H2.01933C1.77106 27.4231 1.53296 27.5217 1.35741 27.6973C1.18186 27.8728 1.08323 28.1109 1.08323 28.3592C1.08323 28.6075 1.18186 28.8456 1.35741 29.0211C1.53296 29.1967 1.77106 29.2953 2.01933 29.2953H28.2299C28.4782 29.2953 28.7163 29.1967 28.8918 29.0211C29.0674 28.8456 29.166 28.6075 29.166 28.3592C29.166 28.1109 29.0674 27.8728 28.8918 27.6973C28.7163 27.5217 28.4782 27.4231 28.2299 27.4231L28.228 27.4218ZM12.3151 13.2169C12.8895 13.0137 13.3822 12.6292 13.7189 12.1214L16.0588 12.711C16.1112 13.2448 16.3154 13.7524 16.6472 14.1739C16.9789 14.5953 17.4244 14.9129 17.931 15.0891V27.4218H12.3151V13.2169ZM19.8038 15.0891C20.1775 14.9559 20.5188 14.745 20.805 14.4703C21.0913 14.1957 21.3162 13.8634 21.4648 13.4956C21.6133 13.1277 21.6823 12.7325 21.6671 12.3361C21.6518 11.9396 21.5528 11.5509 21.3765 11.1955L25.3315 6.63227L25.4204 6.66464V27.4218H19.8038V15.0891ZM26.3539 3.08389C26.5391 3.08389 26.7201 3.13879 26.874 3.24165C27.0279 3.34451 27.1479 3.49072 27.2188 3.66177C27.2896 3.83283 27.3082 4.02105 27.272 4.20264C27.2359 4.38423 27.1468 4.55103 27.0158 4.68195C26.8849 4.81287 26.7181 4.90203 26.5366 4.93815C26.355 4.97427 26.1668 4.95573 25.9957 4.88488C25.8247 4.81402 25.6785 4.69404 25.5756 4.54009C25.4727 4.38615 25.4178 4.20516 25.4178 4.02001C25.4178 3.89705 25.4419 3.77529 25.4889 3.66167C25.5359 3.54806 25.6049 3.44483 25.6918 3.35789C25.7788 3.27094 25.882 3.20199 25.9956 3.15498C26.1092 3.10796 26.231 3.0838 26.3539 3.08389ZM18.8652 11.5084C19.0503 11.5079 19.2314 11.5623 19.3856 11.6647C19.5398 11.7671 19.6602 11.9129 19.7315 12.0838C19.8029 12.2546 19.8219 12.4427 19.7864 12.6244C19.7508 12.8061 19.6621 12.9731 19.5317 13.1044C19.4012 13.2357 19.2347 13.3254 19.0532 13.362C18.8718 13.3987 18.6835 13.3808 18.5123 13.3105C18.341 13.2402 18.1945 13.1207 18.0911 12.9671C17.9878 12.8136 17.9323 12.6328 17.9316 12.4477C17.9311 12.3246 17.9549 12.2027 18.0016 12.0889C18.0482 11.9751 18.1169 11.8716 18.2036 11.7844C18.2903 11.6971 18.3934 11.6278 18.5069 11.5805C18.6204 11.5331 18.7422 11.5086 18.8652 11.5084ZM11.3764 9.63611C11.5616 9.63611 11.7426 9.69102 11.8965 9.79388C12.0505 9.89674 12.1704 10.0429 12.2413 10.214C12.3121 10.3851 12.3307 10.5733 12.2946 10.7549C12.2584 10.9365 12.1693 11.1033 12.0384 11.2342C11.9074 11.3651 11.7407 11.4543 11.5591 11.4904C11.3775 11.5265 11.1893 11.508 11.0182 11.4371C10.8472 11.3662 10.701 11.2463 10.5981 11.0923C10.4953 10.9384 10.4404 10.7574 10.4404 10.5722C10.4404 10.4493 10.4646 10.3276 10.5116 10.2141C10.5587 10.1006 10.6276 9.9974 10.7146 9.91052C10.8015 9.82365 10.9047 9.75475 11.0183 9.70778C11.1318 9.6608 11.2535 9.63603 11.3764 9.63611ZM3.88771 18.0606C4.07296 18.06 4.25422 18.1143 4.40857 18.2168C4.56291 18.3192 4.68338 18.4652 4.75474 18.6361C4.8261 18.8071 4.84512 18.9954 4.80941 19.1772C4.77371 19.3589 4.68487 19.526 4.55414 19.6573C4.42342 19.7886 4.25669 19.8781 4.07506 19.9145C3.89343 19.951 3.70507 19.9327 3.53383 19.8621C3.36258 19.7914 3.21616 19.6715 3.11308 19.5176C3.01 19.3637 2.95491 19.1826 2.95479 18.9973C2.9547 18.8744 2.97886 18.7526 3.02587 18.639C3.07289 18.5254 3.14184 18.4222 3.22878 18.3352C3.31572 18.2483 3.41894 18.1793 3.53255 18.1323C3.64616 18.0853 3.76793 18.0611 3.89088 18.0612L3.88771 18.0606ZM4.8238 21.6413C5.20784 21.5055 5.55773 21.2877 5.84918 21.0031C6.14062 20.7185 6.36665 20.3739 6.51156 19.9931C6.65648 19.6124 6.71682 19.2047 6.68839 18.7983C6.65996 18.392 6.54345 17.9966 6.34693 17.6398L10.3204 13.1699L10.4423 13.2169V27.4218H4.82697L4.8238 21.6413Z\"><\/path><\/mask><path d=\"M28.228 27.4218H27.2919V6.66464C27.8356 6.47084 28.3063 6.11424 28.6401 5.64335C28.9739 5.17247 29.1544 4.61019 29.1572 4.03301C29.1601 3.45584 28.985 2.89182 28.6558 2.4177C28.3267 1.94358 27.8594 1.5824 27.3177 1.38331C26.776 1.18421 26.186 1.15688 25.6282 1.30502C25.0704 1.45316 24.5718 1.76958 24.2002 2.21123C23.8286 2.65287 23.6021 3.19828 23.5515 3.77324C23.501 4.3482 23.6288 4.92478 23.9176 5.42451L20.0285 9.90902C19.4227 9.63129 18.7379 9.57813 18.0966 9.75906C17.4552 9.93999 16.8991 10.3432 16.5278 10.8965L14.1879 10.3069C14.1441 9.89479 14.0095 9.49745 13.794 9.14343C13.5784 8.78941 13.2872 8.4875 12.9411 8.25936C12.5951 8.03121 12.2029 7.88249 11.7926 7.82387C11.3822 7.76525 10.9641 7.79818 10.568 7.9203C10.1719 8.04242 9.80777 8.2507 9.50171 8.53019C9.19565 8.80969 8.95524 9.15346 8.79775 9.53686C8.64025 9.92025 8.56957 10.3338 8.59077 10.7477C8.61198 11.1616 8.72455 11.5658 8.9204 11.931L4.94692 16.401C4.59812 16.2462 4.22144 16.1642 3.83989 16.1599C3.45834 16.1556 3.07991 16.2291 2.72771 16.376C2.37551 16.5228 2.05693 16.7399 1.79141 17.0139C1.52589 17.288 1.319 17.6133 1.18338 17.9699C1.04775 18.3266 0.986234 18.7072 1.00258 19.0884C1.01892 19.4696 1.11278 19.8436 1.27844 20.1873C1.44409 20.5311 1.67805 20.8375 1.96605 21.0878C2.25405 21.3381 2.59005 21.5271 2.95352 21.6432V27.4231H2.01933C1.77106 27.4231 1.53296 27.5217 1.35741 27.6973C1.18186 27.8728 1.08323 28.1109 1.08323 28.3592C1.08323 28.6075 1.18186 28.8456 1.35741 29.0211C1.53296 29.1967 1.77106 29.2953 2.01933 29.2953H28.2299C28.4782 29.2953 28.7163 29.1967 28.8918 29.0211C29.0674 28.8456 29.166 28.6075 29.166 28.3592C29.166 28.1109 29.0674 27.8728 28.8918 27.6973C28.7163 27.5217 28.4782 27.4231 28.2299 27.4231L28.228 27.4218ZM12.3151 13.2169C12.8895 13.0137 13.3822 12.6292 13.7189 12.1214L16.0588 12.711C16.1112 13.2448 16.3154 13.7524 16.6472 14.1739C16.9789 14.5953 17.4244 14.9129 17.931 15.0891V27.4218H12.3151V13.2169ZM19.8038 15.0891C20.1775 14.9559 20.5188 14.745 20.805 14.4703C21.0913 14.1957 21.3162 13.8634 21.4648 13.4956C21.6133 13.1277 21.6823 12.7325 21.6671 12.3361C21.6518 11.9396 21.5528 11.5509 21.3765 11.1955L25.3315 6.63227L25.4204 6.66464V27.4218H19.8038V15.0891ZM26.3539 3.08389C26.5391 3.08389 26.7201 3.13879 26.874 3.24165C27.0279 3.34451 27.1479 3.49072 27.2188 3.66177C27.2896 3.83283 27.3082 4.02105 27.272 4.20264C27.2359 4.38423 27.1468 4.55103 27.0158 4.68195C26.8849 4.81287 26.7181 4.90203 26.5366 4.93815C26.355 4.97427 26.1668 4.95573 25.9957 4.88488C25.8247 4.81402 25.6785 4.69404 25.5756 4.54009C25.4727 4.38615 25.4178 4.20516 25.4178 4.02001C25.4178 3.89705 25.4419 3.77529 25.4889 3.66167C25.5359 3.54806 25.6049 3.44483 25.6918 3.35789C25.7788 3.27094 25.882 3.20199 25.9956 3.15498C26.1092 3.10796 26.231 3.0838 26.3539 3.08389ZM18.8652 11.5084C19.0503 11.5079 19.2314 11.5623 19.3856 11.6647C19.5398 11.7671 19.6602 11.9129 19.7315 12.0838C19.8029 12.2546 19.8219 12.4427 19.7864 12.6244C19.7508 12.8061 19.6621 12.9731 19.5317 13.1044C19.4012 13.2357 19.2347 13.3254 19.0532 13.362C18.8718 13.3987 18.6835 13.3808 18.5123 13.3105C18.341 13.2402 18.1945 13.1207 18.0911 12.9671C17.9878 12.8136 17.9323 12.6328 17.9316 12.4477C17.9311 12.3246 17.9549 12.2027 18.0016 12.0889C18.0482 11.9751 18.1169 11.8716 18.2036 11.7844C18.2903 11.6971 18.3934 11.6278 18.5069 11.5805C18.6204 11.5331 18.7422 11.5086 18.8652 11.5084ZM11.3764 9.63611C11.5616 9.63611 11.7426 9.69102 11.8965 9.79388C12.0505 9.89674 12.1704 10.0429 12.2413 10.214C12.3121 10.3851 12.3307 10.5733 12.2946 10.7549C12.2584 10.9365 12.1693 11.1033 12.0384 11.2342C11.9074 11.3651 11.7407 11.4543 11.5591 11.4904C11.3775 11.5265 11.1893 11.508 11.0182 11.4371C10.8472 11.3662 10.701 11.2463 10.5981 11.0923C10.4953 10.9384 10.4404 10.7574 10.4404 10.5722C10.4404 10.4493 10.4646 10.3276 10.5116 10.2141C10.5587 10.1006 10.6276 9.9974 10.7146 9.91052C10.8015 9.82365 10.9047 9.75475 11.0183 9.70778C11.1318 9.6608 11.2535 9.63603 11.3764 9.63611ZM3.88771 18.0606C4.07296 18.06 4.25422 18.1143 4.40857 18.2168C4.56291 18.3192 4.68338 18.4652 4.75474 18.6361C4.8261 18.8071 4.84512 18.9954 4.80941 19.1772C4.77371 19.3589 4.68487 19.526 4.55414 19.6573C4.42342 19.7886 4.25669 19.8781 4.07506 19.9145C3.89343 19.951 3.70507 19.9327 3.53383 19.8621C3.36258 19.7914 3.21616 19.6715 3.11308 19.5176C3.01 19.3637 2.95491 19.1826 2.95479 18.9973C2.9547 18.8744 2.97886 18.7526 3.02587 18.639C3.07289 18.5254 3.14184 18.4222 3.22878 18.3352C3.31572 18.2483 3.41894 18.1793 3.53255 18.1323C3.64616 18.0853 3.76793 18.0611 3.89088 18.0612L3.88771 18.0606ZM4.8238 21.6413C5.20784 21.5055 5.55773 21.2877 5.84918 21.0031C6.14062 20.7185 6.36665 20.3739 6.51156 19.9931C6.65648 19.6124 6.71682 19.2047 6.68839 18.7983C6.65996 18.392 6.54345 17.9966 6.34693 17.6398L10.3204 13.1699L10.4423 13.2169V27.4218H4.82697L4.8238 21.6413Z\" fill=\"#FF8484\"><\/path><path d=\"M28.228 27.4218H27.2919V6.66464C27.8356 6.47084 28.3063 6.11424 28.6401 5.64335C28.9739 5.17247 29.1544 4.61019 29.1572 4.03301C29.1601 3.45584 28.985 2.89182 28.6558 2.4177C28.3267 1.94358 27.8594 1.5824 27.3177 1.38331C26.776 1.18421 26.186 1.15688 25.6282 1.30502C25.0704 1.45316 24.5718 1.76958 24.2002 2.21123C23.8286 2.65287 23.6021 3.19828 23.5515 3.77324C23.501 4.3482 23.6288 4.92478 23.9176 5.42451L20.0285 9.90902C19.4227 9.63129 18.7379 9.57813 18.0966 9.75906C17.4552 9.93999 16.8991 10.3432 16.5278 10.8965L14.1879 10.3069C14.1441 9.89479 14.0095 9.49745 13.794 9.14343C13.5784 8.78941 13.2872 8.4875 12.9411 8.25936C12.5951 8.03121 12.2029 7.88249 11.7926 7.82387C11.3822 7.76525 10.9641 7.79818 10.568 7.9203C10.1719 8.04242 9.80777 8.2507 9.50171 8.53019C9.19565 8.80969 8.95524 9.15346 8.79775 9.53686C8.64025 9.92025 8.56957 10.3338 8.59077 10.7477C8.61198 11.1616 8.72455 11.5658 8.9204 11.931L4.94692 16.401C4.59812 16.2462 4.22144 16.1642 3.83989 16.1599C3.45834 16.1556 3.07991 16.2291 2.72771 16.376C2.37551 16.5228 2.05693 16.7399 1.79141 17.0139C1.52589 17.288 1.319 17.6133 1.18338 17.9699C1.04775 18.3266 0.986234 18.7072 1.00258 19.0884C1.01892 19.4696 1.11278 19.8436 1.27844 20.1873C1.44409 20.5311 1.67805 20.8375 1.96605 21.0878C2.25405 21.3381 2.59005 21.5271 2.95352 21.6432V27.4231H2.01933C1.77106 27.4231 1.53296 27.5217 1.35741 27.6973C1.18186 27.8728 1.08323 28.1109 1.08323 28.3592C1.08323 28.6075 1.18186 28.8456 1.35741 29.0211C1.53296 29.1967 1.77106 29.2953 2.01933 29.2953H28.2299C28.4782 29.2953 28.7163 29.1967 28.8918 29.0211C29.0674 28.8456 29.166 28.6075 29.166 28.3592C29.166 28.1109 29.0674 27.8728 28.8918 27.6973C28.7163 27.5217 28.4782 27.4231 28.2299 27.4231L28.228 27.4218ZM12.3151 13.2169C12.8895 13.0137 13.3822 12.6292 13.7189 12.1214L16.0588 12.711C16.1112 13.2448 16.3154 13.7524 16.6472 14.1739C16.9789 14.5953 17.4244 14.9129 17.931 15.0891V27.4218H12.3151V13.2169ZM19.8038 15.0891C20.1775 14.9559 20.5188 14.745 20.805 14.4703C21.0913 14.1957 21.3162 13.8634 21.4648 13.4956C21.6133 13.1277 21.6823 12.7325 21.6671 12.3361C21.6518 11.9396 21.5528 11.5509 21.3765 11.1955L25.3315 6.63227L25.4204 6.66464V27.4218H19.8038V15.0891ZM26.3539 3.08389C26.5391 3.08389 26.7201 3.13879 26.874 3.24165C27.0279 3.34451 27.1479 3.49072 27.2188 3.66177C27.2896 3.83283 27.3082 4.02105 27.272 4.20264C27.2359 4.38423 27.1468 4.55103 27.0158 4.68195C26.8849 4.81287 26.7181 4.90203 26.5366 4.93815C26.355 4.97427 26.1668 4.95573 25.9957 4.88488C25.8247 4.81402 25.6785 4.69404 25.5756 4.54009C25.4727 4.38615 25.4178 4.20516 25.4178 4.02001C25.4178 3.89705 25.4419 3.77529 25.4889 3.66167C25.5359 3.54806 25.6049 3.44483 25.6918 3.35789C25.7788 3.27094 25.882 3.20199 25.9956 3.15498C26.1092 3.10796 26.231 3.0838 26.3539 3.08389ZM18.8652 11.5084C19.0503 11.5079 19.2314 11.5623 19.3856 11.6647C19.5398 11.7671 19.6602 11.9129 19.7315 12.0838C19.8029 12.2546 19.8219 12.4427 19.7864 12.6244C19.7508 12.8061 19.6621 12.9731 19.5317 13.1044C19.4012 13.2357 19.2347 13.3254 19.0532 13.362C18.8718 13.3987 18.6835 13.3808 18.5123 13.3105C18.341 13.2402 18.1945 13.1207 18.0911 12.9671C17.9878 12.8136 17.9323 12.6328 17.9316 12.4477C17.9311 12.3246 17.9549 12.2027 18.0016 12.0889C18.0482 11.9751 18.1169 11.8716 18.2036 11.7844C18.2903 11.6971 18.3934 11.6278 18.5069 11.5805C18.6204 11.5331 18.7422 11.5086 18.8652 11.5084ZM11.3764 9.63611C11.5616 9.63611 11.7426 9.69102 11.8965 9.79388C12.0505 9.89674 12.1704 10.0429 12.2413 10.214C12.3121 10.3851 12.3307 10.5733 12.2946 10.7549C12.2584 10.9365 12.1693 11.1033 12.0384 11.2342C11.9074 11.3651 11.7407 11.4543 11.5591 11.4904C11.3775 11.5265 11.1893 11.508 11.0182 11.4371C10.8472 11.3662 10.701 11.2463 10.5981 11.0923C10.4953 10.9384 10.4404 10.7574 10.4404 10.5722C10.4404 10.4493 10.4646 10.3276 10.5116 10.2141C10.5587 10.1006 10.6276 9.9974 10.7146 9.91052C10.8015 9.82365 10.9047 9.75475 11.0183 9.70778C11.1318 9.6608 11.2535 9.63603 11.3764 9.63611ZM3.88771 18.0606C4.07296 18.06 4.25422 18.1143 4.40857 18.2168C4.56291 18.3192 4.68338 18.4652 4.75474 18.6361C4.8261 18.8071 4.84512 18.9954 4.80941 19.1772C4.77371 19.3589 4.68487 19.526 4.55414 19.6573C4.42342 19.7886 4.25669 19.8781 4.07506 19.9145C3.89343 19.951 3.70507 19.9327 3.53383 19.8621C3.36258 19.7914 3.21616 19.6715 3.11308 19.5176C3.01 19.3637 2.95491 19.1826 2.95479 18.9973C2.9547 18.8744 2.97886 18.7526 3.02587 18.639C3.07289 18.5254 3.14184 18.4222 3.22878 18.3352C3.31572 18.2483 3.41894 18.1793 3.53255 18.1323C3.64616 18.0853 3.76793 18.0611 3.89088 18.0612L3.88771 18.0606ZM4.8238 21.6413C5.20784 21.5055 5.55773 21.2877 5.84918 21.0031C6.14062 20.7185 6.36665 20.3739 6.51156 19.9931C6.65648 19.6124 6.71682 19.2047 6.68839 18.7983C6.65996 18.392 6.54345 17.9966 6.34693 17.6398L10.3204 13.1699L10.4423 13.2169V27.4218H4.82697L4.8238 21.6413Z\" stroke=\"#FF8484\" mask=\"url(#path-2-outside-1_10027_82683)\"><\/path><path d=\"M12.8501 45.5278C15.7273 49.1654 19.6221 51.8568 24.0313 53.2639L17.3925 56.5553L17.3924 56.5551L17.3842 56.5596C17.1143 56.7062 16.9119 56.9518 16.8194 57.2446C16.7269 57.5374 16.7516 57.8547 16.8882 58.1297C17.0249 58.4047 17.2629 58.616 17.5521 58.7191C17.8414 58.8222 18.1594 58.8091 18.4392 58.6826L18.4393 58.6827L18.4472 58.6788L27.9517 53.9683H27.9936L28.0573 53.925L28.1492 53.8625L28.1506 53.8616L28.205 53.8251L28.2221 53.8136L28.237 53.7996L28.3214 53.7203L28.3215 53.7203L28.327 53.7148L28.3689 53.6729L28.3759 53.6659L28.3824 53.6583C28.4297 53.6028 28.4716 53.543 28.5077 53.4796L28.5405 53.4221V53.396C28.5575 53.3624 28.5729 53.328 28.5867 53.293L28.6039 53.249V53.2017V53.0544C28.6049 53.0383 28.6054 53.0221 28.6057 53.0059C28.614 52.9924 28.6232 52.976 28.6314 52.9582C28.6376 52.9448 28.6467 52.9234 28.653 52.8971C28.6573 52.8791 28.6663 52.8363 28.6566 52.7834V52.7832V52.783V52.7829V52.7827V52.7825V52.7823V52.7821V52.7819V52.7818V52.7816V52.7814V52.7812V52.781V52.7808V52.7807V52.7805V52.7803V52.7801V52.7799V52.7797V52.7796V52.7794V52.7792V52.779V52.7788V52.7786V52.7784V52.7783V52.7781V52.7779V52.7777V52.7775V52.7773V52.7772V52.777V52.7768V52.7766V52.7764V52.7762V52.7761V52.7759V52.7757V52.7755V52.7753V52.7751V52.775V52.7748V52.7746V52.7744V52.7742V52.774V52.7739V52.7737V52.7735V52.7733V52.7731V52.7729V52.7728V52.7726V52.7724V52.7722V52.772V52.7718V52.7717V52.7715V52.7713V52.7711V52.7709V52.7708V52.7706V52.7704V52.7702V52.77V52.7698V52.7697V52.7695V52.7693V52.7691V52.7689V52.7687V52.7686V52.7684V52.7682V52.768V52.7678V52.7676V52.7675V52.7673V52.7671V52.7669V52.7667V52.7666V52.7664V52.7662V52.766V52.7658V52.7656V52.7655V52.7653V52.7651V52.7649V52.7647V52.7646V52.7644V52.7642V52.764V52.7638V52.7636V52.7635V52.7633V52.7631V52.7629V52.7627V52.7626V52.7624V52.7622V52.762V52.7618V52.7616V52.7615V52.7613V52.7611V52.7609V52.7607V52.7606V52.7604V52.7602V52.76V52.7598V52.7597V52.7595V52.7593V52.7591V52.7589V52.7588V52.7586V52.7584V52.7582V52.758V52.7578V52.7577V52.7575V52.7573V52.7571V52.7569V52.7568V52.7566V52.7564V52.7562V52.756V52.7559V52.7557V52.7555V52.7553V52.7551V52.755V52.7548V52.7546V52.7544V52.7542V52.7541V52.7539V52.7537V52.7535V52.7533V52.7532V52.753V52.7528V52.7526V52.7525V52.7523V52.7521V52.7519V52.7517V52.7516V52.7514V52.7512V52.751V52.7508V52.7507V52.7505V52.7503V52.7501V52.7499V52.7498V52.7496V52.7494V52.7492V52.7491V52.7489V52.7487V52.7485V52.7483V52.7482V52.748V52.7478V52.7476V52.7474V52.7473V52.7471V52.7469V52.7467V52.7466V52.7464V52.7462V52.746V52.7458V52.7457V52.7455V52.7453V52.7451V52.745V52.7448V52.7446V52.7444V52.7442V52.7441V52.7439V52.7437V52.7435V52.7434V52.7432V52.743V52.7428V52.7427V52.7425V52.7423V52.7421V52.742V52.7418V52.7416V52.7414V52.7412V52.7411V52.7409V52.7407V52.7405V52.7404V52.7402V52.74V52.7398V52.7397V52.7395V52.7393V52.7391V52.739V52.7388V52.7386V52.7384V52.7383V52.7381V52.7379V52.7377V52.7376V52.7374V52.7372V52.737V52.7369V52.7367V52.7365V52.6603C28.6599 52.6166 28.6545 52.5724 28.6406 52.5305C28.6326 52.5066 28.622 52.4838 28.6089 52.4625C28.5988 52.4328 28.5875 52.4034 28.5749 52.3745L28.5752 52.3744L28.5694 52.3629L23.8001 42.796L23.8002 42.7959L23.796 42.7882C23.6495 42.5183 23.4039 42.3159 23.1111 42.2234C22.8183 42.1309 22.501 42.1556 22.226 42.2922C21.951 42.4289 21.7397 42.6669 21.6366 42.9562C21.5335 43.2454 21.5466 43.5634 21.6731 43.8432L21.673 43.8433L21.6769 43.8513L25.3094 51.177C21.2189 49.9968 17.5815 47.5937 14.8894 44.284C12.0808 40.8309 10.4478 36.5713 10.2283 32.1256C10.2213 31.9701 10.1837 31.8174 10.1178 31.6764C10.0517 31.5352 9.95854 31.4084 9.8435 31.3032C9.72846 31.198 9.59383 31.1165 9.44728 31.0633C9.30073 31.0102 9.14515 30.9864 8.98943 30.9934C8.8337 31.0003 8.68087 31.0379 8.53967 31.104C8.39846 31.17 8.27164 31.2632 8.16646 31.3782C8.06127 31.4933 7.97977 31.6279 7.92662 31.7745C7.87346 31.921 7.84969 32.0766 7.85666 32.2323L7.85665 32.2323L7.85671 32.2335C8.09609 37.0768 9.84179 41.7246 12.8501 45.5278Z\" fill=\"#FF8484\" stroke=\"#FF8484\" stroke-width=\"0.5\"><\/path><path d=\"M53.9004 34.9123L53.9004 34.9122C54.8089 29.3082 53.6323 23.5655 50.5931 18.7704C47.6675 14.1545 43.2113 10.7247 38.0158 9.07424L44.6766 5.78057C44.8201 5.71497 44.9492 5.62136 45.0561 5.50522C45.1641 5.38795 45.2473 5.25012 45.3008 5.09999C45.3544 4.94985 45.3771 4.79046 45.3676 4.63132L45.118 4.64617L45.3676 4.63132C45.3581 4.4722 45.3167 4.31662 45.2458 4.17388C45.1748 4.03112 45.0758 3.90414 44.9547 3.80051C44.8336 3.69688 44.6929 3.61872 44.5409 3.57071C44.3889 3.5227 44.2287 3.50581 44.0701 3.52107C43.9131 3.53617 43.7607 3.58242 43.6218 3.65711L34.0688 8.38652L34.0688 8.38653C33.9007 8.46975 33.7548 8.59164 33.6429 8.74219C33.5311 8.89274 33.4566 9.06766 33.4254 9.2526L33.422 9.2732V9.2941V9.30224C33.3894 9.58243 33.4579 9.86505 33.6151 10.0992L38.2879 19.5003L38.2878 19.5003L38.2916 19.5074C38.4375 19.7787 38.6832 19.9825 38.9767 20.0758C39.2702 20.1692 39.5885 20.1447 39.8643 20.0075C40.1401 19.8703 40.3517 19.6313 40.4544 19.3409C40.557 19.0506 40.5427 18.7316 40.4145 18.4516L40.4146 18.4515L40.4108 18.4439L36.7806 11.1797C41.5808 12.5598 45.7315 15.6231 48.4652 19.8181C51.3002 24.1686 52.4063 29.4218 51.5664 34.5461C51.5162 34.8515 51.5872 35.1644 51.7645 35.4181C51.9418 35.6719 52.2112 35.8463 52.5154 35.9041L52.5385 35.9085H52.562H52.5627H52.7157C52.9995 35.9117 53.275 35.8131 53.4923 35.6305C53.71 35.4477 53.8547 35.1928 53.9004 34.9123Z\" fill=\"#FF8484\" stroke=\"#FF8484\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tStrict privacy policy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEventBookings maintains a strict stand against sharing any data with third-party websites or social media platforms for advertising aims.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-405fb078 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"405fb078\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-652bb432\" data-id=\"652bb432\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bb9cacd SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"6bb9cacd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Switch to EventBookings today<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b2f648b elementor-mobile-align-center elementor-align-center new-fix-url elementor-widget elementor-widget-button\" data-id=\"2b2f648b\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/users\/login\/1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Use EventBookings For Free<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Leaders in the Event Space are Making the Switch! Discover why EventBookings is becoming the top choice for event organizers. While many platforms devour up to 15% in ticketing fees, EventBookings ensures you retain more of your hard-earned money. Create Event Free Forever. No Credit Card Required. Excellent 4.7\/5 Create Event Free Forever. No Credit [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-155176","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EventBookings vs Ticketleap | EventBookings<\/title>\n<meta name=\"description\" content=\"Maximise savings and simplify events. EventBookings is the best TicketLeap alternative with low fees, flexible payouts, a customisable page, and built-in virtual tools.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eventbookings.com\/en-us\/alternative-to-ticketleap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EventBookings vs Ticketleap | EventBookings\" \/>\n<meta property=\"og:description\" content=\"Maximise savings and simplify events. EventBookings is the best TicketLeap alternative with low fees, flexible payouts, a customisable page, and built-in virtual tools.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eventbookings.com\/en-us\/alternative-to-ticketleap\/\" \/>\n<meta property=\"og:site_name\" content=\"EventBookings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eEventBookings\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T10:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eEventBookings\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/\",\"url\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/\",\"name\":\"EventBookings vs Ticketleap | EventBookings\",\"isPartOf\":{\"@id\":\"https:\/\/www.eventbookings.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\",\"datePublished\":\"2023-08-28T05:04:33+00:00\",\"dateModified\":\"2026-03-09T10:37:57+00:00\",\"description\":\"Maximise savings and simplify events. EventBookings is the best TicketLeap alternative with low fees, flexible payouts, a customisable page, and built-in virtual tools.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#primaryimage\",\"url\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\",\"contentUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eventbookings.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EventBookings vs Ticketleap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eventbookings.com\/#website\",\"url\":\"https:\/\/www.eventbookings.com\/\",\"name\":\"EventBookings\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eventbookings.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eventbookings.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eventbookings.com\/#organization\",\"name\":\"EventBookings\",\"url\":\"https:\/\/www.eventbookings.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\",\"contentUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\",\"width\":1200,\"height\":674,\"caption\":\"EventBookings\"},\"image\":{\"@id\":\"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eEventBookings\",\"https:\/\/x.com\/eEventBookings\",\"https:\/\/www.linkedin.com\/company\/eeventbookings\/\",\"https:\/\/www.instagram.com\/eeventbookings\/\",\"https:\/\/www.youtube.com\/channel\/UCrN_RsacOWc9V3JU_Q3-tJA\",\"https:\/\/www.tiktok.com\/@eventbookings\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EventBookings vs Ticketleap | EventBookings","description":"Maximise savings and simplify events. EventBookings is the best TicketLeap alternative with low fees, flexible payouts, a customisable page, and built-in virtual tools.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eventbookings.com\/en-us\/alternative-to-ticketleap\/","og_locale":"en_US","og_type":"article","og_title":"EventBookings vs Ticketleap | EventBookings","og_description":"Maximise savings and simplify events. EventBookings is the best TicketLeap alternative with low fees, flexible payouts, a customisable page, and built-in virtual tools.","og_url":"https:\/\/www.eventbookings.com\/en-us\/alternative-to-ticketleap\/","og_site_name":"EventBookings","article_publisher":"https:\/\/www.facebook.com\/eEventBookings","article_modified_time":"2026-03-09T10:37:57+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@eEventBookings","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/","url":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/","name":"EventBookings vs Ticketleap | EventBookings","isPartOf":{"@id":"https:\/\/www.eventbookings.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#primaryimage"},"image":{"@id":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg","datePublished":"2023-08-28T05:04:33+00:00","dateModified":"2026-03-09T10:37:57+00:00","description":"Maximise savings and simplify events. EventBookings is the best TicketLeap alternative with low fees, flexible payouts, a customisable page, and built-in virtual tools.","breadcrumb":{"@id":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#primaryimage","url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg","contentUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eventbookings.com\/alternative-to-ticketleap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eventbookings.com\/"},{"@type":"ListItem","position":2,"name":"EventBookings vs Ticketleap"}]},{"@type":"WebSite","@id":"https:\/\/www.eventbookings.com\/#website","url":"https:\/\/www.eventbookings.com\/","name":"EventBookings","description":"","publisher":{"@id":"https:\/\/www.eventbookings.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eventbookings.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eventbookings.com\/#organization","name":"EventBookings","url":"https:\/\/www.eventbookings.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","contentUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","width":1200,"height":674,"caption":"EventBookings"},"image":{"@id":"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eEventBookings","https:\/\/x.com\/eEventBookings","https:\/\/www.linkedin.com\/company\/eeventbookings\/","https:\/\/www.instagram.com\/eeventbookings\/","https:\/\/www.youtube.com\/channel\/UCrN_RsacOWc9V3JU_Q3-tJA","https:\/\/www.tiktok.com\/@eventbookings"]}]}},"_links":{"self":[{"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/pages\/155176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/comments?post=155176"}],"version-history":[{"count":103,"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/pages\/155176\/revisions"}],"predecessor-version":[{"id":223681,"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/pages\/155176\/revisions\/223681"}],"wp:attachment":[{"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/media?parent=155176"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-us\/wp-json\/wp\/v2\/tags?post=155176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}