{"id":107389,"date":"2023-02-15T01:05:03","date_gmt":"2023-02-14T14:05:03","guid":{"rendered":"https:\/\/www.eventbookings.com\/?page_id=107389"},"modified":"2026-03-08T21:40:29","modified_gmt":"2026-03-08T10:40:29","slug":"alternative-to-humanitix","status":"publish","type":"page","link":"https:\/\/www.eventbookings.com\/en-it\/alternative-to-humanitix\/","title":{"rendered":"EventBookings vs Humanitix"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"107389\" class=\"elementor elementor-107389\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c5446a laptop-container  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c5446a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4431b48\" data-id=\"4431b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-301c205 br-none SharpSans ticketing udergreen-curve elementor-widget elementor-widget-heading\" data-id=\"301c205\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Leaders in the Event Space are Making the Switch!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9da61fd SharpSans  elementor-widget elementor-widget-heading\" data-id=\"9da61fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Discover why EventBookings is becoming the top choice for event organizers. While many platforms devour up to 15% in ticketing fees, EventBookings ensures you retain more of your hard-earned money.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4df3400 compare-button-section elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4df3400\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ef59cfd comp-btn\" data-id=\"ef59cfd\" data-element_type=\"column\" data-no-translation=\"\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bd4b5b elementor-mobile-align-center elementor-align-left elementor-tablet-align-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-button\" data-id=\"7bd4b5b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba361e5\" data-id=\"ba361e5\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0415418 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"0415418\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><em>Free Forever.<br>\nNo Credit Card Required.<\/em><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f8565b9 top-logo-section elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8565b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3702fbd\" data-id=\"3702fbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0e1483 elementor-widget elementor-widget-image\" data-id=\"d0e1483\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"112\" height=\"25\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\" class=\"attachment-full size-full wp-image-158596\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-87e606c\" data-id=\"87e606c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af66bbf elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"af66bbf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"168\" height=\"26\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/software-advice-logo.svg\" class=\"attachment-full size-full wp-image-158616\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-736ff0b\" data-id=\"736ff0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32ec8bd elementor-widget elementor-widget-image\" data-id=\"32ec8bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"115\" height=\"21\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/get-apps-logo.svg\" class=\"attachment-full size-full wp-image-158611\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-78bfd47 top-star-review elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78bfd47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee89474\" data-id=\"ee89474\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d3c443 elementor-widget elementor-widget-image\" data-id=\"8d3c443\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"127\" height=\"18\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png\" class=\"attachment-full size-full wp-image-158606\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png 127w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image-18x3.png 18w\" sizes=\"(max-width: 127px) 100vw, 127px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-534cba6\" data-id=\"534cba6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf2f0c2 review--content-text elementor-widget elementor-widget-heading\" data-id=\"cf2f0c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Excellent 4.7\/5<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eaf9c2 elementor-widget elementor-widget-html\" data-id=\"8eaf9c2\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n.top-star-review p{\n   font-family: Sharp Sans !important;\n}\n@media (max-width:1024px) {\n.compare-button-section .elementor-row{\n    max-width: 330px;\n    justify-content: center;\n    margin: 0 auto;\n    flex-wrap: nowrap;\n    }\n.compare-button-section .elementor-column:nth-child(1){\n        width:200px;\n    }\n.top-logo-section .elementor-row{\n    max-width:421px;\n    justify-content: center;\n    margin: 0 auto;\n    flex-wrap: nowrap;\n}\n.top-star-review .elementor-row{\n    max-width: 367px;\n    margin: 0 auto;\n    flex-wrap: nowrap;\n    justify-content: center;\n}\n.top-star-review .elementor-column:nth-child(1){\n        width:127px;\n}\n}\n@media (max-width:767px) {\n.compare-button-section .elementor-column:nth-child(1) {\n    width: 116px;\n}\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f5af036\" data-id=\"f5af036\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c38223 elementor-widget elementor-widget-image\" data-id=\"2c38223\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"749\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Humanitix-banner-1.png\" class=\"attachment-full size-full wp-image-110521\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Humanitix-banner-1.png 785w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Humanitix-banner-1-300x286.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Humanitix-banner-1-768x733.png 768w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Humanitix-banner-1-13x12.png 13w\" sizes=\"(max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48d7ae6 compare-button-section comp-btn comp-btn elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48d7ae6\" data-element_type=\"section\" data-no-translation=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1624ac0\" data-id=\"1624ac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5c695d elementor-mobile-align-center elementor-align-left elementor-tablet-align-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-button\" data-id=\"b5c695d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-715d87a\" data-id=\"715d87a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-414c5f0 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"414c5f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><em>Free Forever.<br>\nNo Credit Card Required.<\/em><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8ca45a2 top-logo-section elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ca45a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f266de9\" data-id=\"f266de9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bad9e69 elementor-widget elementor-widget-image\" data-id=\"bad9e69\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"112\" height=\"25\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\" class=\"attachment-full size-full wp-image-158596\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6f112a4\" data-id=\"6f112a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddcda61 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ddcda61\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"168\" height=\"26\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/software-advice-logo.svg\" class=\"attachment-full size-full wp-image-158616\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9f9a165\" data-id=\"9f9a165\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e72b014 elementor-widget elementor-widget-image\" data-id=\"e72b014\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"115\" height=\"21\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/get-apps-logo.svg\" class=\"attachment-full size-full wp-image-158611\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-247fff6 top-star-review elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"247fff6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-da4033c\" data-id=\"da4033c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bb1dbc elementor-widget elementor-widget-image\" data-id=\"1bb1dbc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"127\" height=\"18\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png\" class=\"attachment-full size-full wp-image-158606\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image.png 127w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/star-icon-image-18x3.png 18w\" sizes=\"(max-width: 127px) 100vw, 127px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c8e553\" data-id=\"5c8e553\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f074c1 elementor-widget elementor-widget-heading\" data-id=\"4f074c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Excellent 4.7\/5<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3451c30 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3451c30\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab17cbf\" data-id=\"ab17cbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11fa031 elementor-widget elementor-widget-html\" data-id=\"11fa031\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-11fa031{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de8cc4c elementor-widget elementor-widget-html\" data-id=\"de8cc4c\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-de8cc4c{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f73ba elementor-widget elementor-widget-html\" data-id=\"18f73ba\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-18f73ba{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8647268 elementor-widget elementor-widget-html\" data-id=\"8647268\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"client-logo-section\">\r\n                <h4 class=\"client-title\">Events created by thousands of organizations around the globe<\/h4>\r\n                <div class=\"client-logo-box\">\r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/Logos_APC-02.png\" width=\"176\" height=\"46\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                      <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/EDS-logo.png\" width=\"91\" height=\"37\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                   \r\n                   \r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/covey-theater-logo.png\" width=\"98\" height=\"98\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/vilamoura-logo1.png\" width=\"133\" height=\"77\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/kendall-nicole-eich-foundation-1.png\" width=\"176\" height=\"58\" alt=\"Brand Logo\">\r\n                    <\/div> \r\n                <\/div>\r\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9082021 SharpSans  elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"9082021\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00a2<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21a2d9de leverage-complete-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21a2d9de\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47afd93b\" data-id=\"47afd93b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-164a2d8f SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"164a2d8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7 reasons organizers are&nbsp;<br>\nswitching to  EventBookings<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-65260596 elementor-section-full_width SharpSans  br-none elementor-section-height-default elementor-section-height-default\" data-id=\"65260596\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31885c5d\" data-id=\"31885c5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63624f07 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"63624f07\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.5\" y=\"0.5\" width=\"100\" height=\"100\" rx=\"50\" fill=\"#C0EBFA\"><\/rect><path d=\"M51.8577 43.2587C50.92 42.4932 49.8657 42.0045 48.8004 41.7702V40.1948C48.8004 39.3927 48.1503 38.7422 47.3478 38.7422C46.5453 38.7422 45.8948 39.3927 45.8948 40.1948V41.7562C44.3495 42.0956 42.9241 43.0201 42.2053 44.5426C41.4656 46.1102 41.5081 47.7292 42.4376 49.165C43.2994 50.4957 44.8194 51.5082 46.6945 52.2858C48.4048 52.9955 49.3215 53.7501 49.7471 54.4045C50.1221 54.9809 50.1946 55.5932 49.9058 56.3692C49.6466 57.0661 48.8745 57.6043 47.5598 57.6511C46.2604 57.6971 44.8553 57.2126 43.9764 56.3724C43.3964 55.8181 42.4766 55.8388 41.9224 56.4188C41.3677 56.9987 41.3884 57.9181 41.9684 58.4728C43.0426 59.4994 44.4581 60.151 45.8948 60.4192V61.8106C45.8948 62.6127 46.5453 63.2633 47.3478 63.2633C48.1503 63.2633 48.8004 62.6128 48.8004 61.8106V60.4223C50.4077 60.0996 51.9606 59.1798 52.629 57.3826C53.2043 55.8361 53.1107 54.2466 52.1827 52.8201C51.305 51.4708 49.7811 50.4207 47.8077 49.6019C46.1679 48.9217 45.2754 48.2019 44.8767 47.5857C44.5454 47.0743 44.4795 46.5314 44.8331 45.7823C45.1191 45.1758 45.8129 44.6672 46.8317 44.5401C47.833 44.415 49.0163 44.6898 50.0199 45.5095C50.6416 46.0169 51.5567 45.9246 52.0641 45.3029C52.5712 44.6812 52.4788 43.7661 51.8576 43.2587L51.8577 43.2587Z\" fill=\"black\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M31 65.0773C31 68.3485 33.6519 71 36.9227 71H57.5567C60.8275 71 63.4794 68.3485 63.4794 65.0773V36.9231C63.4794 33.6519 60.8275 31 57.5567 31H36.9227C33.6519 31 31 33.6519 31 36.9231V65.0773ZM36.9227 68.0948C35.2565 68.0948 33.9056 66.7439 33.9056 65.0773V36.9231C33.9056 35.2565 35.2565 33.9056 36.9227 33.9056H57.5567C59.2229 33.9056 60.5737 35.2565 60.5737 36.9231V65.0773C60.5737 66.7439 59.2229 68.0948 57.5567 68.0948H36.9227Z\" fill=\"black\"><\/path><path d=\"M73.4536 45.1953C73.4536 43.1588 71.8025 41.5078 69.7657 41.5078H67.7105C66.908 41.5078 66.2578 42.1579 66.2578 42.9605C66.2578 43.7626 66.9079 44.4131 67.7105 44.4131H69.7657C70.1975 44.4131 70.5479 44.7635 70.5479 45.1954V63.0994C70.5479 63.5313 70.1975 63.8817 69.7657 63.8817H67.7105C66.908 63.8817 66.2578 64.5322 66.2578 65.3343C66.2578 66.1368 66.9079 66.7873 67.7105 66.7873H69.7657C71.8025 66.7873 73.4536 65.1363 73.4536 63.0994V45.1953Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAffordable ticket costs\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEventBookings charges a low fee of only 1% per ticket plus 25 cents in Italy, offering one of the most cost-effective solutions in the market. You have the option to pass on the savings to your attendees.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc7df19 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"2bc7df19\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.960938\" y=\"0.40625\" width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#BBF9BB\"><\/rect><path d=\"M69.6255 25.5H30.3551C28.9346 25.5 27.5728 26.0648 26.5683 27.0699C25.5642 28.0754 25 29.4387 25 30.8606V70.172C25 71.594 25.5642 72.9572 26.5683 73.9628C27.5727 74.9679 28.9346 75.5327 30.3551 75.5327H69.6255C71.046 75.5327 72.4078 74.9679 73.4123 73.9628C74.4164 72.9573 74.9806 71.594 74.9806 70.172V30.8606C74.9806 29.4387 74.4164 28.0755 73.4123 27.0699C72.4079 26.0648 71.046 25.5 69.6255 25.5ZM71.4106 70.172C71.4106 70.6459 71.2225 71.1006 70.8878 71.4356C70.5531 71.7707 70.0989 71.9589 69.6255 71.9589H30.3551C29.8817 71.9589 29.4275 71.7707 29.0928 71.4356C28.7581 71.1006 28.57 70.6459 28.57 70.172V39.7951H71.4106V70.172ZM71.4106 36.2213H28.57V30.8606C28.57 30.3868 28.7581 29.9321 29.0928 29.5971C29.4275 29.262 29.8817 29.0738 30.3551 29.0738H69.6255C70.0989 29.0738 70.5531 29.262 70.8878 29.5971C71.2225 29.9321 71.4106 30.3868 71.4106 30.8606V36.2213Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M33.9294 30.8594H32.1444C31.5065 30.8594 30.9172 31.2 30.5984 31.7528C30.2797 32.3056 30.2797 32.9869 30.5984 33.5397C30.9172 34.0925 31.5065 34.4331 32.1444 34.4331H33.9294C34.5673 34.4331 35.1566 34.0925 35.4753 33.5397C35.7941 32.9869 35.7941 32.3056 35.4753 31.7528C35.1566 31.2 34.5673 30.8594 33.9294 30.8594Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M41.07 30.8594H39.285C38.6471 30.8594 38.0578 31.2 37.7391 31.7528C37.4203 32.3056 37.4203 32.9869 37.7391 33.5397C38.0578 34.0925 38.6471 34.4331 39.285 34.4331H41.07C41.7079 34.4331 42.2972 34.0925 42.616 33.5397C42.9347 32.9869 42.9347 32.3056 42.616 31.7528C42.2972 31.2 41.7079 30.8594 41.07 30.8594Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M35.7107 54.0885H64.271C65.2177 54.0885 66.1258 53.712 66.7956 53.0419C67.4649 52.3714 67.8411 51.4624 67.8411 50.5147V46.941C67.8411 45.9933 67.4649 45.0842 66.7956 44.4138C66.1258 43.7437 65.2177 43.3672 64.271 43.3672H35.7107C34.764 43.3672 33.8559 43.7437 33.1861 44.4138C32.5168 45.0843 32.1406 45.9933 32.1406 46.941V50.5147C32.1406 51.4624 32.5168 52.3714 33.1861 53.0419C33.8559 53.712 34.764 54.0885 35.7107 54.0885ZM35.7107 46.941H64.271V50.5147H35.7107V46.941Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><path d=\"M62.4873 57.6641H55.3472C53.4338 57.6641 51.6659 58.686 50.7097 60.3444C49.753 62.0028 49.753 64.0466 50.7097 65.705C51.6659 67.3635 53.4338 68.3854 55.3472 68.3854H62.4873C64.4006 68.3854 66.1685 67.3635 67.1247 65.705C68.0814 64.0466 68.0814 62.0028 67.1247 60.3444C66.1685 58.686 64.4006 57.6641 62.4873 57.6641ZM62.4873 64.8116H55.3472C54.7093 64.8116 54.12 64.471 53.8012 63.9181C53.4825 63.3653 53.4825 62.6841 53.8012 62.1313C54.12 61.5785 54.7093 61.2378 55.3472 61.2378H62.4873C63.1252 61.2378 63.7144 61.5784 64.0332 62.1313C64.3519 62.6841 64.3519 63.3653 64.0332 63.9181C63.7144 64.471 63.1251 64.8116 62.4873 64.8116Z\" fill=\"black\" stroke=\"#BBF9BB\" stroke-width=\"1.19125\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUser-friendly platform\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00a0The platform offers a simple and intuitive interface for creating, managing, and promoting events.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c48553a elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"7c48553a\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-7c48553a{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b31230 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"8b31230\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100\" height=\"101\" viewbox=\"0 0 100 101\" fill=\"none\"><rect width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#E9D8FB\"><\/rect><path d=\"M50.5 26C44.002 26 37.7709 28.5811 33.176 33.176C28.581 37.7705 26 44.002 26 50.5C26 56.998 28.5811 63.2291 33.176 67.824C37.7705 72.4189 44.002 75 50.5 75C56.998 75 63.2291 72.4188 67.824 67.824C72.4189 63.2295 75 56.998 75 50.5C74.9929 44.0044 72.409 37.777 67.8161 33.1841C63.2232 28.5912 56.9952 26.0073 50.5002 26.0002L50.5 26ZM50.5 71.0803C45.042 71.0803 39.807 68.9123 35.9479 65.0525C32.0882 61.1931 29.9201 55.9583 29.9201 50.5004C29.9201 45.0425 32.0881 39.8074 35.9479 35.9483C39.8073 32.0886 45.0421 29.9205 50.5 29.9205C55.9579 29.9205 61.193 32.0885 65.0521 35.9483C68.9118 39.8077 71.0799 45.0425 71.0799 50.5004C71.0735 55.9568 68.9036 61.1874 65.0454 65.0454C61.1871 68.9036 55.9563 71.0736 50.5004 71.0799L50.5 71.0803ZM50.5 41.6797C51.5396 41.6797 52.5367 41.267 53.2719 40.5319C54.0069 39.7968 54.42 38.7997 54.42 37.76C54.42 36.72 54.0069 35.7233 53.2719 34.9878C52.5368 34.2528 51.5397 33.84 50.5 33.84C49.4603 33.84 48.4633 34.2527 47.7281 34.9878C46.993 35.7233 46.58 36.72 46.58 37.76C46.58 38.7996 46.9931 39.7967 47.7281 40.5319C48.4632 41.267 49.4603 41.6797 50.5 41.6797ZM60.9982 41.7L50.7416 43.1919V43.1923C50.581 43.2153 50.4176 43.2153 50.2571 43.1923L40.0015 41.7004V41.7C39.3096 41.6012 38.6169 41.8784 38.1844 42.4275C37.7519 42.9766 37.6444 43.7149 37.9025 44.3643C38.1607 45.0142 38.7455 45.4773 39.4369 45.58L45.7497 46.4987V46.4983C45.9864 46.5328 46.1625 46.7362 46.1625 46.9756V54.5386L45.9948 55.3118L41.9462 64.2121V64.2125C41.5933 64.8171 41.5898 65.5645 41.9375 66.1724C42.2848 66.7806 42.9299 67.1568 43.6305 67.16C44.3307 67.1632 44.9794 66.7925 45.3323 66.1878L50.0254 56.422C50.1158 56.2337 50.3065 56.1139 50.5155 56.1143C50.7248 56.1147 50.9151 56.2349 51.0051 56.4232L55.6654 66.1874V66.1878C56.0191 66.7905 56.6673 67.1596 57.3668 67.1556C58.0658 67.1521 58.71 66.7762 59.0574 66.17C59.4051 65.5633 59.4035 64.8176 59.053 64.2125L54.9402 55.1707L54.8359 54.6902V46.9757C54.8359 46.7363 55.012 46.5329 55.2487 46.4988L61.5604 45.5801H61.5608C62.2522 45.4778 62.8366 45.0151 63.0951 44.3657C63.3532 43.7162 63.2462 42.978 62.814 42.4288C62.3819 41.8797 61.69 41.6018 60.9977 41.7001L60.9982 41.7Z\" fill=\"black\" stroke=\"#E9D8FB\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEfficient accessibility\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe are committed to providing efficient and cost-effective event booking services. Accessible worldwide, we strive to make event booking a breeze.\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31263d69 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"31263d69\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><rect x=\"0.960938\" y=\"0.507812\" width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#FFB661\"><\/rect><path d=\"M74.0651 57.1848C73.6173 56.6291 72.804 56.5412 72.2485 56.9891L64.8094 62.9833L61.6208 60.1415V60.1411C61.0871 59.6662 60.27 59.714 59.7956 60.2481C59.3209 60.7823 59.369 61.6003 59.9026 62.0756L63.9107 65.6453C64.3823 66.0647 65.0883 66.082 65.58 65.6857L73.872 59.0041C74.4271 58.555 74.5133 57.7405 74.0651 57.1848L74.0651 57.1848Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M66.9075 49.4062C63.7247 49.4062 60.6719 50.6722 58.4212 52.9251C56.1705 55.1782 54.9062 58.2338 54.9062 61.4199C54.9062 64.6064 56.1705 67.662 58.4212 69.9151C60.6719 72.1681 63.7247 73.4339 66.9075 73.4339C70.0903 73.4339 73.1428 72.168 75.3934 69.9151C77.6441 67.662 78.9086 64.6064 78.9086 61.4199C78.9052 58.2349 77.6394 55.1812 75.3896 52.929C73.1398 50.6767 70.0892 49.4101 66.9075 49.4062ZM66.9075 70.8453V70.8457C64.4103 70.8457 62.0153 69.8524 60.2494 68.0847C58.4834 66.3169 57.4916 63.9195 57.4916 61.4196C57.4916 58.9198 58.4834 56.5223 60.2494 54.7545C62.0153 52.9871 64.4102 51.9939 66.9075 51.9939C69.4047 51.9939 71.7997 52.9871 73.5656 54.7545C75.3312 56.5223 76.3234 58.9197 76.3234 61.4196C76.3207 63.9187 75.3277 66.3145 73.5626 68.0815C71.7974 69.8489 69.404 70.8429 66.9076 70.8456L66.9075 70.8453Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M40.7878 47.9045C39.7463 46.9286 38.3647 46.3994 36.9386 46.431C35.5124 46.4622 34.155 47.0515 33.1578 48.0721C32.1602 49.093 31.6016 50.4642 31.6016 51.8922C31.6016 53.3202 32.1602 54.6913 33.1578 55.7123C34.155 56.7329 35.5123 57.3221 36.9386 57.3534C38.3647 57.3849 39.7463 56.8558 40.7878 55.8799C41.8288 56.8546 43.21 57.3826 44.635 57.3507C46.06 57.3191 47.4162 56.7299 48.4126 55.7096C49.4094 54.6894 49.9676 53.3191 49.9676 51.8922C49.9676 50.4653 49.4094 49.095 48.4126 48.0748C47.4162 47.0545 46.0599 46.4653 44.635 46.4337C43.2099 46.4017 41.8288 46.9297 40.7878 47.9045ZM37.0744 54.7713C36.313 54.7717 35.5827 54.469 35.0442 53.9302C34.5056 53.3914 34.2032 52.6604 34.2028 51.8983C34.2028 51.1361 34.5052 50.4051 35.0434 49.866C35.5817 49.3272 36.3119 49.0241 37.0732 49.0241C37.8345 49.0241 38.5648 49.3268 39.103 49.8656C39.6416 50.4048 39.944 51.1358 39.944 51.8979C39.9432 52.6597 39.6409 53.3899 39.103 53.9287C38.5648 54.4675 37.8353 54.7706 37.0743 54.7714L37.0744 54.7713ZM47.3715 51.8944C47.3723 52.6981 47.0364 53.4657 46.4451 54.0095C45.8538 54.5533 45.0616 54.824 44.2614 54.7551C43.4612 54.6861 42.7267 54.2841 42.2369 53.6471C42.627 52.5125 42.627 51.2801 42.2369 50.1455C42.7736 49.4353 43.6135 49.0197 44.5034 49.024C45.2628 49.0247 45.9911 49.3271 46.5289 49.8643C47.0664 50.4016 47.3692 51.1303 47.3715 51.8909L47.3715 51.8944Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M66.3177 40.4112C66.3177 39.6968 65.7391 39.1172 65.025 39.1172H54.4255C53.7114 39.1172 53.1328 39.6968 53.1328 40.4112C53.1328 41.126 53.7114 41.7053 54.4255 41.7053H65.025C65.3678 41.7053 65.6968 41.5689 65.9391 41.3263C66.1815 41.0837 66.3177 40.7547 66.3177 40.4112Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><path d=\"M52.7752 60.8846H27.9301C27.7396 60.8846 27.5853 60.7302 27.5853 60.5395V35.9337C27.5853 35.7431 27.7396 35.5886 27.9301 35.5886H70.0101C70.1012 35.5886 70.189 35.6252 70.2536 35.6899C70.3182 35.7546 70.3548 35.842 70.3548 35.9337V47.6978C71.2447 47.922 72.1107 48.2328 72.9402 48.626V35.9331C72.9402 35.1552 72.6312 34.4092 72.0818 33.8592C71.5324 33.3093 70.7872 33 70.0101 33H27.9301C27.1529 33 26.4077 33.3093 25.8579 33.8592C25.3086 34.4092 25 35.1552 25 35.9331V60.539C25 61.3169 25.3086 62.0629 25.8579 62.6133C26.4077 63.1632 27.1529 63.4721 27.9301 63.4721H52.9131H52.9128C52.8085 62.7943 52.7535 62.1095 52.7485 61.4232C52.7485 61.2422 52.7681 61.0647 52.775 60.884L52.7752 60.8846Z\" fill=\"black\" stroke=\"#FFB661\" stroke-width=\"0.15\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSecure and fast transactions\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEventBookings provides prompt payouts through a dependable and fast payment transfer system and uses secure payment processing to protect your information.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-640e3415\" data-id=\"640e3415\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19340c53 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"19340c53\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"101\" height=\"101\" viewbox=\"0 0 101 101\" fill=\"none\"><path d=\"M65.6175 33.3273L64.0728 32.1582C64.0473 32.1402 64.0214 32.1281 63.9959 32.1101C63.2649 28.5016 59.8746 25.7624 55.8043 25.7624H55.6251L51.6191 22.7292C48.4273 20.3497 43.9725 20.3497 40.7741 22.7351L36.7749 25.7623H36.5956C32.5257 25.7623 29.1288 28.5078 28.4045 32.1162C28.3661 32.1401 28.3214 32.1581 28.2892 32.1882L26.7893 33.3213C24.0585 35.3889 22.4883 38.4644 22.4883 41.755V60.1277C22.4883 65.6366 27.2825 70.1203 33.1791 70.1203H59.2336C65.124 70.1203 69.9182 65.6366 69.9182 60.1219V41.7546C69.9182 38.4639 68.348 35.3948 65.6176 33.3268L65.6175 33.3273ZM67.1108 39.8012L64.1497 42.0068V35.3112C65.643 36.492 66.6686 38.0625 67.1108 39.8011V39.8012ZM42.3828 24.6055C44.6325 22.9271 47.7734 22.9271 50.0163 24.5996L51.5547 25.7624H40.8506L42.3828 24.6055ZM36.6014 28.16H55.8104C58.9959 28.16 61.5917 30.5819 61.5917 33.5669V43.9254L50.0226 52.551C47.7729 54.2295 44.632 54.2295 42.3823 52.551L30.8201 43.9191V33.5669C30.8201 30.5819 33.4092 28.16 36.6014 28.16ZM28.2561 35.3114V42.007L25.295 39.801C25.7372 38.0628 26.7628 36.4923 28.2561 35.3115V35.3114ZM59.2264 67.7226H33.1776C28.6973 67.7226 25.0504 64.3115 25.0504 60.1218V42.6836L40.7799 54.4207C42.376 55.6137 44.286 56.2071 46.2022 56.2071C48.1185 56.2071 50.0289 55.6137 51.6245 54.4207L67.3541 42.6836V60.1207C67.3541 64.3109 63.7072 67.722 59.2269 67.722L59.2264 67.7226Z\" fill=\"black\"><\/path><path d=\"M39.9497 37.7573H52.4677C53.1727 37.7573 53.7495 37.2179 53.7495 36.5586C53.7495 35.8992 53.1727 35.3598 52.4677 35.3598L39.9497 35.3594C39.2447 35.3594 38.668 35.8988 38.668 36.5581C38.668 37.2175 39.2385 37.7573 39.9497 37.7573V37.7573Z\" fill=\"black\"><\/path><path d=\"M39.9497 46.1475H52.4677C53.1727 46.1475 53.7495 45.6081 53.7495 44.9488C53.7495 44.2894 53.1727 43.75 52.4677 43.75H39.9497C39.2447 43.75 38.668 44.2894 38.668 44.9488C38.668 45.6082 39.2385 46.1475 39.9497 46.1475Z\" fill=\"black\"><\/path><rect x=\"0.660156\" y=\"0.5\" width=\"100\" height=\"100\" rx=\"50\" fill=\"#FFC9BD\"><\/rect><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M33.7143 46.485C32.6364 46.7632 31.6416 47.3258 30.8419 48.1273C29.6615 49.3059 29 50.904 29 52.5711V57.2854C29 58.9526 29.6615 60.5506 30.8419 61.7292C32.0205 62.9096 33.6186 63.5711 35.2857 63.5711H36.8571C37.6899 63.5711 38.49 63.2396 39.0792 62.6503C39.6685 62.0611 40 61.2609 40 60.4283V49.4283C40 48.5956 39.6685 47.7954 39.0792 47.2062C38.4899 46.617 37.6916 46.2854 36.8571 46.2854V44.6309C36.9091 37.6818 43.2684 32.143 51 32.143C58.7628 32.143 65.1429 37.7278 65.1429 44.7144V46.2858C64.3101 46.2858 63.51 46.6173 62.9208 47.2066C62.3315 47.7958 62 48.596 62 49.4286V60.4286C62 61.2613 62.3315 62.0615 62.9208 62.6507C63.3498 63.0797 63.8889 63.3719 64.4718 63.4992C63.9502 64.6163 63.3059 65.4806 62.396 66.0293C61.7832 66.3986 61.0571 66.6105 60.1929 66.6782C59.5313 64.8679 57.787 63.5714 55.7378 63.5714C53.1201 63.5714 51 65.6866 51 68.2857C51 70.8849 53.12 73 55.7378 73C57.8136 73 59.5751 71.6706 60.2164 69.8255C61.7359 69.7361 62.9776 69.3478 64.0176 68.721C65.7606 67.6697 66.9721 65.9033 67.8739 63.463C69.1107 63.2318 70.2577 62.6317 71.1581 61.7295C72.3385 60.5509 73 58.9528 73 57.2857V52.5714C73 50.9042 72.3385 49.3061 71.1581 48.1276C70.3584 47.3261 69.3636 46.7635 68.2857 46.4853V44.7143C68.2857 36.0886 60.5843 29 51 29C41.4547 29 33.7753 36.0335 33.7143 44.6119V46.485ZM57.3064 67.9992C57.1696 67.2651 56.5161 66.7137 55.7381 66.7137C54.8612 66.7137 54.1431 67.4145 54.1431 68.2851C54.1431 69.1557 54.8611 69.8565 55.7381 69.8565C56.527 69.8565 57.1885 69.2894 57.3127 68.5412C57.2892 68.4202 57.2814 68.2929 57.2892 68.1659C57.2923 68.1091 57.2987 68.0525 57.3064 67.9992ZM66.7367 60.428C67.5617 60.4217 68.352 60.0916 68.9367 59.5072C69.526 58.9179 69.8575 58.1178 69.8575 57.2851V52.5709C69.8575 51.7381 69.526 50.938 68.9367 50.3488C68.3474 49.7595 67.5473 49.428 66.7146 49.428H65.1432V60.428H66.7367ZM36.8571 49.428V60.428H35.2857C34.453 60.428 33.6529 60.0965 33.0636 59.5072C32.4744 58.9179 32.1429 58.1178 32.1429 57.2851V52.5709C32.1429 51.7381 32.4743 50.938 33.0636 50.3488C33.6529 49.7595 34.453 49.428 35.2857 49.428H36.8571Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRound-the-clock customer support\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOur customer support team is available to answer questions, help with event setup, and resolve even complex issues.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41ebdbe elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"41ebdbe\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100\" height=\"101\" viewbox=\"0 0 100 101\" fill=\"none\"><rect y=\"0.101562\" width=\"100\" height=\"100.104\" rx=\"50\" fill=\"#B8EAE9\"><\/rect><path d=\"M67.8454 30.1016H32.1059C30.7515 30.1016 29.4532 30.6281 28.4954 31.566C27.5381 32.5035 27 33.7754 27 35.1013V57.6014C27 58.9277 27.5381 60.1992 28.4954 61.1371C29.4532 62.0746 30.7515 62.6015 32.1059 62.6015H47.4231V67.6017H41.0407C40.3359 67.6017 39.7645 68.1613 39.7645 68.8514C39.7645 69.542 40.3359 70.1016 41.0407 70.1016H58.9115C59.6162 70.1016 60.1876 69.542 60.1876 68.8514C60.1876 68.1613 59.6162 67.6017 58.9115 67.6017H52.529V62.6015H67.8462C69.2006 62.6015 70.499 62.0746 71.4567 61.1371C72.4141 60.1992 72.9521 58.9277 72.9521 57.6014V35.1013C72.9521 33.7754 72.4141 32.5035 71.4567 31.566C70.499 30.6281 69.2006 30.1016 67.8462 30.1016H67.8454ZM70.3981 57.602L70.3985 57.6016C70.3977 58.2645 70.1284 58.8998 69.6497 59.3686C69.1711 59.8374 68.5223 60.101 67.8454 60.1019H32.1059C31.4289 60.101 30.7802 59.8374 30.3015 59.3686C29.8229 58.8998 29.5536 58.2645 29.5528 57.6016V35.1015C29.5536 34.439 29.8229 33.8033 30.3015 33.3349C30.7802 32.8662 31.429 32.6025 32.1059 32.6017H67.8454C68.5223 32.6025 69.1711 32.8662 69.6497 33.3349C70.1284 33.8033 70.3977 34.4391 70.3985 35.1015L70.3981 57.602ZM49.9752 47.6017C51.3291 47.6017 52.6279 47.0748 53.5857 46.1373C54.543 45.1993 55.0811 43.9279 55.0811 42.6015C55.0811 41.2756 54.543 40.0037 53.5857 39.0662C52.6279 38.1283 51.3291 37.6018 49.9752 37.6018C48.6212 37.6018 47.3225 38.1283 46.3647 39.0662C45.4074 40.0037 44.8693 41.2756 44.8693 42.6015C44.8706 43.9274 45.4091 45.1985 46.3664 46.1356C47.3238 47.0731 48.6217 47.6004 49.9752 47.6017ZM49.9752 40.1017C50.6521 40.1017 51.3018 40.3649 51.7804 40.8341C52.2591 41.3029 52.5279 41.9386 52.5279 42.6015C52.5279 43.2649 52.2591 43.9006 51.7804 44.3694C51.3018 44.8381 50.6522 45.1018 49.9752 45.1018C49.2982 45.1018 48.6486 44.8381 48.1699 44.3694C47.6913 43.9006 47.4225 43.2649 47.4225 42.6015C47.4233 41.939 47.6926 41.3037 48.1708 40.835C48.6495 40.3662 49.2983 40.1025 49.9752 40.1017ZM60.1861 55.4996L60.1865 56.3514C60.1865 57.0415 59.6151 57.6011 58.9104 57.6011C58.2052 57.6011 57.6338 57.0415 57.6338 56.3514V55.4992C57.6338 54.9991 57.3291 54.5471 56.8598 54.3503L55.5059 53.7816C51.9723 52.3071 47.978 52.3071 44.4447 53.7816L43.0898 54.3503H43.0894C42.6206 54.5479 42.3167 54.9995 42.3167 55.4992V56.3514C42.3167 57.0415 41.7453 57.6011 41.0401 57.6011C40.3354 57.6011 39.764 57.0415 39.764 56.3514V55.4992C39.7636 54.7656 39.9832 54.0478 40.3957 53.435C40.8081 52.8223 41.3949 52.3418 42.0838 52.0531L43.44 51.4843C47.615 49.7411 52.3359 49.7411 56.511 51.4843L57.8658 52.0531C58.5552 52.3419 59.1424 52.8223 59.5549 53.4347C59.9677 54.0474 60.1874 54.7652 60.187 55.4993L60.1861 55.4996Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIntegrated video conferencing\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tThe platform features an in-built video conferencing solution, saving you time and money.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9f8134 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5f9f8134\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100\" height=\"100\" viewbox=\"0 0 100 100\" fill=\"none\"><rect width=\"100\" height=\"100\" rx=\"50\" fill=\"#C0EBFA\"><\/rect><path d=\"M69.1292 37.382L67.5845 36.2128C67.559 36.1949 67.5331 36.1827 67.5076 36.1648C66.7766 32.5563 63.3863 29.8171 59.3161 29.8171H59.1368L55.1309 26.7839C51.9391 24.4044 47.4842 24.4044 44.2858 26.7898L40.2866 29.817H40.1073C36.0374 29.817 32.6405 32.5624 31.9163 36.1709C31.8778 36.1948 31.8331 36.2127 31.8009 36.2429L30.301 37.376C27.5702 39.4436 26 42.519 26 45.8097V64.1824C26 69.6913 30.7942 74.175 36.6908 74.175H62.7453C68.6357 74.175 73.4299 69.6913 73.4299 64.1766V45.8093C73.4299 42.5186 71.8597 39.4495 69.1294 37.3815L69.1292 37.382ZM70.6225 43.8559L67.6614 46.0615V39.3659C69.1547 40.5467 70.1803 42.1172 70.6225 43.8557V43.8559ZM45.8945 28.6602C48.1442 26.9818 51.2851 26.9818 53.5281 28.6543L55.0665 29.8171H44.3623L45.8945 28.6602ZM40.1131 32.2147H59.3221C62.5076 32.2147 65.1035 34.6365 65.1035 37.6216V47.9801L53.5344 56.6057C51.2846 58.2841 48.1438 58.2841 45.894 56.6057L34.3318 47.9738V37.6216C34.3318 34.6365 36.9209 32.2147 40.1131 32.2147ZM31.7678 39.3661V46.0617L28.8067 43.8556C29.2489 42.1175 30.2745 40.547 31.7678 39.3662V39.3661ZM62.7381 71.7773H36.6893C32.209 71.7773 28.5621 68.3662 28.5621 64.1765V46.7383L44.2917 58.4754C45.8877 59.6684 47.7978 60.2617 49.714 60.2617C51.6302 60.2617 53.5407 59.6684 55.1363 58.4754L70.8658 46.7383V64.1754C70.8658 68.3656 67.2189 71.7767 62.7386 71.7767L62.7381 71.7773Z\" fill=\"black\"><\/path><path d=\"M43.4615 41.812H55.9794C56.6845 41.812 57.2612 41.2726 57.2612 40.6132C57.2612 39.9539 56.6844 39.4145 55.9794 39.4145L43.4615 39.4141C42.7564 39.4141 42.1797 39.9535 42.1797 40.6128C42.1797 41.2722 42.7502 41.812 43.4615 41.812V41.812Z\" fill=\"black\"><\/path><path d=\"M43.4615 50.2022H55.9794C56.6845 50.2022 57.2612 49.6628 57.2612 49.0035C57.2612 48.3441 56.6844 47.8047 55.9794 47.8047H43.4615C42.7564 47.8047 42.1797 48.3441 42.1797 49.0035C42.1797 49.6629 42.7502 50.2022 43.4615 50.2022Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEmbedded email marketing tools\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEventBookings eliminates the need for third-party email service providers with its built-in tools for successful email marketing.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a4d7ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a4d7ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-516ffadd\" data-id=\"516ffadd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23f84096 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23f84096\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-65ed6668\" data-id=\"65ed6668\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b175065 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"6b175065\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Control everything from one platform<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7377d7 br-none elementor-widget elementor-widget-heading\" data-id=\"1e7377d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">EventBookings offers a streamlined ticketing solution that simplifies event management. Its user-friendly design is accompanied by a comprehensive set of outstanding features that can elevate your event experiences. Explore more about these features compare to Humanitx:<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5486262e laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5486262e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af882d7\" data-id=\"af882d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-783fee04 elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"783fee04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f249704\" data-id=\"6f249704\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40de80d8 elementor-widget elementor-widget-image\" data-id=\"40de80d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"679\" height=\"531\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event.png\" class=\"attachment-full size-full wp-image-220246\" alt=\"Compare with EventBookings competitors\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event.png 679w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event-300x235.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/compare-event-15x12.png 15w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d2f523\" data-id=\"9d2f523\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dc87873 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"7dc87873\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Low-cost ticketing solution<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc10be3 elementor-widget elementor-widget-text-editor\" data-id=\"fc10be3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Choose EventBookings for a more affordable option compared to Humanitix. Our fee is 2% + 30c per ticket in Australia, while Humanitix charges 4% + 99\u00a2 under its standard package. Utilise our intuitive features and stay within budget with our<a href=\"https:\/\/www.eventbookings.com\/en-it\/\"> low-cost ticketing platform<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-feced3a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"feced3a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65956b75\" data-id=\"65956b75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1258e64c SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"1258e64c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Built-in virtual event platform<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39d2436d br-none elementor-widget elementor-widget-heading\" data-id=\"39d2436d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">With EventBookings, you can stream your events without the need for a third-party platform. Our platform includes an embedded virtual event platform with features such as video meeting recording, breakout sessions, virtual polling, and screen sharing. Humanitix requires you to integrate with third-party video conferencing software.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b9fee96\" data-id=\"1b9fee96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb70e21 elementor-widget elementor-widget-image\" data-id=\"fb70e21\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"502\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Run-virtual-\u2028business-events.png\" class=\"attachment-full size-full wp-image-106637\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Run-virtual-\u2028business-events.png 673w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Run-virtual-\u2028business-events-300x224.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Run-virtual-\u2028business-events-16x12.png 16w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f35bb54 elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2f35bb54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3dfd02e6\" data-id=\"3dfd02e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49cd5ab elementor-widget elementor-widget-image\" data-id=\"49cd5ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"574\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/efficient-organiser-dashboard.png\" class=\"attachment-full size-full wp-image-220286\" alt=\"efficient organiser dashboard\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/efficient-organiser-dashboard.png 741w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/efficient-organiser-dashboard-300x232.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/efficient-organiser-dashboard-15x12.png 15w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dbabc97\" data-id=\"dbabc97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38690f38 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"38690f38\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Intuitive organizer dashboard<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78a22b5e br-none elementor-widget elementor-widget-heading\" data-id=\"78a22b5e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Easily monitor all the important details of your event with EventBookings' intuitive dashboard. Get a complete overview of your sales status, visitor details, and more, all in one easy-to-navigate platform. Optimize your event based on analytical insights.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-473e4de5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"473e4de5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2c0744da\" data-id=\"2c0744da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b3f00f3 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"7b3f00f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Branded and high-converting event page<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-614fc9a elementor-widget elementor-widget-text-editor\" data-id=\"614fc9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Customise the look of your event page to match your branding with EventBookings. Our platform includes all the necessary information, such as event details, organiser profile, and ticket information in a modern layout. Add multiple sections with text, images, and videos to promote your event, and use strategic placement of social buttons, booking and countdown timers, and call-to-action buttons to <a href=\"https:\/\/www.eventbookings.com\/blog\/increase-ticket-sales\/\" target=\"_blank\" rel=\"noopener\">increase ticket sales<\/a>.\u200b<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20585051\" data-id=\"20585051\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8952fca elementor-widget elementor-widget-image\" data-id=\"8952fca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"633\" height=\"447\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page.png\" class=\"attachment-full size-full wp-image-106597\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page.png 633w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-300x212.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-18x12.png 18w\" sizes=\"(max-width: 633px) 100vw, 633px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d15dbfc elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2d15dbfc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d9617f4\" data-id=\"5d9617f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7921913 elementor-widget elementor-widget-image\" data-id=\"7921913\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"471\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/social-marketing-2.png\" class=\"attachment-full size-full wp-image-113505\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/social-marketing-2.png 617w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/social-marketing-2-300x229.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/social-marketing-2-16x12.png 16w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-40089dfb\" data-id=\"40089dfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eaf1173 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"2eaf1173\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Packed with marketing tools<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78c4efc elementor-widget elementor-widget-text-editor\" data-id=\"78c4efc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Maximize your<a href=\"https:\/\/www.eventbookings.com\/sell-event-tickets\/\" target=\"_blank\" rel=\"noopener\"> event&#8217;s ticket sale<\/a> with EventBookings\u2019 marketing tools. Create custom email campaigns, promote on social media, offer discounts and coupons, send invitations, and track RSVP responses. Utilize all the available promotional tools to become a marketing pro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55b9907a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b9907a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dfb3504\" data-id=\"7dfb3504\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d641eb3 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"1d641eb3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Protecting your privacy with EventBookings<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-798c08d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"798c08d1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-555478aa\" data-id=\"555478aa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ccf797f SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"6ccf797f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"67\" viewbox=\"0 0 59 67\" fill=\"none\"><path d=\"M2.20243 57.0145C3.61449 58.4237 5.52792 59.2151 7.52282 59.2151C9.51772 59.2151 11.4311 58.4237 12.8432 57.0145L13.9611 55.8966C15.2906 56.8718 16.9251 57.3391 18.5692 57.2141C20.2132 57.0891 21.7583 56.38 22.9251 55.2149L25.0113 53.1287L36.5108 64.6108C36.9709 65.0667 37.517 65.4268 38.1173 65.6701C38.7177 65.9135 39.3604 66.0352 40.0081 66.0283C41.5106 65.9886 42.9462 65.3991 44.043 64.3714C45.1398 63.3437 45.8213 61.9494 45.9586 60.4527C46.021 59.7413 45.9275 59.025 45.6847 58.3535C45.4419 57.682 45.0555 57.0715 44.5526 56.5646L33.1015 45.0992C37.6142 41.0905 42.1818 40.0824 48.2615 39.8275L48.9771 40.5431C50.0367 41.6023 51.4735 42.1974 52.9717 42.1974C54.4698 42.1974 55.9067 41.6023 56.9662 40.5431L57.0276 40.4818C57.5517 39.9577 57.9675 39.3355 58.2512 38.6507C58.5349 37.966 58.6809 37.232 58.6809 36.4908C58.6809 35.7496 58.5349 35.0157 58.2512 34.3309C57.9675 33.6462 57.5517 33.024 57.0276 32.4999L26.7156 2.18937C25.6563 1.13256 24.221 0.539062 22.7247 0.539062C21.2283 0.539062 19.7931 1.13256 18.7337 2.18937L18.6659 2.25725C17.609 3.31671 17.0155 4.75208 17.0155 6.24854C17.0155 7.745 17.609 9.18037 18.6659 10.2398L19.3815 10.9555C19.1158 17.5335 17.9495 22.3458 13.0692 27.2261L4.00706 36.2854C2.84178 37.452 2.13248 38.9971 2.00744 40.6412C1.88241 42.2854 2.3499 43.92 3.32536 45.2494L2.20026 46.3745C0.791285 47.7866 0 49.7 0 51.6949C0 53.6897 0.791285 55.6031 2.20026 57.0152L2.20243 57.0145ZM4.60861 54.6011C4.22317 54.2207 3.91714 53.7675 3.70825 53.2679C3.49937 52.7682 3.39181 52.2321 3.39181 51.6905C3.39181 51.149 3.49937 50.6128 3.70825 50.1132C3.91714 49.6135 4.22317 49.1603 4.60861 48.7799L5.6651 47.7234L11.4863 53.5446L10.4298 54.6011C10.0498 54.9869 9.597 55.2935 9.09762 55.5029C8.59824 55.7124 8.06224 55.8206 7.52072 55.8212C6.9792 55.8219 6.44293 55.715 5.94303 55.5068C5.44313 55.2986 4.98955 54.9932 4.60861 54.6083V54.6011ZM41.7795 61.8269C40.9007 62.6992 39.5914 62.8769 38.9162 62.1952L27.424 50.7095L30.6737 47.4786L42.1558 58.9715C42.831 59.646 42.6613 60.9545 41.781 61.8276L41.7795 61.8269ZM21.0706 4.67715L21.1385 4.60927C21.5586 4.19144 22.1271 3.9569 22.7196 3.9569C23.3122 3.9569 23.8806 4.19144 24.3007 4.60927L54.6221 34.9075C55.0408 35.3272 55.276 35.8958 55.276 36.4887C55.276 37.0815 55.0408 37.6501 54.6221 38.0698L54.5607 38.1312C54.141 38.5501 53.5723 38.7854 52.9792 38.7854C52.3862 38.7854 51.8175 38.5501 51.3978 38.1312L21.0677 7.8257C20.654 7.4059 20.422 6.84014 20.422 6.2507C20.422 5.66127 20.654 5.09551 21.0677 4.67571L21.0706 4.67715ZM45.0653 36.6407C39.6867 37.1722 35.1538 38.6858 30.6881 42.6872L16.5334 28.5353C20.555 24.0768 22.0484 19.5374 22.5799 14.1582L45.0653 36.6407ZM6.42336 38.6858L14.1503 30.969L28.2473 45.0659L20.5203 52.7929C19.862 53.4505 18.9695 53.8198 18.039 53.8198C17.1085 53.8198 16.2161 53.4505 15.5578 52.7929L6.42336 43.6621C5.76577 43.0037 5.3964 42.1113 5.3964 41.1808C5.3964 40.2503 5.76577 39.3579 6.42336 38.6995V38.6858Z\" fill=\"#22D88F\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAttendee information security\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAt EventBookings, the privacy of your attendees is of utmost importance. We won't use their interests for promoting other events on your page.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1d402879\" data-id=\"1d402879\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cb0dc1d SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"3cb0dc1d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\" viewbox=\"0 0 64 64\" fill=\"none\"><path d=\"M44.9089 21.7763C46.5348 21.7763 48.0942 21.1304 49.244 19.9807C50.3937 18.831 51.0396 17.2717 51.0396 15.6458C51.0396 14.0199 50.3937 12.4606 49.244 11.3109C48.0942 10.1612 46.5348 9.51532 44.9089 9.51532C44.7637 8.17194 44.1209 6.93156 43.107 6.03832C42.0931 5.14509 40.7816 4.66372 39.4305 4.68895C38.4141 4.71239 37.4215 5.00167 36.5516 5.52799C35.6817 6.05431 34.9649 6.79931 34.4724 7.68881C34.1242 6.12077 33.2468 4.72036 31.9878 3.72291C30.7287 2.72545 29.1646 2.19175 27.5584 2.21146C25.6609 2.22797 23.8457 2.98908 22.5038 4.33087C21.162 5.67265 20.4008 7.48776 20.3843 9.38526V9.51603C19.9144 9.40156 19.4301 9.35749 18.9472 9.38526C17.3212 9.38526 15.7618 10.0311 14.6121 11.1808C13.4623 12.3305 12.8164 13.8898 12.8164 15.5158C12.8164 17.1417 13.4623 18.701 14.6121 19.8507C15.7618 21.0004 17.3212 21.6462 18.9472 21.6462H44.9038L44.9089 21.7763Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M4.60547 41.3438H25.4754V55.6906H4.60547V41.3438Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M59.3897 55.6906H43.738C43.0466 55.6887 42.3841 55.4132 41.8952 54.9244C41.4063 54.4355 41.1308 53.773 41.1289 53.0816V43.9527C41.1308 43.2614 41.4063 42.5989 41.8952 42.11C42.3841 41.6211 43.0466 41.3456 43.738 41.3438H59.3905C60.0819 41.3456 60.7444 41.6211 61.2333 42.11C61.7222 42.5989 61.9977 43.2614 61.9996 43.9527V53.0823C61.9975 53.7737 61.7218 54.4361 61.2328 54.9249C60.7437 55.4136 60.0811 55.6889 59.3897 55.6906Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M28.0838 62.2089H2L4.6091 55.6875H25.4747L28.0838 62.2089Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linejoin=\"round\"><\/path><path d=\"M51.5625 55.6875V60.904\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M46.3477 60.9062H56.7826\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M34.6055 29.6016H51.5635V36.1229\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M12.4297 36.1229V29.6016H29.3878\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M31.9961 26.9978V21.7812\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M34.6049 29.6012C34.6049 30.1172 34.4519 30.6216 34.1652 31.0506C33.8785 31.4797 33.471 31.8141 32.9943 32.0115C32.5175 32.209 31.9929 32.2607 31.4868 32.16C30.9807 32.0593 30.5158 31.8109 30.1509 31.446C29.786 31.0811 29.5375 30.6162 29.4369 30.1102C29.3362 29.6041 29.3879 29.0795 29.5853 28.6027C29.7828 28.126 30.1172 27.7186 30.5463 27.4319C30.9753 27.1452 31.4798 26.9922 31.9958 26.9922C32.6878 26.9922 33.3514 27.2671 33.8407 27.7563C34.33 28.2456 34.6049 28.9092 34.6049 29.6012Z\" stroke=\"#0DABD2\" stroke-width=\"3\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSafe data management\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYour attendees' details will stay secure with EventBookings. We won't share it with advertisers or marketing agencies.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1b06399d\" data-id=\"1b06399d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11db1137 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"11db1137\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"62\" height=\"62\" viewbox=\"0 0 62 62\" fill=\"none\"><path d=\"M51.4264 44.0219H58.218C58.6223 44.0048 59.0257 44.0725 59.4024 44.2205C59.7808 44.3692 60.1237 44.5958 60.409 44.8855C60.6943 45.1752 60.9156 45.5215 61.0585 45.9022C61.1956 46.2672 61.2577 46.6559 61.2412 47.0452L61.2425 47.0645C61.2764 47.6031 61.1773 48.1418 60.9537 48.633C60.757 49.0653 60.4692 49.4491 60.111 49.7586C60.2524 50.1297 60.3254 50.524 60.3259 50.9222V50.9227C60.3255 51.3906 60.2115 51.8515 59.9936 52.2656C59.8075 52.6195 59.5503 52.9303 59.2389 53.1788C59.4771 53.8163 59.4876 54.519 59.2646 55.1664C59.042 55.8126 58.6023 56.3589 58.0236 56.7145C58.0932 56.9811 58.1282 57.2558 58.1275 57.5318M51.4264 44.0219L57.8775 57.5312M51.4264 44.0219C51.7764 42.9938 51.9867 41.9226 52.051 40.8373L52.0522 40.8184L52.0504 40.7995C51.867 38.8171 51.0036 36.9591 49.6067 35.5406L49.6054 35.5393C49.1177 35.0516 48.492 34.8532 47.8806 34.8241C47.2714 34.7952 46.6623 34.9331 46.178 35.1342L51.4264 44.0219ZM58.1275 57.5318L57.8775 57.5312M58.1275 57.5318C58.1275 57.5317 58.1275 57.5315 58.1275 57.5313L57.8775 57.5312M58.1275 57.5318C58.1272 58.2829 57.8287 59.0032 57.2976 59.5343C56.7663 60.0656 56.0459 60.3641 55.2946 60.3643H55.2945H43.2097H43.2089C43.0984 60.3639 42.9886 60.348 42.8825 60.317L42.8831 60.3171L42.9521 60.0768M57.8775 57.5312C57.8773 58.2163 57.6052 58.8732 57.1208 59.3575C56.6364 59.8419 55.9795 60.1141 55.2945 60.1143H43.2097C43.1225 60.114 43.0358 60.1014 42.9521 60.0768M42.9521 60.0768L42.8817 60.3167M42.9521 60.0768L42.5186 59.9525V60.1847C42.5186 60.194 42.5185 60.2032 42.5182 60.2125M42.8817 60.3167L31.5977 60.2926C31.6243 60.5218 31.7346 60.733 31.9073 60.8859C32.0801 61.0387 32.3032 61.1224 32.5338 61.1209M42.8817 60.3167L42.5182 60.2125M42.8817 60.3167L32.5346 61.3709M42.5182 60.2125L42.4216 60.1847L42.2686 60.1408V60.1847C42.2686 60.433 42.17 60.6711 41.9944 60.8467C41.8188 61.0222 41.5807 61.1209 41.3325 61.1209H32.5338M42.5182 60.2125C42.5111 60.517 42.3871 60.8075 42.1712 61.0234C41.9487 61.2459 41.647 61.3709 41.3325 61.3709H32.5346M32.5338 61.1209V61.3709H32.5346M32.5338 61.1209L32.5355 61.3708C32.5352 61.3708 32.5349 61.3709 32.5346 61.3709M32.5346 61.3709C32.2427 61.3726 31.9603 61.2666 31.7417 61.0731C31.5228 60.8794 31.3831 60.6118 31.3494 60.3214L31.3494 60.321L29.8517 47.2164M32.5346 61.3709L29.8517 47.2164M29.8517 47.2164C29.8516 47.2163 29.8516 47.2162 29.8516 47.2161M29.8517 47.2164L29.8516 47.2161M29.8516 47.2161C29.8323 47.0494 29.8486 46.8804 29.8995 46.7204C29.9503 46.5603 30.0347 46.4128 30.1468 46.2878C30.2589 46.1627 30.3963 46.0629 30.5499 45.9949C30.7032 45.9271 30.8692 45.8925 31.0368 45.8935M29.8516 47.2161L41.3318 46.1435M31.0368 45.8935C31.0371 45.8935 31.0375 45.8935 31.0378 45.8935L31.0361 46.1435V45.8935H31.0368ZM31.0368 45.8935H41.331M41.331 45.8935C41.3308 45.8935 41.3305 45.8935 41.3303 45.8935L41.3318 46.1435M41.331 45.8935H41.3318V46.1435M41.331 45.8935C41.4246 45.893 41.5176 45.9035 41.6082 45.9245C42.3855 44.8193 43.9898 42.3596 44.635 41.1403C44.8777 40.6818 44.959 39.9707 44.9578 39.2313C44.9567 38.5041 44.8767 37.7949 44.8275 37.3614C44.8274 37.3605 44.8273 37.3597 44.8272 37.3589L45.0756 37.3306C45.0505 37.1443 45.0348 36.9569 45.0286 36.769L41.3318 46.1435M57.9543 48.0412V48.0615C57.7714 48.0953 57.5977 48.1719 57.4481 48.2865C57.2291 48.4544 57.0754 48.6933 57.0136 48.9623C56.9518 49.2313 56.9857 49.5133 57.1095 49.76C57.2292 49.9986 57.4259 50.1896 57.6672 50.3025C57.7609 50.3711 57.8368 50.4612 57.8886 50.5654C57.9435 50.6757 57.9695 50.7981 57.9641 50.9212L57.9638 50.9212L57.9639 50.9337C57.9648 51.0708 57.9112 51.2027 57.815 51.3003C57.7189 51.3978 57.5881 51.4532 57.4514 51.4544H57.3538C57.0792 51.4256 56.8029 51.4935 56.5727 51.6467C56.3382 51.8029 56.167 52.0373 56.0896 52.3082C56.0122 52.5791 56.0337 52.8686 56.1503 53.1251C56.267 53.3815 56.471 53.5881 56.726 53.7078L56.7395 53.7141L56.7537 53.7188C56.8252 53.7425 56.8913 53.7801 56.9482 53.8295C57.005 53.879 57.0515 53.9392 57.0849 54.0067C57.1184 54.0742 57.1381 54.1477 57.1429 54.2229C57.1477 54.2981 57.1375 54.3735 57.113 54.4447C57.0884 54.516 57.05 54.5816 56.9999 54.6379C56.9498 54.6942 56.889 54.7399 56.8211 54.7725C56.7532 54.8051 56.6795 54.8239 56.6042 54.8278C56.529 54.8317 56.4537 54.8207 56.3828 54.7953L56.3709 54.791L56.3586 54.788C56.0742 54.7176 55.7738 54.7549 55.5152 54.8929C55.2567 55.0308 55.0584 55.2596 54.9586 55.535C54.8587 55.8105 54.8643 56.1132 54.9743 56.3848C55.0805 56.6469 55.2767 56.8621 55.5271 56.9921C55.6027 57.056 55.6636 57.1355 55.7055 57.2254C55.7507 57.3222 55.7726 57.4283 55.7694 57.5352L55.7693 57.5352V57.5426C55.7693 57.665 55.7207 57.7824 55.6341 57.8689C55.5476 57.9555 55.4302 58.0041 55.3079 58.0041H43.3773L42.5186 57.7453V48.3847C42.6617 48.3166 42.7935 48.226 42.9088 48.1162L42.9237 48.102L42.936 48.0855C44.333 46.2296 45.6026 44.2813 46.7363 42.2539L46.7364 42.2539L46.7392 42.2486C47.1569 41.4579 47.2964 40.4402 47.3213 39.5011C47.3436 38.6582 47.274 37.8538 47.2137 37.2896C47.338 37.2504 47.4794 37.2191 47.6116 37.2056C47.7102 37.1956 47.7935 37.1965 47.8557 37.2066C47.9133 37.2159 47.9314 37.2295 47.9315 37.2292C47.9316 37.2292 47.9311 37.2288 47.9304 37.228L47.9305 37.2282C48.9253 38.2441 49.5455 39.5676 49.6896 40.9821C49.6971 41.1071 49.6719 41.3252 49.6123 41.622C49.5535 41.9148 49.4658 42.2628 49.3614 42.633C49.1528 43.373 48.8811 44.1893 48.6516 44.8061L48.6505 44.8093C48.5871 44.9871 48.567 45.1775 48.5921 45.3647C48.6171 45.5518 48.6865 45.7303 48.7944 45.8852C48.9024 46.0401 49.0458 46.167 49.2126 46.2553C49.3795 46.3436 49.5651 46.3908 49.7539 46.3929V46.3929H49.7567H58.1809C58.4721 46.3929 58.6278 46.4589 58.7144 46.5454C58.801 46.632 58.867 46.7877 58.867 47.079C58.867 47.6268 58.7235 47.8419 58.6132 47.932C58.4949 48.0286 58.3465 48.0412 58.2043 48.0412H57.9543ZM40.1464 58.9993H33.5991L32.3736 48.2658H40.1458L40.1464 58.9993Z\" fill=\"#FF8484\" stroke=\"#FF8484\" stroke-width=\"0.5\"><\/path><mask id=\"path-2-outside-1_10027_82683\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0.210938\" width=\"30\" height=\"30\" fill=\"black\"><rect fill=\"white\" y=\"0.210938\" width=\"30\" height=\"30\"><\/rect><path d=\"M28.228 27.4218H27.2919V6.66464C27.8356 6.47084 28.3063 6.11424 28.6401 5.64335C28.9739 5.17247 29.1544 4.61019 29.1572 4.03301C29.1601 3.45584 28.985 2.89182 28.6558 2.4177C28.3267 1.94358 27.8594 1.5824 27.3177 1.38331C26.776 1.18421 26.186 1.15688 25.6282 1.30502C25.0704 1.45316 24.5718 1.76958 24.2002 2.21123C23.8286 2.65287 23.6021 3.19828 23.5515 3.77324C23.501 4.3482 23.6288 4.92478 23.9176 5.42451L20.0285 9.90902C19.4227 9.63129 18.7379 9.57813 18.0966 9.75906C17.4552 9.93999 16.8991 10.3432 16.5278 10.8965L14.1879 10.3069C14.1441 9.89479 14.0095 9.49745 13.794 9.14343C13.5784 8.78941 13.2872 8.4875 12.9411 8.25936C12.5951 8.03121 12.2029 7.88249 11.7926 7.82387C11.3822 7.76525 10.9641 7.79818 10.568 7.9203C10.1719 8.04242 9.80777 8.2507 9.50171 8.53019C9.19565 8.80969 8.95524 9.15346 8.79775 9.53686C8.64025 9.92025 8.56957 10.3338 8.59077 10.7477C8.61198 11.1616 8.72455 11.5658 8.9204 11.931L4.94692 16.401C4.59812 16.2462 4.22144 16.1642 3.83989 16.1599C3.45834 16.1556 3.07991 16.2291 2.72771 16.376C2.37551 16.5228 2.05693 16.7399 1.79141 17.0139C1.52589 17.288 1.319 17.6133 1.18338 17.9699C1.04775 18.3266 0.986234 18.7072 1.00258 19.0884C1.01892 19.4696 1.11278 19.8436 1.27844 20.1873C1.44409 20.5311 1.67805 20.8375 1.96605 21.0878C2.25405 21.3381 2.59005 21.5271 2.95352 21.6432V27.4231H2.01933C1.77106 27.4231 1.53296 27.5217 1.35741 27.6973C1.18186 27.8728 1.08323 28.1109 1.08323 28.3592C1.08323 28.6075 1.18186 28.8456 1.35741 29.0211C1.53296 29.1967 1.77106 29.2953 2.01933 29.2953H28.2299C28.4782 29.2953 28.7163 29.1967 28.8918 29.0211C29.0674 28.8456 29.166 28.6075 29.166 28.3592C29.166 28.1109 29.0674 27.8728 28.8918 27.6973C28.7163 27.5217 28.4782 27.4231 28.2299 27.4231L28.228 27.4218ZM12.3151 13.2169C12.8895 13.0137 13.3822 12.6292 13.7189 12.1214L16.0588 12.711C16.1112 13.2448 16.3154 13.7524 16.6472 14.1739C16.9789 14.5953 17.4244 14.9129 17.931 15.0891V27.4218H12.3151V13.2169ZM19.8038 15.0891C20.1775 14.9559 20.5188 14.745 20.805 14.4703C21.0913 14.1957 21.3162 13.8634 21.4648 13.4956C21.6133 13.1277 21.6823 12.7325 21.6671 12.3361C21.6518 11.9396 21.5528 11.5509 21.3765 11.1955L25.3315 6.63227L25.4204 6.66464V27.4218H19.8038V15.0891ZM26.3539 3.08389C26.5391 3.08389 26.7201 3.13879 26.874 3.24165C27.0279 3.34451 27.1479 3.49072 27.2188 3.66177C27.2896 3.83283 27.3082 4.02105 27.272 4.20264C27.2359 4.38423 27.1468 4.55103 27.0158 4.68195C26.8849 4.81287 26.7181 4.90203 26.5366 4.93815C26.355 4.97427 26.1668 4.95573 25.9957 4.88488C25.8247 4.81402 25.6785 4.69404 25.5756 4.54009C25.4727 4.38615 25.4178 4.20516 25.4178 4.02001C25.4178 3.89705 25.4419 3.77529 25.4889 3.66167C25.5359 3.54806 25.6049 3.44483 25.6918 3.35789C25.7788 3.27094 25.882 3.20199 25.9956 3.15498C26.1092 3.10796 26.231 3.0838 26.3539 3.08389ZM18.8652 11.5084C19.0503 11.5079 19.2314 11.5623 19.3856 11.6647C19.5398 11.7671 19.6602 11.9129 19.7315 12.0838C19.8029 12.2546 19.8219 12.4427 19.7864 12.6244C19.7508 12.8061 19.6621 12.9731 19.5317 13.1044C19.4012 13.2357 19.2347 13.3254 19.0532 13.362C18.8718 13.3987 18.6835 13.3808 18.5123 13.3105C18.341 13.2402 18.1945 13.1207 18.0911 12.9671C17.9878 12.8136 17.9323 12.6328 17.9316 12.4477C17.9311 12.3246 17.9549 12.2027 18.0016 12.0889C18.0482 11.9751 18.1169 11.8716 18.2036 11.7844C18.2903 11.6971 18.3934 11.6278 18.5069 11.5805C18.6204 11.5331 18.7422 11.5086 18.8652 11.5084ZM11.3764 9.63611C11.5616 9.63611 11.7426 9.69102 11.8965 9.79388C12.0505 9.89674 12.1704 10.0429 12.2413 10.214C12.3121 10.3851 12.3307 10.5733 12.2946 10.7549C12.2584 10.9365 12.1693 11.1033 12.0384 11.2342C11.9074 11.3651 11.7407 11.4543 11.5591 11.4904C11.3775 11.5265 11.1893 11.508 11.0182 11.4371C10.8472 11.3662 10.701 11.2463 10.5981 11.0923C10.4953 10.9384 10.4404 10.7574 10.4404 10.5722C10.4404 10.4493 10.4646 10.3276 10.5116 10.2141C10.5587 10.1006 10.6276 9.9974 10.7146 9.91052C10.8015 9.82365 10.9047 9.75475 11.0183 9.70778C11.1318 9.6608 11.2535 9.63603 11.3764 9.63611ZM3.88771 18.0606C4.07296 18.06 4.25422 18.1143 4.40857 18.2168C4.56291 18.3192 4.68338 18.4652 4.75474 18.6361C4.8261 18.8071 4.84512 18.9954 4.80941 19.1772C4.77371 19.3589 4.68487 19.526 4.55414 19.6573C4.42342 19.7886 4.25669 19.8781 4.07506 19.9145C3.89343 19.951 3.70507 19.9327 3.53383 19.8621C3.36258 19.7914 3.21616 19.6715 3.11308 19.5176C3.01 19.3637 2.95491 19.1826 2.95479 18.9973C2.9547 18.8744 2.97886 18.7526 3.02587 18.639C3.07289 18.5254 3.14184 18.4222 3.22878 18.3352C3.31572 18.2483 3.41894 18.1793 3.53255 18.1323C3.64616 18.0853 3.76793 18.0611 3.89088 18.0612L3.88771 18.0606ZM4.8238 21.6413C5.20784 21.5055 5.55773 21.2877 5.84918 21.0031C6.14062 20.7185 6.36665 20.3739 6.51156 19.9931C6.65648 19.6124 6.71682 19.2047 6.68839 18.7983C6.65996 18.392 6.54345 17.9966 6.34693 17.6398L10.3204 13.1699L10.4423 13.2169V27.4218H4.82697L4.8238 21.6413Z\"><\/path><\/mask><path d=\"M28.228 27.4218H27.2919V6.66464C27.8356 6.47084 28.3063 6.11424 28.6401 5.64335C28.9739 5.17247 29.1544 4.61019 29.1572 4.03301C29.1601 3.45584 28.985 2.89182 28.6558 2.4177C28.3267 1.94358 27.8594 1.5824 27.3177 1.38331C26.776 1.18421 26.186 1.15688 25.6282 1.30502C25.0704 1.45316 24.5718 1.76958 24.2002 2.21123C23.8286 2.65287 23.6021 3.19828 23.5515 3.77324C23.501 4.3482 23.6288 4.92478 23.9176 5.42451L20.0285 9.90902C19.4227 9.63129 18.7379 9.57813 18.0966 9.75906C17.4552 9.93999 16.8991 10.3432 16.5278 10.8965L14.1879 10.3069C14.1441 9.89479 14.0095 9.49745 13.794 9.14343C13.5784 8.78941 13.2872 8.4875 12.9411 8.25936C12.5951 8.03121 12.2029 7.88249 11.7926 7.82387C11.3822 7.76525 10.9641 7.79818 10.568 7.9203C10.1719 8.04242 9.80777 8.2507 9.50171 8.53019C9.19565 8.80969 8.95524 9.15346 8.79775 9.53686C8.64025 9.92025 8.56957 10.3338 8.59077 10.7477C8.61198 11.1616 8.72455 11.5658 8.9204 11.931L4.94692 16.401C4.59812 16.2462 4.22144 16.1642 3.83989 16.1599C3.45834 16.1556 3.07991 16.2291 2.72771 16.376C2.37551 16.5228 2.05693 16.7399 1.79141 17.0139C1.52589 17.288 1.319 17.6133 1.18338 17.9699C1.04775 18.3266 0.986234 18.7072 1.00258 19.0884C1.01892 19.4696 1.11278 19.8436 1.27844 20.1873C1.44409 20.5311 1.67805 20.8375 1.96605 21.0878C2.25405 21.3381 2.59005 21.5271 2.95352 21.6432V27.4231H2.01933C1.77106 27.4231 1.53296 27.5217 1.35741 27.6973C1.18186 27.8728 1.08323 28.1109 1.08323 28.3592C1.08323 28.6075 1.18186 28.8456 1.35741 29.0211C1.53296 29.1967 1.77106 29.2953 2.01933 29.2953H28.2299C28.4782 29.2953 28.7163 29.1967 28.8918 29.0211C29.0674 28.8456 29.166 28.6075 29.166 28.3592C29.166 28.1109 29.0674 27.8728 28.8918 27.6973C28.7163 27.5217 28.4782 27.4231 28.2299 27.4231L28.228 27.4218ZM12.3151 13.2169C12.8895 13.0137 13.3822 12.6292 13.7189 12.1214L16.0588 12.711C16.1112 13.2448 16.3154 13.7524 16.6472 14.1739C16.9789 14.5953 17.4244 14.9129 17.931 15.0891V27.4218H12.3151V13.2169ZM19.8038 15.0891C20.1775 14.9559 20.5188 14.745 20.805 14.4703C21.0913 14.1957 21.3162 13.8634 21.4648 13.4956C21.6133 13.1277 21.6823 12.7325 21.6671 12.3361C21.6518 11.9396 21.5528 11.5509 21.3765 11.1955L25.3315 6.63227L25.4204 6.66464V27.4218H19.8038V15.0891ZM26.3539 3.08389C26.5391 3.08389 26.7201 3.13879 26.874 3.24165C27.0279 3.34451 27.1479 3.49072 27.2188 3.66177C27.2896 3.83283 27.3082 4.02105 27.272 4.20264C27.2359 4.38423 27.1468 4.55103 27.0158 4.68195C26.8849 4.81287 26.7181 4.90203 26.5366 4.93815C26.355 4.97427 26.1668 4.95573 25.9957 4.88488C25.8247 4.81402 25.6785 4.69404 25.5756 4.54009C25.4727 4.38615 25.4178 4.20516 25.4178 4.02001C25.4178 3.89705 25.4419 3.77529 25.4889 3.66167C25.5359 3.54806 25.6049 3.44483 25.6918 3.35789C25.7788 3.27094 25.882 3.20199 25.9956 3.15498C26.1092 3.10796 26.231 3.0838 26.3539 3.08389ZM18.8652 11.5084C19.0503 11.5079 19.2314 11.5623 19.3856 11.6647C19.5398 11.7671 19.6602 11.9129 19.7315 12.0838C19.8029 12.2546 19.8219 12.4427 19.7864 12.6244C19.7508 12.8061 19.6621 12.9731 19.5317 13.1044C19.4012 13.2357 19.2347 13.3254 19.0532 13.362C18.8718 13.3987 18.6835 13.3808 18.5123 13.3105C18.341 13.2402 18.1945 13.1207 18.0911 12.9671C17.9878 12.8136 17.9323 12.6328 17.9316 12.4477C17.9311 12.3246 17.9549 12.2027 18.0016 12.0889C18.0482 11.9751 18.1169 11.8716 18.2036 11.7844C18.2903 11.6971 18.3934 11.6278 18.5069 11.5805C18.6204 11.5331 18.7422 11.5086 18.8652 11.5084ZM11.3764 9.63611C11.5616 9.63611 11.7426 9.69102 11.8965 9.79388C12.0505 9.89674 12.1704 10.0429 12.2413 10.214C12.3121 10.3851 12.3307 10.5733 12.2946 10.7549C12.2584 10.9365 12.1693 11.1033 12.0384 11.2342C11.9074 11.3651 11.7407 11.4543 11.5591 11.4904C11.3775 11.5265 11.1893 11.508 11.0182 11.4371C10.8472 11.3662 10.701 11.2463 10.5981 11.0923C10.4953 10.9384 10.4404 10.7574 10.4404 10.5722C10.4404 10.4493 10.4646 10.3276 10.5116 10.2141C10.5587 10.1006 10.6276 9.9974 10.7146 9.91052C10.8015 9.82365 10.9047 9.75475 11.0183 9.70778C11.1318 9.6608 11.2535 9.63603 11.3764 9.63611ZM3.88771 18.0606C4.07296 18.06 4.25422 18.1143 4.40857 18.2168C4.56291 18.3192 4.68338 18.4652 4.75474 18.6361C4.8261 18.8071 4.84512 18.9954 4.80941 19.1772C4.77371 19.3589 4.68487 19.526 4.55414 19.6573C4.42342 19.7886 4.25669 19.8781 4.07506 19.9145C3.89343 19.951 3.70507 19.9327 3.53383 19.8621C3.36258 19.7914 3.21616 19.6715 3.11308 19.5176C3.01 19.3637 2.95491 19.1826 2.95479 18.9973C2.9547 18.8744 2.97886 18.7526 3.02587 18.639C3.07289 18.5254 3.14184 18.4222 3.22878 18.3352C3.31572 18.2483 3.41894 18.1793 3.53255 18.1323C3.64616 18.0853 3.76793 18.0611 3.89088 18.0612L3.88771 18.0606ZM4.8238 21.6413C5.20784 21.5055 5.55773 21.2877 5.84918 21.0031C6.14062 20.7185 6.36665 20.3739 6.51156 19.9931C6.65648 19.6124 6.71682 19.2047 6.68839 18.7983C6.65996 18.392 6.54345 17.9966 6.34693 17.6398L10.3204 13.1699L10.4423 13.2169V27.4218H4.82697L4.8238 21.6413Z\" fill=\"#FF8484\"><\/path><path d=\"M28.228 27.4218H27.2919V6.66464C27.8356 6.47084 28.3063 6.11424 28.6401 5.64335C28.9739 5.17247 29.1544 4.61019 29.1572 4.03301C29.1601 3.45584 28.985 2.89182 28.6558 2.4177C28.3267 1.94358 27.8594 1.5824 27.3177 1.38331C26.776 1.18421 26.186 1.15688 25.6282 1.30502C25.0704 1.45316 24.5718 1.76958 24.2002 2.21123C23.8286 2.65287 23.6021 3.19828 23.5515 3.77324C23.501 4.3482 23.6288 4.92478 23.9176 5.42451L20.0285 9.90902C19.4227 9.63129 18.7379 9.57813 18.0966 9.75906C17.4552 9.93999 16.8991 10.3432 16.5278 10.8965L14.1879 10.3069C14.1441 9.89479 14.0095 9.49745 13.794 9.14343C13.5784 8.78941 13.2872 8.4875 12.9411 8.25936C12.5951 8.03121 12.2029 7.88249 11.7926 7.82387C11.3822 7.76525 10.9641 7.79818 10.568 7.9203C10.1719 8.04242 9.80777 8.2507 9.50171 8.53019C9.19565 8.80969 8.95524 9.15346 8.79775 9.53686C8.64025 9.92025 8.56957 10.3338 8.59077 10.7477C8.61198 11.1616 8.72455 11.5658 8.9204 11.931L4.94692 16.401C4.59812 16.2462 4.22144 16.1642 3.83989 16.1599C3.45834 16.1556 3.07991 16.2291 2.72771 16.376C2.37551 16.5228 2.05693 16.7399 1.79141 17.0139C1.52589 17.288 1.319 17.6133 1.18338 17.9699C1.04775 18.3266 0.986234 18.7072 1.00258 19.0884C1.01892 19.4696 1.11278 19.8436 1.27844 20.1873C1.44409 20.5311 1.67805 20.8375 1.96605 21.0878C2.25405 21.3381 2.59005 21.5271 2.95352 21.6432V27.4231H2.01933C1.77106 27.4231 1.53296 27.5217 1.35741 27.6973C1.18186 27.8728 1.08323 28.1109 1.08323 28.3592C1.08323 28.6075 1.18186 28.8456 1.35741 29.0211C1.53296 29.1967 1.77106 29.2953 2.01933 29.2953H28.2299C28.4782 29.2953 28.7163 29.1967 28.8918 29.0211C29.0674 28.8456 29.166 28.6075 29.166 28.3592C29.166 28.1109 29.0674 27.8728 28.8918 27.6973C28.7163 27.5217 28.4782 27.4231 28.2299 27.4231L28.228 27.4218ZM12.3151 13.2169C12.8895 13.0137 13.3822 12.6292 13.7189 12.1214L16.0588 12.711C16.1112 13.2448 16.3154 13.7524 16.6472 14.1739C16.9789 14.5953 17.4244 14.9129 17.931 15.0891V27.4218H12.3151V13.2169ZM19.8038 15.0891C20.1775 14.9559 20.5188 14.745 20.805 14.4703C21.0913 14.1957 21.3162 13.8634 21.4648 13.4956C21.6133 13.1277 21.6823 12.7325 21.6671 12.3361C21.6518 11.9396 21.5528 11.5509 21.3765 11.1955L25.3315 6.63227L25.4204 6.66464V27.4218H19.8038V15.0891ZM26.3539 3.08389C26.5391 3.08389 26.7201 3.13879 26.874 3.24165C27.0279 3.34451 27.1479 3.49072 27.2188 3.66177C27.2896 3.83283 27.3082 4.02105 27.272 4.20264C27.2359 4.38423 27.1468 4.55103 27.0158 4.68195C26.8849 4.81287 26.7181 4.90203 26.5366 4.93815C26.355 4.97427 26.1668 4.95573 25.9957 4.88488C25.8247 4.81402 25.6785 4.69404 25.5756 4.54009C25.4727 4.38615 25.4178 4.20516 25.4178 4.02001C25.4178 3.89705 25.4419 3.77529 25.4889 3.66167C25.5359 3.54806 25.6049 3.44483 25.6918 3.35789C25.7788 3.27094 25.882 3.20199 25.9956 3.15498C26.1092 3.10796 26.231 3.0838 26.3539 3.08389ZM18.8652 11.5084C19.0503 11.5079 19.2314 11.5623 19.3856 11.6647C19.5398 11.7671 19.6602 11.9129 19.7315 12.0838C19.8029 12.2546 19.8219 12.4427 19.7864 12.6244C19.7508 12.8061 19.6621 12.9731 19.5317 13.1044C19.4012 13.2357 19.2347 13.3254 19.0532 13.362C18.8718 13.3987 18.6835 13.3808 18.5123 13.3105C18.341 13.2402 18.1945 13.1207 18.0911 12.9671C17.9878 12.8136 17.9323 12.6328 17.9316 12.4477C17.9311 12.3246 17.9549 12.2027 18.0016 12.0889C18.0482 11.9751 18.1169 11.8716 18.2036 11.7844C18.2903 11.6971 18.3934 11.6278 18.5069 11.5805C18.6204 11.5331 18.7422 11.5086 18.8652 11.5084ZM11.3764 9.63611C11.5616 9.63611 11.7426 9.69102 11.8965 9.79388C12.0505 9.89674 12.1704 10.0429 12.2413 10.214C12.3121 10.3851 12.3307 10.5733 12.2946 10.7549C12.2584 10.9365 12.1693 11.1033 12.0384 11.2342C11.9074 11.3651 11.7407 11.4543 11.5591 11.4904C11.3775 11.5265 11.1893 11.508 11.0182 11.4371C10.8472 11.3662 10.701 11.2463 10.5981 11.0923C10.4953 10.9384 10.4404 10.7574 10.4404 10.5722C10.4404 10.4493 10.4646 10.3276 10.5116 10.2141C10.5587 10.1006 10.6276 9.9974 10.7146 9.91052C10.8015 9.82365 10.9047 9.75475 11.0183 9.70778C11.1318 9.6608 11.2535 9.63603 11.3764 9.63611ZM3.88771 18.0606C4.07296 18.06 4.25422 18.1143 4.40857 18.2168C4.56291 18.3192 4.68338 18.4652 4.75474 18.6361C4.8261 18.8071 4.84512 18.9954 4.80941 19.1772C4.77371 19.3589 4.68487 19.526 4.55414 19.6573C4.42342 19.7886 4.25669 19.8781 4.07506 19.9145C3.89343 19.951 3.70507 19.9327 3.53383 19.8621C3.36258 19.7914 3.21616 19.6715 3.11308 19.5176C3.01 19.3637 2.95491 19.1826 2.95479 18.9973C2.9547 18.8744 2.97886 18.7526 3.02587 18.639C3.07289 18.5254 3.14184 18.4222 3.22878 18.3352C3.31572 18.2483 3.41894 18.1793 3.53255 18.1323C3.64616 18.0853 3.76793 18.0611 3.89088 18.0612L3.88771 18.0606ZM4.8238 21.6413C5.20784 21.5055 5.55773 21.2877 5.84918 21.0031C6.14062 20.7185 6.36665 20.3739 6.51156 19.9931C6.65648 19.6124 6.71682 19.2047 6.68839 18.7983C6.65996 18.392 6.54345 17.9966 6.34693 17.6398L10.3204 13.1699L10.4423 13.2169V27.4218H4.82697L4.8238 21.6413Z\" stroke=\"#FF8484\" mask=\"url(#path-2-outside-1_10027_82683)\"><\/path><path d=\"M12.8501 45.5278C15.7273 49.1654 19.6221 51.8568 24.0313 53.2639L17.3925 56.5553L17.3924 56.5551L17.3842 56.5596C17.1143 56.7062 16.9119 56.9518 16.8194 57.2446C16.7269 57.5374 16.7516 57.8547 16.8882 58.1297C17.0249 58.4047 17.2629 58.616 17.5521 58.7191C17.8414 58.8222 18.1594 58.8091 18.4392 58.6826L18.4393 58.6827L18.4472 58.6788L27.9517 53.9683H27.9936L28.0573 53.925L28.1492 53.8625L28.1506 53.8616L28.205 53.8251L28.2221 53.8136L28.237 53.7996L28.3214 53.7203L28.3215 53.7203L28.327 53.7148L28.3689 53.6729L28.3759 53.6659L28.3824 53.6583C28.4297 53.6028 28.4716 53.543 28.5077 53.4796L28.5405 53.4221V53.396C28.5575 53.3624 28.5729 53.328 28.5867 53.293L28.6039 53.249V53.2017V53.0544C28.6049 53.0383 28.6054 53.0221 28.6057 53.0059C28.614 52.9924 28.6232 52.976 28.6314 52.9582C28.6376 52.9448 28.6467 52.9234 28.653 52.8971C28.6573 52.8791 28.6663 52.8363 28.6566 52.7834V52.7832V52.783V52.7829V52.7827V52.7825V52.7823V52.7821V52.7819V52.7818V52.7816V52.7814V52.7812V52.781V52.7808V52.7807V52.7805V52.7803V52.7801V52.7799V52.7797V52.7796V52.7794V52.7792V52.779V52.7788V52.7786V52.7784V52.7783V52.7781V52.7779V52.7777V52.7775V52.7773V52.7772V52.777V52.7768V52.7766V52.7764V52.7762V52.7761V52.7759V52.7757V52.7755V52.7753V52.7751V52.775V52.7748V52.7746V52.7744V52.7742V52.774V52.7739V52.7737V52.7735V52.7733V52.7731V52.7729V52.7728V52.7726V52.7724V52.7722V52.772V52.7718V52.7717V52.7715V52.7713V52.7711V52.7709V52.7708V52.7706V52.7704V52.7702V52.77V52.7698V52.7697V52.7695V52.7693V52.7691V52.7689V52.7687V52.7686V52.7684V52.7682V52.768V52.7678V52.7676V52.7675V52.7673V52.7671V52.7669V52.7667V52.7666V52.7664V52.7662V52.766V52.7658V52.7656V52.7655V52.7653V52.7651V52.7649V52.7647V52.7646V52.7644V52.7642V52.764V52.7638V52.7636V52.7635V52.7633V52.7631V52.7629V52.7627V52.7626V52.7624V52.7622V52.762V52.7618V52.7616V52.7615V52.7613V52.7611V52.7609V52.7607V52.7606V52.7604V52.7602V52.76V52.7598V52.7597V52.7595V52.7593V52.7591V52.7589V52.7588V52.7586V52.7584V52.7582V52.758V52.7578V52.7577V52.7575V52.7573V52.7571V52.7569V52.7568V52.7566V52.7564V52.7562V52.756V52.7559V52.7557V52.7555V52.7553V52.7551V52.755V52.7548V52.7546V52.7544V52.7542V52.7541V52.7539V52.7537V52.7535V52.7533V52.7532V52.753V52.7528V52.7526V52.7525V52.7523V52.7521V52.7519V52.7517V52.7516V52.7514V52.7512V52.751V52.7508V52.7507V52.7505V52.7503V52.7501V52.7499V52.7498V52.7496V52.7494V52.7492V52.7491V52.7489V52.7487V52.7485V52.7483V52.7482V52.748V52.7478V52.7476V52.7474V52.7473V52.7471V52.7469V52.7467V52.7466V52.7464V52.7462V52.746V52.7458V52.7457V52.7455V52.7453V52.7451V52.745V52.7448V52.7446V52.7444V52.7442V52.7441V52.7439V52.7437V52.7435V52.7434V52.7432V52.743V52.7428V52.7427V52.7425V52.7423V52.7421V52.742V52.7418V52.7416V52.7414V52.7412V52.7411V52.7409V52.7407V52.7405V52.7404V52.7402V52.74V52.7398V52.7397V52.7395V52.7393V52.7391V52.739V52.7388V52.7386V52.7384V52.7383V52.7381V52.7379V52.7377V52.7376V52.7374V52.7372V52.737V52.7369V52.7367V52.7365V52.6603C28.6599 52.6166 28.6545 52.5724 28.6406 52.5305C28.6326 52.5066 28.622 52.4838 28.6089 52.4625C28.5988 52.4328 28.5875 52.4034 28.5749 52.3745L28.5752 52.3744L28.5694 52.3629L23.8001 42.796L23.8002 42.7959L23.796 42.7882C23.6495 42.5183 23.4039 42.3159 23.1111 42.2234C22.8183 42.1309 22.501 42.1556 22.226 42.2922C21.951 42.4289 21.7397 42.6669 21.6366 42.9562C21.5335 43.2454 21.5466 43.5634 21.6731 43.8432L21.673 43.8433L21.6769 43.8513L25.3094 51.177C21.2189 49.9968 17.5815 47.5937 14.8894 44.284C12.0808 40.8309 10.4478 36.5713 10.2283 32.1256C10.2213 31.9701 10.1837 31.8174 10.1178 31.6764C10.0517 31.5352 9.95854 31.4084 9.8435 31.3032C9.72846 31.198 9.59383 31.1165 9.44728 31.0633C9.30073 31.0102 9.14515 30.9864 8.98943 30.9934C8.8337 31.0003 8.68087 31.0379 8.53967 31.104C8.39846 31.17 8.27164 31.2632 8.16646 31.3782C8.06127 31.4933 7.97977 31.6279 7.92662 31.7745C7.87346 31.921 7.84969 32.0766 7.85666 32.2323L7.85665 32.2323L7.85671 32.2335C8.09609 37.0768 9.84179 41.7246 12.8501 45.5278Z\" fill=\"#FF8484\" stroke=\"#FF8484\" stroke-width=\"0.5\"><\/path><path d=\"M53.9004 34.9123L53.9004 34.9122C54.8089 29.3082 53.6323 23.5655 50.5931 18.7704C47.6675 14.1545 43.2113 10.7247 38.0158 9.07424L44.6766 5.78057C44.8201 5.71497 44.9492 5.62136 45.0561 5.50522C45.1641 5.38795 45.2473 5.25012 45.3008 5.09999C45.3544 4.94985 45.3771 4.79046 45.3676 4.63132L45.118 4.64617L45.3676 4.63132C45.3581 4.4722 45.3167 4.31662 45.2458 4.17388C45.1748 4.03112 45.0758 3.90414 44.9547 3.80051C44.8336 3.69688 44.6929 3.61872 44.5409 3.57071C44.3889 3.5227 44.2287 3.50581 44.0701 3.52107C43.9131 3.53617 43.7607 3.58242 43.6218 3.65711L34.0688 8.38652L34.0688 8.38653C33.9007 8.46975 33.7548 8.59164 33.6429 8.74219C33.5311 8.89274 33.4566 9.06766 33.4254 9.2526L33.422 9.2732V9.2941V9.30224C33.3894 9.58243 33.4579 9.86505 33.6151 10.0992L38.2879 19.5003L38.2878 19.5003L38.2916 19.5074C38.4375 19.7787 38.6832 19.9825 38.9767 20.0758C39.2702 20.1692 39.5885 20.1447 39.8643 20.0075C40.1401 19.8703 40.3517 19.6313 40.4544 19.3409C40.557 19.0506 40.5427 18.7316 40.4145 18.4516L40.4146 18.4515L40.4108 18.4439L36.7806 11.1797C41.5808 12.5598 45.7315 15.6231 48.4652 19.8181C51.3002 24.1686 52.4063 29.4218 51.5664 34.5461C51.5162 34.8515 51.5872 35.1644 51.7645 35.4181C51.9418 35.6719 52.2112 35.8463 52.5154 35.9041L52.5385 35.9085H52.562H52.5627H52.7157C52.9995 35.9117 53.275 35.8131 53.4923 35.6305C53.71 35.4477 53.8547 35.1928 53.9004 34.9123Z\" fill=\"#FF8484\" stroke=\"#FF8484\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tThird-party data protection\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEventBookings follows strict privacy guidelines and never shares any data with third-party websites or social media platforms for advertising.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f89aca5 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f89aca5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f9f26ee\" data-id=\"5f9f26ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56d411fe SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"56d411fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">The future of online ticketing is here<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e7695b elementor-mobile-align-center elementor-align-center new-fix-url elementor-widget elementor-widget-button\" data-id=\"17e7695b\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Leaders in the Event Space are Making the Switch! Discover why EventBookings is becoming the top choice for event organisers. While many platforms devour up to 15% in ticketing fees, EventBookings ensures you retain more of your hard-earned money. Create Event Free Forever. No Credit Card Required. Excellent 4.7\/5 Create Event Free Forever. No Credit [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-107389","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alternative to Humanitix | Sell More Tickets | EventBookings<\/title>\n<meta name=\"description\" content=\"Need a better event ticketing system than Humanitix? Switch to EventBookings and sell more tickets online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eventbookings.com\/en-it\/alternative-to-humanitix\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alternative to Humanitix | Sell More Tickets | EventBookings\" \/>\n<meta property=\"og:description\" content=\"Need a better event ticketing system than Humanitix? Switch to EventBookings and sell more tickets online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eventbookings.com\/en-it\/alternative-to-humanitix\/\" \/>\n<meta property=\"og:site_name\" content=\"EventBookings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eEventBookings\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-08T10:40:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eEventBookings\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/\",\"url\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/\",\"name\":\"Alternative to Humanitix | Sell More Tickets | EventBookings\",\"isPartOf\":{\"@id\":\"https:\/\/www.eventbookings.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\",\"datePublished\":\"2023-02-14T14:05:03+00:00\",\"dateModified\":\"2026-03-08T10:40:29+00:00\",\"description\":\"Need a better event ticketing system than Humanitix? Switch to EventBookings and sell more tickets online.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#primaryimage\",\"url\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\",\"contentUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eventbookings.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EventBookings vs Humanitix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eventbookings.com\/#website\",\"url\":\"https:\/\/www.eventbookings.com\/\",\"name\":\"EventBookings\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eventbookings.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eventbookings.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eventbookings.com\/#organization\",\"name\":\"EventBookings\",\"url\":\"https:\/\/www.eventbookings.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\",\"contentUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\",\"width\":1200,\"height\":674,\"caption\":\"EventBookings\"},\"image\":{\"@id\":\"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eEventBookings\",\"https:\/\/x.com\/eEventBookings\",\"https:\/\/www.linkedin.com\/company\/eeventbookings\/\",\"https:\/\/www.instagram.com\/eeventbookings\/\",\"https:\/\/www.youtube.com\/channel\/UCrN_RsacOWc9V3JU_Q3-tJA\",\"https:\/\/www.tiktok.com\/@eventbookings\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alternative to Humanitix | Sell More Tickets | EventBookings","description":"Need a better event ticketing system than Humanitix? Switch to EventBookings and sell more tickets online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eventbookings.com\/en-it\/alternative-to-humanitix\/","og_locale":"it_IT","og_type":"article","og_title":"Alternative to Humanitix | Sell More Tickets | EventBookings","og_description":"Need a better event ticketing system than Humanitix? Switch to EventBookings and sell more tickets online.","og_url":"https:\/\/www.eventbookings.com\/en-it\/alternative-to-humanitix\/","og_site_name":"EventBookings","article_publisher":"https:\/\/www.facebook.com\/eEventBookings","article_modified_time":"2026-03-08T10:40:29+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@eEventBookings","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/","url":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/","name":"Alternative to Humanitix | Sell More Tickets | EventBookings","isPartOf":{"@id":"https:\/\/www.eventbookings.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#primaryimage"},"image":{"@id":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg","datePublished":"2023-02-14T14:05:03+00:00","dateModified":"2026-03-08T10:40:29+00:00","description":"Need a better event ticketing system than Humanitix? Switch to EventBookings and sell more tickets online.","breadcrumb":{"@id":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eventbookings.com\/alternative-to-humanitix\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#primaryimage","url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg","contentUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/09\/recaptcha-logo.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eventbookings.com\/alternative-to-humanitix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eventbookings.com\/"},{"@type":"ListItem","position":2,"name":"EventBookings vs Humanitix"}]},{"@type":"WebSite","@id":"https:\/\/www.eventbookings.com\/#website","url":"https:\/\/www.eventbookings.com\/","name":"EventBookings","description":"","publisher":{"@id":"https:\/\/www.eventbookings.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eventbookings.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.eventbookings.com\/#organization","name":"EventBookings","url":"https:\/\/www.eventbookings.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","contentUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","width":1200,"height":674,"caption":"EventBookings"},"image":{"@id":"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eEventBookings","https:\/\/x.com\/eEventBookings","https:\/\/www.linkedin.com\/company\/eeventbookings\/","https:\/\/www.instagram.com\/eeventbookings\/","https:\/\/www.youtube.com\/channel\/UCrN_RsacOWc9V3JU_Q3-tJA","https:\/\/www.tiktok.com\/@eventbookings"]}]}},"_links":{"self":[{"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/pages\/107389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/comments?post=107389"}],"version-history":[{"count":251,"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/pages\/107389\/revisions"}],"predecessor-version":[{"id":223156,"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/pages\/107389\/revisions\/223156"}],"wp:attachment":[{"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/media?parent=107389"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-it\/wp-json\/wp\/v2\/tags?post=107389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}