{"id":106861,"date":"2023-02-14T23:20:12","date_gmt":"2023-02-14T12:20:12","guid":{"rendered":"https:\/\/www.eventbookings.com\/?page_id=106861"},"modified":"2026-03-09T15:28:09","modified_gmt":"2026-03-09T04:28:09","slug":"councils","status":"publish","type":"page","link":"https:\/\/www.eventbookings.com\/en-cy\/industry\/councils\/","title":{"rendered":"Councils"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"106861\" class=\"elementor elementor-106861\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20e41f90 laptop-container  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20e41f90\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44576650\" data-id=\"44576650\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59934e89 br-none SharpSans ticketing udergreen-curve elementor-widget elementor-widget-heading\" data-id=\"59934e89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">The powerful <br>\nticketing tool for<br> local councils<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6082fb60 SharpSans  elementor-widget elementor-widget-heading\" data-id=\"6082fb60\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Get advanced reporting and great ticketing flexibility with EventBookings.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61baeff elementor-mobile-align-center elementor-align-left banner-btn new-fix-url elementor-tablet-align-left elementor-hidden-mobile elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"61baeff\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa6ad3c capterra-section elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa6ad3c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e0f718\" data-id=\"8e0f718\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d30cb7e elementor-widget elementor-widget-image\" data-id=\"d30cb7e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"153\" height=\"35\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png\" class=\"attachment-large size-large wp-image-106165\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png 153w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2-150x35.png 150w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2-18x4.png 18w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f11eae captera-right-content-star\" data-id=\"2f11eae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e539983 SharpSans  elementor-widget elementor-widget-heading\" data-id=\"e539983\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Excellent 4.7\/5<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5105233 elementor-widget elementor-widget-image\" data-id=\"5105233\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"110\" height=\"16\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/star-review.png\" class=\"attachment-large size-large wp-image-106169\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/star-review.png 110w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/star-review-18x3.png 18w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6000546d\" data-id=\"6000546d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-561ec26e elementor-widget elementor-widget-image\" data-id=\"561ec26e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"781\" height=\"765\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Councils-1.png\" class=\"attachment-full size-full wp-image-108785\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Councils-1.png 781w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Councils-1-300x294.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Councils-1-768x752.png 768w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Councils-1-12x12.png 12w\" sizes=\"(max-width: 781px) 100vw, 781px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77952c66 elementor-mobile-align-center elementor-align-left elementor-tablet-align-center elementor-hidden-desktop new-fix-url elementor-widget elementor-widget-button\" data-id=\"77952c66\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c007d9c capterra-section captera-center elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c007d9c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66e92f3\" data-id=\"66e92f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb0c4a3 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-image\" data-id=\"bb0c4a3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"153\" height=\"35\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png\" class=\"attachment-large size-large wp-image-106165\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png 153w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2-150x35.png 150w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2-18x4.png 18w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d33048 captera-right-content-star\" data-id=\"9d33048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82a23d4 SharpSans  elementor-widget elementor-widget-heading\" data-id=\"82a23d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Excellent 4.7\/5<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0212163 elementor-widget elementor-widget-image\" data-id=\"0212163\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"110\" height=\"16\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/star-review.png\" class=\"attachment-large size-large wp-image-106169\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/star-review.png 110w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/star-review-18x3.png 18w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4af94f laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4af94f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5564c2\" data-id=\"c5564c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a01e5 elementor-widget elementor-widget-html\" data-id=\"39a01e5\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-39a01e5{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f6b5fe elementor-widget elementor-widget-html\" data-id=\"0f6b5fe\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-0f6b5fe{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-498c78f elementor-widget elementor-widget-html\" data-id=\"498c78f\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-498c78f{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c5d44b elementor-widget elementor-widget-html\" data-id=\"1c5d44b\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"client-logo-section\">\r\n                <h4 class=\"client-title\">Events created by thousands of organizations around the globe<\/h4>\r\n                <div class=\"client-logo-box\">\r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/Logos_APC-02.png\" width=\"176\" height=\"46\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                      <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/EDS-logo.png\" width=\"91\" height=\"37\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                   \r\n                   \r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/covey-theater-logo.png\" width=\"98\" height=\"98\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/vilamoura-logo1.png\" width=\"133\" height=\"77\" alt=\"Brand Logo\">\r\n                    <\/div>\r\n                     <div class=\"logo-item\">\r\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/08\/kendall-nicole-eich-foundation-1.png\" width=\"176\" height=\"58\" alt=\"Brand Logo\">\r\n                    <\/div> \r\n                <\/div>\r\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b14535c SharpSans  elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b14535c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00a2<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51507959 price-sec laptop-container elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"51507959\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba741bf left-sec\" data-id=\"ba741bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79041aaf SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"79041aaf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lowest fees in the industry for local councils<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a29876 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"72a29876\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Save More on Ticketing Fees<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f69d4c6 br-none elementor-widget elementor-widget-heading\" data-id=\"4f69d4c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Enjoy lower fees with our platform compared to other event ticketing providers.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46ddbf45 left-sec\" data-id=\"46ddbf45\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c5ef3d2 venu-online-section pricing-amount-section-res price-box elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c5ef3d2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3cf5eebe price-black-box\" data-id=\"3cf5eebe\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54ab53d9 price-amount  elementor-widget elementor-widget-heading\" data-id=\"54ab53d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">20<sup>\u00a2<\/sup><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-119ecbcf SharpSans  elementor-widget elementor-widget-heading\" data-id=\"119ecbcf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">+<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-617cddd9 price-percent elementor-widget elementor-widget-heading\" data-id=\"617cddd9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">1%<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4133000e elementor-widget elementor-widget-heading\" data-id=\"4133000e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Per ticket sold<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33ad8d6e openStripemodal elementor-widget elementor-widget-heading\" data-id=\"33ad8d6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Includes credit card processing fees<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae098ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae098ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d783c20\" data-id=\"7d783c20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-719da81b SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"719da81b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why choose EventBookings for<br>\nyour next council event?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6799de51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6799de51\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-28ebb4f\" data-id=\"28ebb4f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22f3e1a5 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"22f3e1a5\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-22f3e1a5{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99481f9 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"99481f9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"69\" height=\"70\" viewbox=\"0 0 69 70\" fill=\"none\"><g clip-path=\"url(#clip0_12292_94543)\"><path d=\"M34.9403 68.4106C17.6446 68.4368 3.60991 56.7725 0.571608 40.5399C-2.76136 22.7444 8.81346 5.24575 26.5282 1.27544C32.0704 0.0278461 37.8369 0.188675 43.301 1.74324C48.765 3.2978 53.7526 6.19654 57.808 10.1747C61.8635 14.1529 64.8576 19.0838 66.517 24.5169C68.1764 29.9501 68.4481 35.7124 67.3074 41.2776C67.0062 42.788 65.6813 43.755 64.2887 43.4952C62.7259 43.2049 61.8703 41.8582 62.1759 40.1972C63.8849 30.9513 61.7895 22.6702 55.6584 15.5328C42.9114 0.690476 18.9237 3.00194 9.16705 19.944C-0.377863 36.5324 8.27651 57.3531 26.7705 62.2489C31.6919 63.5557 36.875 63.5089 41.7721 62.1136C42.034 62.0416 42.2937 61.9521 42.5579 61.8953C44.0246 61.5679 45.3953 62.3319 45.7642 63.7026C46.1527 65.1235 45.3801 66.4877 43.9002 66.9395C40.7157 67.9173 37.4416 68.3954 34.9403 68.4106Z\" fill=\"#1AC8A4\"><\/path><path d=\"M36.6642 23.2101V31.823C39.7767 31.9103 42.4025 33.0169 44.3604 35.4746C45.8167 37.2711 46.5513 39.5457 46.4208 41.8546C46.2549 45.7682 43.3017 50.6902 36.6293 50.9848C36.6293 52.4429 36.6467 53.9053 36.6293 55.3677C36.6378 55.8629 36.4987 56.3495 36.2297 56.7654C35.9607 57.1813 35.574 57.5078 35.1188 57.7032C34.7034 57.9153 34.2358 58.0038 33.7715 57.9582C33.3072 57.9125 32.8658 57.7346 32.4996 57.4456C32.1494 57.2023 31.866 56.875 31.6753 56.4936C31.4846 56.1122 31.3928 55.689 31.4083 55.2629C31.4083 53.8507 31.4083 52.4385 31.4083 51.2009C29.8433 50.7513 28.2761 50.5265 26.9228 49.8673C23.5593 48.2434 21.8175 45.4059 21.6145 41.6757C21.525 40.0408 22.5836 38.8644 24.0701 38.7945C25.6198 38.7247 26.7439 39.816 26.8312 41.4749C26.9621 43.9784 28.9375 45.8119 31.3581 45.622V37.1117C28.1451 37.0309 25.4844 35.8239 23.5266 33.2483C22.1073 31.4201 21.4292 29.124 21.6276 26.8181C21.9616 22.3414 25.4582 18.0873 31.4039 17.8996C31.4039 16.4765 31.4039 15.0446 31.4039 13.615C31.3824 13.1632 31.4813 12.7138 31.6902 12.3127C31.8992 11.9116 32.2109 11.5732 32.5935 11.3319C32.9751 11.062 33.426 10.9071 33.8928 10.8854C34.3597 10.8638 34.823 10.9763 35.228 11.2097C35.6478 11.4147 36.0011 11.734 36.2475 12.131C36.4938 12.5279 36.6231 12.9863 36.6205 13.4535C36.6489 14.9181 36.6205 16.3848 36.6205 17.9018C38.5522 18 40.3311 18.4213 41.9136 19.469C44.7947 21.381 46.3139 24.0766 46.4143 27.5449C46.4328 27.8932 46.3809 28.2416 46.2616 28.5694C46.1424 28.8971 45.9583 29.1974 45.7202 29.4523C45.4822 29.7073 45.1952 29.9116 44.8765 30.053C44.5577 30.1944 44.2136 30.2701 43.8649 30.2755C42.4221 30.3126 41.2806 29.1841 41.1976 27.6562C41.0667 25.0392 39.2114 23.2014 36.6642 23.2101ZM31.345 31.775V23.2057C28.7126 23.1621 26.7198 25.1985 26.8355 27.7479C26.9425 30.127 29.0488 32.0129 31.345 31.775ZM36.6751 45.6853C38.3972 45.67 39.7309 45.0305 40.5887 43.5702C41.4967 42.0205 41.4377 40.4446 40.4337 38.9582C39.5606 37.6486 38.2706 37.0789 36.6751 37.0964V45.6853Z\" fill=\"#1AC8A4\"><\/path><path d=\"M56.1634 60.9037L56.1634 55.0105C56.1634 53.1857 56.1372 51.361 56.1634 49.5385C56.1939 47.9866 57.3289 46.8537 58.7673 46.8516C60.2057 46.8494 61.3647 47.9735 61.3647 49.5406C61.3996 52.9696 61.3778 56.3987 61.38 59.8298L61.38 60.9212C62.3644 60.0154 63.1632 59.2492 63.9992 58.5202C64.3947 58.1562 64.8939 57.9247 65.4273 57.8582C65.9607 57.7917 66.5015 57.8934 66.9742 58.1492C67.915 58.649 68.5196 59.6531 68.31 60.7226C68.1874 61.3566 67.8842 61.9417 67.437 62.4076C65.2237 64.5423 62.9537 66.618 60.6706 68.6916C59.4418 69.8113 58.095 69.82 56.8706 68.7068C54.5962 66.6347 52.3407 64.5459 50.1042 62.4403C48.9736 61.3817 48.8906 59.7884 49.8598 58.7123C50.8594 57.6013 52.4528 57.5511 53.6511 58.6141C54.4456 59.3104 55.2073 60.0307 56.1634 60.9037Z\" fill=\"#1AC8A4\"><\/path><\/g><defs><clippath id=\"clip0_12292_94543\"><rect width=\"69.0931\" height=\"68.9995\" fill=\"white\" transform=\"translate(69 0.445312) rotate(90)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLowest ticketing fees\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEventBookings offers the lowest ticketing fees in the market with no monthly charges, set-up costs, or lock-in contracts. You only pay when you sell tickets.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7fde0f4a\" data-id=\"7fde0f4a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dc7ab77 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5dc7ab77\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"59\" viewbox=\"0 0 59 59\" fill=\"none\"><path d=\"M48.4508 6.17901e-05C44.7711 0.00373595 41.3602 1.92753 39.4531 5.07496C37.5459 8.22294 37.4197 12.1375 39.1196 15.4018L15.4029 39.1255C12.4035 37.5603 8.83535 37.5316 5.81092 39.0483C2.78648 40.565 0.675094 43.4434 0.135164 46.784C-0.404784 50.1246 0.692003 53.5216 3.08475 55.9143C5.47673 58.3078 8.87278 59.4049 12.2124 58.8648C15.552 58.3247 18.4296 56.2127 19.9458 53.1874C21.462 50.162 21.4334 46.5928 19.8686 43.5925L43.5853 19.8688C46.4533 21.3701 49.8523 21.4686 52.8034 20.1363C55.7538 18.8033 57.9274 16.1865 58.6973 13.0414C59.468 9.89621 58.7487 6.57102 56.7484 4.02483C54.748 1.47938 51.6884 -0.00506623 48.4509 1.2992e-05L48.4508 6.17901e-05ZM10.5372 52.6735C9.41985 52.6735 8.34872 52.2296 7.55829 51.4396C6.76857 50.649 6.32486 49.5776 6.32486 48.4598C6.32486 47.3421 6.76857 46.2699 7.55829 45.48C8.34874 44.6901 9.41982 44.2455 10.5372 44.2455C11.6546 44.2455 12.7265 44.6901 13.5161 45.48C14.3059 46.27 14.7503 47.3421 14.7503 48.4598C14.7503 49.5775 14.3059 50.649 13.5161 51.4396C12.7264 52.2296 11.6546 52.6735 10.5372 52.6735ZM48.4508 14.7486C47.3334 14.7486 46.2615 14.304 45.4719 13.5141C44.6822 12.7241 44.2377 11.652 44.2377 10.5343C44.2377 9.41658 44.6822 8.34513 45.4719 7.55446C46.2616 6.76451 47.3334 6.32066 48.4508 6.32066C49.5681 6.32066 50.6393 6.76451 51.4297 7.55446C52.2194 8.34514 52.6632 9.41654 52.6632 10.5343C52.6632 11.652 52.2194 12.7242 51.4297 13.5141C50.6393 14.304 49.5682 14.7486 48.4508 14.7486Z\" fill=\"#FFAD21\"><\/path><path d=\"M49.5382 44.1536C49.5382 45.5816 48.9711 46.9518 47.9615 47.9614C46.9519 48.971 45.5817 49.5382 44.1536 49.5382H28V56H44.1536C47.2959 56 50.3089 54.7523 52.5302 52.5302C54.7523 50.3089 56 47.2959 56 44.1536V28H49.5382L49.5382 44.1536Z\" fill=\"#FFAD21\"><\/path><path d=\"M9.4618 14.8464C9.4618 13.4184 10.0289 12.0482 11.0385 11.0386C12.0481 10.029 13.4183 9.46183 14.8464 9.46183H31V3H14.8464C11.7041 3 8.69108 4.24773 6.46976 6.46976C4.24768 8.69108 3 11.7041 3 14.8464V31H9.46184L9.4618 14.8464Z\" fill=\"#FFAD21\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPowerful features\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMake hosting council events stress-free with an array of features like mobile ticket scanning, team collaboration, promotional tools, analytics and more. Achieve success with all the necessary components at your fingertips.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f49deda\" data-id=\"7f49deda\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-416a6a87 SharpSans   elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"416a6a87\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"71\" height=\"63\" viewbox=\"0 0 71 63\" fill=\"none\"><path d=\"M5.7139 46.1189H10.278V50.8544V50.8539C10.278 52.3695 10.8799 53.8227 11.9515 54.8944C13.0232 55.9661 14.4765 56.5679 15.992 56.5679H35.2765C36.2625 56.5679 37.0621 55.7688 37.0621 54.7823C37.0621 53.7964 36.2625 52.9967 35.2765 52.9967H15.992C15.4236 52.9967 14.8785 52.771 14.477 52.369C14.0749 51.9674 13.8492 51.4224 13.8492 50.8539V46.1189H30.8124C31.7984 46.1189 32.598 45.3193 32.598 44.3333C32.598 43.3468 31.7984 42.5477 30.8124 42.5477H5.71327C5.14531 42.5477 4.60026 42.3215 4.19819 41.9199C3.79664 41.5179 3.57094 40.9728 3.57094 40.4049V12.5495L51.3395 12.549V16.9563C51.3395 17.9423 52.1386 18.7419 53.1251 18.7419C54.1111 18.7419 54.9107 17.9423 54.9107 16.9563V5.71404C54.9107 4.19845 54.3083 2.74523 53.2372 1.67349C52.1655 0.601835 50.7122 0 49.1966 0H5.71353C4.19845 0 2.74523 0.601848 1.67349 1.67349C0.601746 2.74513 0 4.19845 0 5.71404V40.4044C0 41.9199 0.601849 43.3732 1.67349 44.4444C2.74514 45.5161 4.19845 46.1184 5.71353 46.1184L5.7139 46.1189ZM5.7139 3.59997H49.2825C49.8509 3.59997 50.396 3.82615 50.7975 4.22772C51.1996 4.62977 51.4253 5.17483 51.4253 5.7428V9.05687H3.5713V5.71436C3.57877 5.15088 3.80745 4.61331 4.20851 4.21777C4.60957 3.82219 5.15063 3.59998 5.71364 3.59998L5.7139 3.59997Z\" fill=\"#FF8484\"><\/path><path d=\"M14.9974 34.6875H9.17622C8.19025 34.6875 7.39062 35.4871 7.39062 36.4731C7.39062 37.4591 8.19025 38.2587 9.17622 38.2587H14.9974C15.9839 38.2587 16.783 37.4591 16.783 36.4731C16.783 35.4871 15.9839 34.6875 14.9974 34.6875Z\" fill=\"#FF8484\"><\/path><path d=\"M23.2856 34.6875C22.2996 34.6875 21.5 35.4871 21.5 36.4731C21.5 37.4591 22.2996 38.2587 23.2856 38.2587H29.0853C30.0713 38.2587 30.8709 37.4591 30.8709 36.4731C30.8709 35.4871 30.0713 34.6875 29.0853 34.6875H23.2856Z\" fill=\"#FF8484\"><\/path><path d=\"M20.6042 25.739V21.5466C20.6097 20.4889 20.1942 19.4725 19.4489 18.7222C18.704 17.9713 17.6907 17.5484 16.633 17.5469H11.3619C10.3092 17.5484 9.30028 17.9674 8.55594 18.7117C7.81162 19.456 7.39261 20.4654 7.39062 21.5176V25.7106C7.39062 26.7643 7.80912 27.7753 8.55346 28.521C9.29778 29.2668 10.3082 29.6868 11.3619 29.6888H16.64C17.6878 29.6848 18.6917 29.2683 19.434 28.5285C20.1763 27.7891 20.5968 26.7867 20.6043 25.739L20.6042 25.739ZM17.033 25.739C17.033 25.9598 16.8542 26.1391 16.633 26.1391H11.3619C11.1412 26.1391 10.9618 25.9598 10.9618 25.739V21.5466C10.9618 21.3254 11.1412 21.1465 11.3619 21.1465H16.64C16.8612 21.1465 17.04 21.3254 17.04 21.5466L17.033 25.739Z\" fill=\"#FF8484\"><\/path><path d=\"M69.9226 29.689C69.9226 29.2152 69.7342 28.7613 69.3995 28.4265C69.0647 28.0912 68.6103 27.9034 68.137 27.9034C62.3089 27.9034 58.0661 26.3036 54.3802 22.718C53.6867 22.0419 52.5807 22.0419 51.8872 22.718C48.2018 26.2892 43.9591 27.9034 38.1304 27.9034C37.1444 27.9034 36.3448 28.7025 36.3448 29.689C36.3448 30.6605 36.3448 31.6674 36.3089 32.7032C36.1161 42.7023 35.8591 56.3164 52.5502 62.1018H52.5507C52.9299 62.2333 53.3424 62.2333 53.722 62.1018C70.4135 56.3166 70.1495 42.6668 69.9633 32.7032C69.9344 31.6744 69.9204 30.6675 69.9204 29.689H69.9226ZM53.1303 58.5302C39.4807 53.4948 39.6886 42.5032 39.8735 32.8176V31.4749C44.7217 31.3534 49.3849 29.5908 53.101 26.4754C56.8177 29.5908 61.4809 31.3534 66.3284 31.4749V32.8176C66.571 42.4954 66.7853 53.4948 53.129 58.5302H53.1303Z\" fill=\"#FF8484\"><\/path><path d=\"M56.8991 37.5513L51.3136 43.1224L49.3566 41.1654C48.6586 40.4674 47.5266 40.4674 46.8282 41.1654C46.1302 41.8639 46.1302 42.9959 46.8282 43.6938L50.0497 46.9153C50.3845 47.2511 50.8393 47.4399 51.3136 47.4399C51.7884 47.4399 52.2433 47.2511 52.5781 46.9153L59.4275 40.0658C60.0573 39.3574 60.0239 38.2813 59.3523 37.6132C58.6802 36.9451 57.6036 36.9182 56.8991 37.5514L56.8991 37.5513Z\" fill=\"#FF8484\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSecure payment\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWith a PCI-compliant payment gateway, you can rest assured that your attendees\u2019 data is kept safe and secure. You have complete control over the accessing and sharing of user information with third-party websites or services.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dc75968 laptop-container gallery-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dc75968\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3454743b event-first-colum-image\" data-id=\"3454743b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fb4adc7 elementor-widget elementor-widget-image-change-slider\" data-id=\"2fb4adc7\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-374451654\" type=\"hidden\" name=\"time\" value=\"6000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"374451654\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Music concerts<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Music-concert.png\">\n                <\/div>\n            <\/div>\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Dance<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Galas.webp\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31f2d041 elementor-widget elementor-widget-image-change-slider\" data-id=\"31f2d041\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-1802952940\" type=\"hidden\" name=\"time\" value=\"17000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"1802952940\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Galas<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/event-bookings-image.png\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-54e09ea8\" data-id=\"54e09ea8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f6a873e second-colume-image-big elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f6a873e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7662b8ab\" data-id=\"7662b8ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e173cc elementor-widget elementor-widget-image-change-slider\" data-id=\"36e173cc\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-609231667\" type=\"hidden\" name=\"time\" value=\"15000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"609231667\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">PTA fundraisers\u00a0<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2022\/05\/Fundraising.jpg\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c41fec5\" data-id=\"6c41fec5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-502463cf elementor-widget elementor-widget-image-change-slider\" data-id=\"502463cf\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-505370821\" type=\"hidden\" name=\"time\" value=\"13000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"505370821\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Auction<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Councils.png\">\n                <\/div>\n            <\/div>\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Colloquiums<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Colloquiums.webp\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c8d7794 second-section-first-colume elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8d7794\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-54bfff73\" data-id=\"54bfff73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d130148 elementor-widget elementor-widget-image-change-slider\" data-id=\"6d130148\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-1122972688\" type=\"hidden\" name=\"time\" value=\"12000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"1122972688\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Charity runs<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Sporting-Club1.png\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f1ef9e0\" data-id=\"4f1ef9e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-439775cf elementor-widget elementor-widget-image-change-slider\" data-id=\"439775cf\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-126708574\" type=\"hidden\" name=\"time\" value=\"19000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"126708574\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Golf tournament\u00a0<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/golf.webp\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1515316c third-colume-image-smal\" data-id=\"1515316c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc4baa3 elementor-widget elementor-widget-image-change-slider\" data-id=\"cc4baa3\" data-element_type=\"widget\" data-widget_type=\"image-change-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Add Markup Starts -->\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick-theme.min.css\" rel=\"stylesheet\"\/>\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.css\" rel=\"stylesheet\"\/>\n<!-- <script src=\"https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.1.1\/jquery.min.js\"><\/script> -->\n<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.min.js\"><\/script>\n<!-- <script src=\"\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-easing\/1.3\/jquery.easing.min.js\"><\/script> -->\n\n\n\n\n<input id=\"myField-1828902647\" type=\"hidden\" name=\"time\" value=\"16000\"\/>\n\n\n\n    <div class=\"slick-carousel\" id=\"1828902647\">\n                    <div class=\"item\">\n                <div class=\"img-item\">\n                    <h3 class=\"image-slider-title\">Challengers event\u00a0<\/h3>\n                    <img decoding=\"async\" class=\"image-slider-img\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/athletic-sports.webp\">\n                <\/div>\n            <\/div>\n         \n  <\/div>\n\n\n<style>\n<\/style>\n\n\n\n\n\n  \n<!-- Add Markup Ends -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-569f650b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"569f650b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53d9457c\" data-id=\"53d9457c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-164830b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"164830b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-209c702a\" data-id=\"209c702a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fcb3ce SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"3fcb3ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Powerful features for your<br>\nfree or paid local council event<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41863cff laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41863cff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72a40ffe\" data-id=\"72a40ffe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-51f6c175 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"51f6c175\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b1e6fc9\" data-id=\"1b1e6fc9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7982e6af SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"7982e6af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Professional council event pages<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a3763be br-none elementor-widget elementor-widget-heading\" data-id=\"1a3763be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Create an event page that is professionally designed to fit with your council's website. Include a logo, feature image and social media buttons to ensure a consistent look and feel across all your channels.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6323b90c\" data-id=\"6323b90c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6147472a elementor-widget elementor-widget-image\" data-id=\"6147472a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"633\" height=\"447\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page.png\" class=\"attachment-full size-full wp-image-106597\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page.png 633w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-300x212.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Design-a-stunning-page-18x12.png 18w\" sizes=\"(max-width: 633px) 100vw, 633px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63e7a4e4 elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"63e7a4e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-151dcfb9\" data-id=\"151dcfb9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-322a95d4 elementor-widget elementor-widget-image\" data-id=\"322a95d4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"659\" height=\"500\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Frame-629830.png\" class=\"attachment-full size-full wp-image-106065\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Frame-629830.png 659w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Frame-629830-300x228.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/Frame-629830-16x12.png 16w\" sizes=\"(max-width: 659px) 100vw, 659px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33d3ae3f\" data-id=\"33d3ae3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c1f1407 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"1c1f1407\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Utilize smart forms to collect key information<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c402c45 br-none elementor-widget elementor-widget-heading\" data-id=\"4c402c45\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">With our easy-to-use customizable drag-and-drop forms, you can capture all the vital information including name, email address, phone number and more. Plus, to ensure a smooth journey for your attendees, you can also add conditions to your order form so that only necessary fields are visible.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18d67387 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"18d67387\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b9cef4e\" data-id=\"1b9cef4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c1eecb8 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"3c1eecb8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Up-to-date <br>reporting<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34a48dac br-none elementor-widget elementor-widget-heading\" data-id=\"34a48dac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Figure out which marketing strategies are yielding positive results in terms of audience turnout and assess how successful your promotional efforts are.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a6d9522\" data-id=\"a6d9522\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ad336ed elementor-widget elementor-widget-image\" data-id=\"2ad336ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"481\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting.png\" class=\"attachment-full size-full wp-image-220336\" alt=\"Track sales in real-time with advanced reporting\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting.png 668w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting-300x216.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/Track-sales-in-real-time-with-advanced-reporting-18x12.png 18w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5799923e elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5799923e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42b93fa2\" data-id=\"42b93fa2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f4ade3 elementor-widget elementor-widget-image\" data-id=\"9f4ade3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"508\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/send-email1.png\" class=\"attachment-full size-full wp-image-112133\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/send-email1.png 683w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/send-email1-300x223.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/send-email1-16x12.png 16w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-686ed20a\" data-id=\"686ed20a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-771080f3 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"771080f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sell more event tickets with powerful tools<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e01bc25 br-none elementor-widget elementor-widget-heading\" data-id=\"1e01bc25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Take advantage of our all-in-one email marketing platform and quickly share it to your social networks with a single click to increase visibility and generate more funds.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bab3159 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bab3159\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d79368\" data-id=\"4d79368\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc91545 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"dc91545\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Work together with your team<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85cd6e2 br-none elementor-widget elementor-widget-heading\" data-id=\"85cd6e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Collaborate with other members of the team. Monitor your event as it happens and assign relevant tasks to the right individuals.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b46acfd\" data-id=\"b46acfd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f17a067 elementor-widget elementor-widget-image\" data-id=\"f17a067\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"653\" height=\"499\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/send-invitation.png\" class=\"attachment-full size-full wp-image-220411\" alt=\"Seamless team coordination\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/send-invitation.png 653w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/send-invitation-300x229.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/send-invitation-16x12.png 16w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0ed65f elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"d0ed65f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62db88f4\" data-id=\"62db88f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e68c4ca elementor-widget elementor-widget-image\" data-id=\"1e68c4ca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"639\" height=\"566\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/st.png\" class=\"attachment-full size-full wp-image-106069\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/st.png 639w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/st-300x266.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/st-14x12.png 14w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3818e466\" data-id=\"3818e466\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617d9e5f SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"617d9e5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Scan tickets with<br> a mobile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc6a4ab br-none elementor-widget elementor-widget-heading\" data-id=\"4bc6a4ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Speed up the entry process at your council event by scanning tickets with our mobile app. You can be certain that all records are up-to-date and accurate by cross-referencing scanned tickets and the guest list.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57b09ef7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"57b09ef7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-339c6ddb\" data-id=\"339c6ddb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d70bd60 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"6d70bd60\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Free for free events<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d588566 br-none elementor-widget elementor-widget-heading\" data-id=\"4d588566\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Planning to host a free council event in your local area? The first 300 tickets are completely free! After that, a small fee will apply.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6d97ae5\" data-id=\"6d97ae5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51e3124 elementor-widget elementor-widget-image\" data-id=\"51e3124\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"484\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/zero-cost-1.png\" class=\"attachment-full size-full wp-image-108449\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/zero-cost-1.png 699w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/zero-cost-1-300x208.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/zero-cost-1-18x12.png 18w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b4003ce laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b4003ce\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49d3f53e\" data-id=\"49d3f53e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b5ead4 SharpSans   elementor-widget elementor-widget-heading\" data-id=\"77b5ead4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Looking for a platform to host your next council event?<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-534bca95 br-none elementor-widget elementor-widget-heading\" data-id=\"534bca95\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Try EventBookings Now!<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4db7a29f elementor-mobile-align-center elementor-align-center new-fix-url elementor-widget elementor-widget-button\" data-id=\"4db7a29f\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/users\/login\/1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Events for Free<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-692be1d8 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"692be1d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38ee7d63\" data-id=\"38ee7d63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-28d655eb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"28d655eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b74ac44\" data-id=\"b74ac44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5727ff22 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"5727ff22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Clever ways to sell more<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b4f82bd br-none elementor-widget elementor-widget-heading\" data-id=\"6b4f82bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">To increase event sales, create promotions with coupons, early bird discounts, VIP benefits, offering free tickets and group ticketing with limited time countdowns.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42ce84c8\" data-id=\"42ce84c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22260bd5 elementor-widget elementor-widget-image\" data-id=\"22260bd5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"653\" height=\"476\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/cp.png\" class=\"attachment-full size-full wp-image-106605\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/cp.png 653w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/cp-300x219.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/cp-16x12.png 16w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-780235a2 elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"780235a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7cca52a7\" data-id=\"7cca52a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-772f567c elementor-widget elementor-widget-image\" data-id=\"772f567c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"554\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events.png\" class=\"attachment-full size-full wp-image-220226\" alt=\"My events\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events.png 717w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events-300x232.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/my-events-16x12.png 16w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-414125ba\" data-id=\"414125ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-500dfe1f SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"500dfe1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sessions, multi-day and other ticket options available<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7796337f br-none elementor-widget elementor-widget-heading\" data-id=\"7796337f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Provide multiple options when it comes to sessions and tickets. You can choose individual tickets, multi-day passes, group packages, as well as limit the number of tickets sold. Additionally, various ticket classes can be set up for extra people or groups (e.g. seniors or media).<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76029cc5 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76029cc5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31d7a865\" data-id=\"31d7a865\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d4f0b2b SharpSans   elementor-widget elementor-widget-heading\" data-id=\"2d4f0b2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Create your next council event with EventBookings<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-161e624 elementor-mobile-align-center elementor-align-center new-fix-url elementor-widget elementor-widget-button\" data-id=\"161e624\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b371b32 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b371b32\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d25d4aa\" data-id=\"4d25d4aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48d187a3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"48d187a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22139ea1\" data-id=\"22139ea1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74e75f00 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"74e75f00\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Free exposure for <br>your council event<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bcaacaa br-none elementor-widget elementor-widget-heading\" data-id=\"5bcaacaa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Add your event to our 'Explore' page for free and benefit from increased awareness to a larger local audience<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e5d2180\" data-id=\"2e5d2180\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d1f5cee elementor-widget elementor-widget-image\" data-id=\"1d1f5cee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"703\" height=\"484\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/discover-events-img.png\" class=\"attachment-full size-full wp-image-220426\" alt=\"Discover events for all the things you love\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/discover-events-img.png 703w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/discover-events-img-300x207.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/discover-events-img-18x12.png 18w\" sizes=\"(max-width: 703px) 100vw, 703px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4834442f elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4834442f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b23170e\" data-id=\"3b23170e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25328fd elementor-widget elementor-widget-image\" data-id=\"25328fd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"521\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/waiting-lists-1.png\" class=\"attachment-full size-full wp-image-109169\" alt=\"\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/waiting-lists-1.png 711w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/waiting-lists-1-300x220.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/waiting-lists-1-16x12.png 16w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7df5035c\" data-id=\"7df5035c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a6a870 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"51a6a870\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lists for those who missed out<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5f2078 br-none elementor-widget elementor-widget-heading\" data-id=\"2b5f2078\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Once your council event is completely booked, ask interested people for their contact information so that you can send invitations when additional spots become available.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55ae4c54 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"55ae4c54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-faeda41\" data-id=\"faeda41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1687e096 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"1687e096\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Last minute ticket sales<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43fd7fad br-none elementor-widget elementor-widget-heading\" data-id=\"43fd7fad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">With our mobile app, selling tickets to people who arrived without one is now easier than ever! Not only can you issue them a ticket within seconds, but you can also scan it as soon as they purchase it.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-742a3726\" data-id=\"742a3726\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76e15b6 elementor-widget elementor-widget-image\" data-id=\"76e15b6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"672\" height=\"488\" src=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/cdf-nonprofit.png\" class=\"attachment-full size-full wp-image-220416\" alt=\"Streamlined guest entry\" srcset=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/cdf-nonprofit.png 672w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/cdf-nonprofit-300x218.png 300w, https:\/\/www.eventbookings.com\/wp-content\/uploads\/2026\/01\/cdf-nonprofit-18x12.png 18w\" sizes=\"(max-width: 672px) 100vw, 672px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45aface1 laptop-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45aface1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a2d0da7\" data-id=\"7a2d0da7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1302b703 SharpSans  br-none elementor-widget elementor-widget-heading\" data-id=\"1302b703\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Council events made easy<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64439719 elementor-mobile-align-center elementor-align-center new-fix-url elementor-widget elementor-widget-button\" data-id=\"64439719\" data-element_type=\"widget\" data-widget_type=\"button.default\" data-no-translation=\"\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbookings.com\/b\/member\/account\/create-event\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Create Event<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>The powerful ticketing tool for local councils Get advanced reporting and great ticketing flexibility with EventBookings. Create Event Excellent 4.7\/5 Create Event Excellent 4.7\/5 Events created by thousands of organisations around the globe \u00a2 Lowest fees in the industry for local councils Costs less than Others If you&#8217;re looking to save on transaction fees, we&#8217;ve [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":61886,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-106861","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Event Ticketing Solutions for Councils | EventBookings<\/title>\n<meta name=\"description\" content=\"Plan successful council events with ease. Our customisable event management solutions streamline the process from start to finish. Create and manage events effortlessly.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eventbookings.com\/en-cy\/industry\/councils\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Event Ticketing Solutions for Councils | EventBookings\" \/>\n<meta property=\"og:description\" content=\"Plan successful council events with ease. Our customisable event management solutions streamline the process from start to finish. Create and manage events effortlessly.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eventbookings.com\/en-cy\/industry\/councils\/\" \/>\n<meta property=\"og:site_name\" content=\"EventBookings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eEventBookings\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T04:28:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"153\" \/>\n\t<meta property=\"og:image:height\" content=\"35\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eEventBookings\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eventbookings.com\/industry\/councils\/\",\"url\":\"https:\/\/www.eventbookings.com\/industry\/councils\/\",\"name\":\"Event Ticketing Solutions for Councils | EventBookings\",\"isPartOf\":{\"@id\":\"https:\/\/www.eventbookings.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eventbookings.com\/industry\/councils\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eventbookings.com\/industry\/councils\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png\",\"datePublished\":\"2023-02-14T12:20:12+00:00\",\"dateModified\":\"2026-03-09T04:28:09+00:00\",\"description\":\"Plan successful council events with ease. Our customisable event management solutions streamline the process from start to finish. Create and manage events effortlessly.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eventbookings.com\/industry\/councils\/#breadcrumb\"},\"inLanguage\":\"el-CY\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eventbookings.com\/industry\/councils\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el-CY\",\"@id\":\"https:\/\/www.eventbookings.com\/industry\/councils\/#primaryimage\",\"url\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png\",\"contentUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eventbookings.com\/industry\/councils\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eventbookings.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industry\",\"item\":\"https:\/\/www.eventbookings.com\/en-nz\/industry\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Councils\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eventbookings.com\/#website\",\"url\":\"https:\/\/www.eventbookings.com\/\",\"name\":\"EventBookings\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eventbookings.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eventbookings.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el-CY\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eventbookings.com\/#organization\",\"name\":\"EventBookings\",\"url\":\"https:\/\/www.eventbookings.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el-CY\",\"@id\":\"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\",\"contentUrl\":\"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg\",\"width\":1200,\"height\":674,\"caption\":\"EventBookings\"},\"image\":{\"@id\":\"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eEventBookings\",\"https:\/\/x.com\/eEventBookings\",\"https:\/\/www.linkedin.com\/company\/eeventbookings\/\",\"https:\/\/www.instagram.com\/eeventbookings\/\",\"https:\/\/www.youtube.com\/channel\/UCrN_RsacOWc9V3JU_Q3-tJA\",\"https:\/\/www.tiktok.com\/@eventbookings\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Event Ticketing Solutions for Councils | EventBookings","description":"Plan successful council events with ease. Our customisable event management solutions streamline the process from start to finish. Create and manage events effortlessly.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eventbookings.com\/en-cy\/industry\/councils\/","og_locale":"en_US","og_type":"article","og_title":"Event Ticketing Solutions for Councils | EventBookings","og_description":"Plan successful council events with ease. Our customisable event management solutions streamline the process from start to finish. Create and manage events effortlessly.","og_url":"https:\/\/www.eventbookings.com\/en-cy\/industry\/councils\/","og_site_name":"EventBookings","article_publisher":"https:\/\/www.facebook.com\/eEventBookings","article_modified_time":"2026-03-09T04:28:09+00:00","og_image":[{"width":153,"height":35,"url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eEventBookings","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eventbookings.com\/industry\/councils\/","url":"https:\/\/www.eventbookings.com\/industry\/councils\/","name":"Event Ticketing Solutions for Councils | EventBookings","isPartOf":{"@id":"https:\/\/www.eventbookings.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eventbookings.com\/industry\/councils\/#primaryimage"},"image":{"@id":"https:\/\/www.eventbookings.com\/industry\/councils\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png","datePublished":"2023-02-14T12:20:12+00:00","dateModified":"2026-03-09T04:28:09+00:00","description":"Plan successful council events with ease. Our customisable event management solutions streamline the process from start to finish. Create and manage events effortlessly.","breadcrumb":{"@id":"https:\/\/www.eventbookings.com\/industry\/councils\/#breadcrumb"},"inLanguage":"el-CY","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eventbookings.com\/industry\/councils\/"]}]},{"@type":"ImageObject","inLanguage":"el-CY","@id":"https:\/\/www.eventbookings.com\/industry\/councils\/#primaryimage","url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png","contentUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2023\/02\/capterra-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eventbookings.com\/industry\/councils\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eventbookings.com\/"},{"@type":"ListItem","position":2,"name":"Industry","item":"https:\/\/www.eventbookings.com\/en-nz\/industry\/"},{"@type":"ListItem","position":3,"name":"Councils"}]},{"@type":"WebSite","@id":"https:\/\/www.eventbookings.com\/#website","url":"https:\/\/www.eventbookings.com\/","name":"EventBookings","description":"","publisher":{"@id":"https:\/\/www.eventbookings.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eventbookings.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el-CY"},{"@type":"Organization","@id":"https:\/\/www.eventbookings.com\/#organization","name":"EventBookings","url":"https:\/\/www.eventbookings.com\/","logo":{"@type":"ImageObject","inLanguage":"el-CY","@id":"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","contentUrl":"https:\/\/www.eventbookings.com\/wp-content\/uploads\/2024\/01\/eb-logo-1200x675-1.jpg","width":1200,"height":674,"caption":"EventBookings"},"image":{"@id":"https:\/\/www.eventbookings.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eEventBookings","https:\/\/x.com\/eEventBookings","https:\/\/www.linkedin.com\/company\/eeventbookings\/","https:\/\/www.instagram.com\/eeventbookings\/","https:\/\/www.youtube.com\/channel\/UCrN_RsacOWc9V3JU_Q3-tJA","https:\/\/www.tiktok.com\/@eventbookings"]}]}},"_links":{"self":[{"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/pages\/106861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/comments?post=106861"}],"version-history":[{"count":136,"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/pages\/106861\/revisions"}],"predecessor-version":[{"id":223366,"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/pages\/106861\/revisions\/223366"}],"up":[{"embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/pages\/61886"}],"wp:attachment":[{"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/media?parent=106861"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eventbookings.com\/en-cy\/wp-json\/wp\/v2\/tags?post=106861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}